{"id":96280,"date":"2015-10-22T09:35:54","date_gmt":"2015-10-22T07:35:54","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=96280"},"modified":"2015-10-23T10:58:44","modified_gmt":"2015-10-23T08:58:44","slug":"le-kosovo-reussi-la-premiere-phase-de-son-adhesion-a-lunesco","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-kosovo-reussi-la-premiere-phase-de-son-adhesion-a-lunesco\/","title":{"rendered":"Le Kosovo r\u00e9ussi la premi\u00e8re phase de son adh\u00e9sion \u00e0 l\u2019UNESCO"},"content":{"rendered":"<p>La R\u00e9publique du Kosovo passe la premi\u00e8re \u00e9tape qui m\u00e8nera \u00e0 sa repr\u00e9sentation \u00e0 l\u2019UNESCO, apr\u00e8s que le Conseil ex\u00e9cutif a vot\u00e9 pour l\u2019adh\u00e9sion de ce pays \u00e0 l\u2019institution.<\/p>\n<p>Le Conseil ex\u00e9cutif de l\u2019UNESCO a vot\u00e9 la recommandation de l\u2019adh\u00e9sion de la R\u00e9publique du Kosovo \u00e0 l\u2019UNESCO. \u00c0 cette occasion le Kosovo a pass\u00e9 aujourd\u2019hui la premi\u00e8re phase devant le mener \u00e0 \u00eatre repr\u00e9sent\u00e9 au sein de cette institution, mais la phase cruciale reste la votation de l\u2019assembl\u00e9 de l\u2019UNESCO, qui se tiendra le mois prochain.<\/p>\n<p>Initialement, le vote sur le Kosovo avait \u00e9t\u00e9 report\u00e9 \u00e0 la demande de la Russie et du Cuba, mais la proc\u00e9dure a repris suite aux recommandations donn\u00e9es par l\u2019Albanie. Lors du vote d\u2019aujourd\u2019hui, le Kosovo a re\u00e7u 27 voix favorables, 14 contres et 14 abstentions.<\/p>\n<p>L\u2019adh\u00e9sion \u00e0 l\u2019UNECSO rend chaque pays membre responsable du patrimoine situ\u00e9 sur son territoire.<\/p>\n<p>Il y a quelques mois, une campagne diplomatique f\u00e9roce contre l\u2019adh\u00e9sion du Kosovo \u00e0 l\u2019UNESCO a commenc\u00e9. La Serbie a fait pression de toutes ses forces contre le Kosovo, tandis que Prishtina et quelques pays alli\u00e9s ont fait pression pour l\u2019adh\u00e9sion du Kosovo \u00e0 cette institution internationale.<\/p>\n<p>Le Vice Premier ministre du Kosovo, Hashim Tha\u00e7i, \u00e0 travers un message publi\u00e9 sur Facebook, a d\u00e9clar\u00e9 que l\u2019approbation de la r\u00e9solution qui recommande l\u2019admission du Kosovo \u00e0 l\u2019UNESCO est une \u00e9tape tr\u00e8s importante pour le Kosovo. \u00ab\u00a0Le Comit\u00e9 ex\u00e9cutif de l\u2019UNESCO vient d\u2019adopter la r\u00e9solution recommandant l\u2019admission de la R\u00e9publique du Kosovo \u00e0 l\u2019UNESCO. Ceci est un grand pas en avant pour le Kosovo\u00a0\u00bb, a \u00e9crit M. Tha\u00e7i.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La R\u00e9publique du Kosovo passe la premi\u00e8re \u00e9tape qui m\u00e8nera \u00e0 sa repr\u00e9sentation \u00e0 l\u2019UNESCO, apr\u00e8s que le Conseil ex\u00e9cutif a vot\u00e9 pour l\u2019adh\u00e9sion de ce pays \u00e0 l\u2019institution. Le Conseil ex\u00e9cutif de l\u2019UNESCO a vot\u00e9 la recommandation de l\u2019adh\u00e9sion de la R\u00e9publique du Kosovo \u00e0 l\u2019UNESCO. \u00c0 cette occasion le Kosovo a pass\u00e9 aujourd\u2019hui [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-96280","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/96280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=96280"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/96280\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=96280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=96280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=96280"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=96280"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=96280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}