{"id":93783,"date":"2015-09-22T15:37:07","date_gmt":"2015-09-22T13:37:07","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=93783"},"modified":"2019-10-10T18:11:42","modified_gmt":"2019-10-10T16:11:42","slug":"revoltohet-opozitaret-e-gjuajne-me-veze-kryeministrin-mustafa-2","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/revoltohet-opozitaret-e-gjuajne-me-veze-kryeministrin-mustafa-2\/","title":{"rendered":"Kosovo: les d\u00e9put\u00e9s de l&#8217;opposition lancent des \u0153ufs sur le Premier ministre"},"content":{"rendered":"<p>Ce mardi, au moment o\u00f9 le Premier ministre Mustafa a pris la parole au parloir du Parlement \u00e0 Prishtina pour pr\u00e9senter les deux derniers accords, l\u2019un avec la Serbie et l\u2019autre avec le Mont\u00e9n\u00e9gro, il a re\u00e7u des projectiles d&#8217;\u0153ufs de la part des d\u00e9put\u00e9s de l\u2019opposition.<\/p>\n<p>Juste apr\u00e8s cette attaque, le Premier ministre a quitt\u00e9 la salle accompagn\u00e9 de la garde de s\u00e9curit\u00e9.<\/p>\n<p>Le pr\u00e9sident du Parlement, Kadri Veseli, a tout de suite r\u00e9agi. Il a qualifi\u00e9 cette attaque de \u00ab\u00a0honteuse\u00a0\u00bb et a suspendu la s\u00e9ance pendant 10 minutes. Il a aussi d\u00e9clar\u00e9 que \u00ab\u00a0cet acte n\u2019est pas digne de l\u2019endroit\u00a0\u00bb.<\/p>\n<p>Mustafa a subi l\u2019attaque aux \u0153ufs au moment o\u00f9 il a annoncait que les accords conclus avec la Serbie sont en conformit\u00e9 avec la Constitution et les lois du pays. C\u2019est juste apr\u00e8s cette d\u00e9claration que l\u2019opposition a boycott\u00e9 la session pl\u00e9ni\u00e8re.<\/p>\n<p>La d\u00e9put\u00e9e du parti Vet\u00ebvendosje, Albulena Haxhiu, a d\u00e9clar\u00e9 que l\u2019opposition ne permettra pas la poursuite de l\u2019audience parce que la situation au Kosovo est tendue et que la liste Srpska mets le pays en danger. \u00ab\u00a0Nous allons rester au parlement mais nous ne permettrons pas la poursuite de la session\u00a0\u00bb, s\u2019est exprim\u00e9e Mme\u00a0Haxhiu.<\/p>\n<p>Le\u00a0Gouvernement du Kosovo a de suite condamn\u00e9 cette action de l\u2019opposition:\u00a0\u00ab\u00a0Le Gouvernement de la R\u00e9publique du Kosovo estime que tout le monde a l\u2019obligation d\u2019\u00e9viter tout acte de violence et d\u2019\u00e9viter les actions qui d\u00e9passent les formes d\u00e9mocratiques d\u2019opposition qui nuisent aux int\u00e9r\u00eats de notre pays\u00a0\u00bb. Ce dernier prie\u00a0l\u2019Assembl\u00e9e \u00e0 cr\u00e9er des conditions de travail normales.<\/p>\n<p>\u00ab\u00a0Le gouvernement assure les citoyens du Kosovo que les accords conclus \u00e0 Bruxelles sont en conformit\u00e9 avec les lois et la Constitution de la R\u00e9publique du Kosovo et il estime que ces accords ouvriront la voie \u00e0 l\u2019int\u00e9gration euro-atlantique du pays, et ils sont fortement soutenus par les partenaires strat\u00e9giques du Kosovo, les Etats-Unis et l\u2019UE\u00a0\u00bb, selon le gouvernement.<\/p>\n<p>L\u2019action de l\u2019opposition a aussi \u00e9t\u00e9 critiqu\u00e9e par la Pr\u00e9sidente de la R\u00e9publique du Kosovo, Atifete Jahjaga. Elle qualifie cette attaque d\u2019inacceptable, contraire \u00e0 l\u2019esprit d\u2019une v\u00e9ritable d\u00e9mocratie, et contre-productive vis-\u00e0-vis des efforts tendant \u00e0 renforcer les institutions de la R\u00e9publique du Kosovo et les valeurs que nous construisons.<\/p>\n<p>\u00ab\u00a0Ces actes laids entravent la bonne discussion et abiment la confiance publique envers les institutions du pays\u00a0\u00bb, \u00e9crit dans son message la Pr\u00e9sidente Jahjaga, qui invite tous les membres et les partis politiques \u00e0 respecter les institutions du pays qui repr\u00e9sentent la volont\u00e9 du peuple.<\/p>\n<p><iframe loading=\"lazy\" title=\"Momenti kur Isa Mustafa u Sulmua nga Deputete\u0308t e Opozite\u0308s\" width=\"587\" height=\"330\" src=\"https:\/\/www.youtube.com\/embed\/o5zjGG6HBYM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce mardi, au moment o\u00f9 le Premier ministre Mustafa a pris la parole au parloir du Parlement \u00e0 Prishtina pour pr\u00e9senter les deux derniers accords, l\u2019un avec la Serbie et l\u2019autre avec le Mont\u00e9n\u00e9gro, il a re\u00e7u des projectiles d&#8217;\u0153ufs de la part des d\u00e9put\u00e9s de l\u2019opposition. Juste apr\u00e8s cette attaque, le Premier ministre a [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":66525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-93783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/93783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=93783"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/93783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/66525"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=93783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=93783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=93783"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=93783"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=93783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}