{"id":923322,"date":"2026-05-13T16:21:19","date_gmt":"2026-05-13T14:21:19","guid":{"rendered":"https:\/\/www.albinfo.ch\/superkupa-kosove-diaspore-organizohet-per-here-te-pare-ne-gjeneve\/"},"modified":"2026-05-13T18:57:48","modified_gmt":"2026-05-13T16:57:48","slug":"superkupa-kosove-diaspore-organizohet-per-here-te-pare-ne-gjeneve","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/superkupa-kosove-diaspore-organizohet-per-here-te-pare-ne-gjeneve\/","title":{"rendered":"La Supercoupe Kosovo-Diaspora est organis\u00e9e pour la premi\u00e8re fois \u00e0 Gen\u00e8ve"},"content":{"rendered":"<p data-start=\"17\" data-end=\"280\">Le Consulat de la R\u00e9publique du Kosovo \u00e0 Gen\u00e8ve a pris part \u00e0 l\u2019activit\u00e9 traditionnelle &#8220;Supercoupe Kosovo-Diaspora&#8221;, organis\u00e9e cette ann\u00e9e pour la premi\u00e8re fois \u00e0 Gen\u00e8ve, marquant un moment particulier pour la communaut\u00e9 albanaise en Suisse, rapporte albinfo.ch.<\/p>\n<p data-start=\"282\" data-end=\"585\">Cet \u00e9v\u00e9nement a \u00e9t\u00e9 organis\u00e9 par le FC Kosova Gen\u00e8ve et l\u2019Union des clubs albanais de football en Suisse, sous l\u2019\u00e9gide de la F\u00e9d\u00e9ration de football du Kosovo (FFK), avec le soutien du minist\u00e8re de la Culture, de la Jeunesse et des Sports ainsi que du minist\u00e8re des Affaires \u00e9trang\u00e8res et de la Diaspora.<\/p>\n<p data-start=\"587\" data-end=\"790\">Le match final pour le troph\u00e9e a oppos\u00e9 le FC Prishtina et le FC Kosova Gen\u00e8ve, offrant de grandes \u00e9motions et une atmosph\u00e8re sportive exceptionnelle, v\u00e9cue avec enthousiasme par les personnes pr\u00e9sentes.<\/p>\n<p data-start=\"792\" data-end=\"1026\">L\u2019organisation de la Supercoupe \u00e0 Gen\u00e8ve a \u00e9t\u00e9 consid\u00e9r\u00e9e comme un \u00e9v\u00e9nement d\u2019une importance particuli\u00e8re, renfor\u00e7ant les liens entre le sport au Kosovo et la diaspora albanaise, tout en promouvant l\u2019unit\u00e9 et l\u2019esprit de coop\u00e9ration.<\/p>\n<p data-start=\"1028\" data-end=\"1237\">Le Consulat a remerci\u00e9 les organisateurs, les clubs participants et tous les compatriotes pour leur contribution et leur participation \u00e0 cet \u00e9v\u00e9nement qui valorise la communaut\u00e9 albanaise en Suisse.\/Albinfo.ch<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/share\/18WA7dcBQ7\/?mibextid=wwXIfr\">https:\/\/www.facebook.com\/share\/18WA7dcBQ7\/?mibextid=wwXIfr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le FC Prishtina et le FC Kosova Gen\u00e8ve se sont affront\u00e9s pour le troph\u00e9e, lors d\u2019un \u00e9v\u00e9nement important pour la communaut\u00e9 albanaise en Suisse<\/p>\n","protected":false},"author":31,"featured_media":923081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24637,18826,24630,1163,1170],"tags":[],"vendi":[],"content_country":[31835,31838,31840],"class_list":["post-923322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles-fr-4","category-lajme-jeta-ne-zvicer-fr","category-nouvelles","category-fr-e-diaspora","category-vivre-en-suisse","content_country-austria-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/923322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=923322"}],"version-history":[{"count":2,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/923322\/revisions"}],"predecessor-version":[{"id":923324,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/923322\/revisions\/923324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/923081"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=923322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=923322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=923322"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=923322"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=923322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}