{"id":86934,"date":"2015-07-01T09:15:17","date_gmt":"2015-07-01T07:15:17","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=86934"},"modified":"2015-07-01T09:39:17","modified_gmt":"2015-07-01T07:39:17","slug":"la-crise-grecque-se-propage-aux-pays-des-balkans","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/la-crise-grecque-se-propage-aux-pays-des-balkans\/","title":{"rendered":"La crise grecque se propage aux pays des Balkans"},"content":{"rendered":"<p>Le syst\u00e8me bancaire des pays balkaniques fait face au risque de contagion des banques grecques. La Gr\u00e8ce doit tr\u00e8s vite d\u00e9cider si elle d\u00e9sire ou non rester dans l\u2019Eurozone. Le syst\u00e8me bancaire de l\u2019Albanie, de la Mac\u00e9doine, de la Roumanie et de la Serbie est d\u00e9muni face \u00e0 la contagion de diverses branches des banques grecques dans ces pays. Dans son dernier rapport, la Banque mondiale pr\u00e9vient ces pays sur le danger que repr\u00e9sentent les banques grecques. \u00ab\u00a0La pression \u00e9conomique et financi\u00e8re en Gr\u00e8ce constitue un risque suppl\u00e9mentaire pour les pr\u00e9visions de la r\u00e9gion, m\u00eame si l\u2019exposition des autres pays de l\u2019Eurozone a \u00e9t\u00e9 en baisse depuis 2010\u00a0\u00bb stipule le rapport.<\/p>\n<p>La Banque mondiale explique que les banques qui ont un capital grec en Albanie repr\u00e9sentent le 18\u00a0% de la totalit\u00e9 des banques, chose qui risque de propager le stress du syst\u00e8me financier grec. \u00c0 part le risque qui peut survenir en Albanie \u00e0 travers les banques grecques, il existe aussi le risque des envois de fonds, puisque l\u2019Albanie touche de l\u2019argent envoy\u00e9 par les migrants \u00e0 hauteur d\u2019environ 3.7\u00a0% de la production int\u00e9rieure brute en Gr\u00e8ce.<\/p>\n<p>Genti Sejko, gouverneur de la Banque de l\u2019Albanie pense au contraire que le syst\u00e8me bancaire albanais est prot\u00e9g\u00e9 et ne sera pas touch\u00e9 par la crise du pays voisin. Selon lui la seule chose qui peut arriver est une baisse des envois de fonds et une baisse des \u00e9changes commerciaux.<\/p>\n<p>L\u2019association des Banques Albanaises (ABA) a assur\u00e9 les \u00e9pargnants que les \u00e9v\u00e9nements grecs n\u2019auront aucun impact sur la stabilit\u00e9 et le fonctionnement normal des banques albanaises. \u00ab\u00a0Notre syst\u00e8me bancaire est financi\u00e8rement et op\u00e9rationnellement ind\u00e9pendant des autres pays. Toutes les banques commerciales op\u00e8rent en Albanie comme entit\u00e9s juridiques ind\u00e9pendantes, dans le cadre l\u00e9gislatif et r\u00e9glementaire albanais, y compris les exigences de fonds propres pour un contr\u00f4le bancaire complet. Aucune des banques commerciales en Albanie n\u2019est la filiale d\u2019une banque \u00e9trang\u00e8re\u00a0\u00bb est \u00e9crit dans un communiqu\u00e9 de l\u2019ABA.<\/p>\n<p>En ce qui concerne le Kosovo, l\u2019impact direct de la crise grecque est estim\u00e9 \u00eatre minime. Car l\u2019\u00e9conomie du Kosovo s\u2019expose peu \u00e0 l\u2019\u00e9conomie grecque, a d\u00e9clar\u00e9 pour REL, Besnik Kada, porte-parole de la Banque Centrale de la R\u00e9publique du Kosovo. Il a ajout\u00e9 que les investissements \u00e9trangers et les fonds par l\u2019\u00c9tat grec sont minimes et qu\u2019aucune banque d\u2019origine grecque n\u2019op\u00e8re dans le secteur bancaire kosovar.<\/p>\n<p>La Gr\u00e8ce a jusqu\u2019\u00e0 minuit pour rembourser la dette de 1.7\u00a0milliards d\u2019euros au Fond Mon\u00e9taire International, dans le cas contraire elle fera faillite. Les cr\u00e9diteurs ont d\u00e9clar\u00e9 qu\u2019ils n\u2019aideront plus la Gr\u00e8ce tant que cette derni\u00e8re ne conclut pas \u00e0 un accord sur les r\u00e9formes. Un r\u00e9f\u00e9rendum aura lieu le 5\u00a0juillet afin de prendre une d\u00e9cision sur les mesures d\u2019aust\u00e9rit\u00e9s propos\u00e9es par les cr\u00e9diteurs.<\/p>\n<p>Les dirigeants europ\u00e9ens d\u00e9crivent l\u2019initiative pl\u00e9biscit\u00e9e comme le choix de rester dans la zone mon\u00e9taire commune ou la sortie de celle-ci.<\/p>\n<p>Les experts voient quatre r\u00e9sultats possibles.<\/p>\n<p>La premi\u00e8re serait un accord de derni\u00e8re la minute. Les cr\u00e9diteurs pr\u00e9f\u00e8rent sans doute une solution politique \u00e0 l\u2019impasse pour parvenir \u00e0 un accord qui permettra \u00e0 l\u2019\u00c9tat hell\u00e9nique d\u2019obtenir les fonds n\u00e9cessaires pour payer les 1.6\u00a0milliards au FMI.<\/p>\n<p>Une solution qui va dans la m\u00eame direction est si le peuple grec d\u00e9cide lors du r\u00e9f\u00e9rendum de voter pour la mise en place des mesures. Pour le Syriza qui recommande le refus des r\u00e9formes demand\u00e9es par les cr\u00e9anciers, ce vote signifiera probablement la d\u00e9mission du Premier ministre Alexis Tsipras.<\/p>\n<p>Ensuite il y a la possibilit\u00e9 que le peuple dise non \u00e0 l\u2019aust\u00e9rit\u00e9. Une telle d\u00e9cision serait le prologue d\u2019une longue p\u00e9riode d\u2019ins\u00e9curit\u00e9 et de crise qui se terminerait avec la sortie de la Gr\u00e8ce de l\u2019Eurozone et le retour au drachme.<\/p>\n<p>La derni\u00e8re possibilit\u00e9 serait que les Grecs votent non et que cela m\u00e8ne \u00e0 une sortie n\u00e9goci\u00e9e de l\u2019Eurozone. Les Grecs verraient ainsi leurs \u00e9pargnes se convertir en leur d\u00e9faveur. Si la Gr\u00e8ce ne d\u00e9sire pas partir de l\u2019Eurozone, ce serait l\u00e9galement impossible de l\u2019\u00e9carter car il n\u2019existe pas de loi pour faire sortir de force un pays membre de l\u2019Union europ\u00e9enne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le syst\u00e8me bancaire des pays balkaniques fait face au risque de contagion des banques grecques. La Gr\u00e8ce doit tr\u00e8s vite d\u00e9cider si elle d\u00e9sire ou non rester dans l\u2019Eurozone. Le syst\u00e8me bancaire de l\u2019Albanie, de la Mac\u00e9doine, de la Roumanie et de la Serbie est d\u00e9muni face \u00e0 la contagion de diverses branches des banques [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159,1411],"tags":[],"vendi":[],"content_country":[],"class_list":["post-86934","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans","category-newsletter-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/86934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=86934"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/86934\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=86934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=86934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=86934"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=86934"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=86934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}