{"id":855471,"date":"2025-08-26T20:19:56","date_gmt":"2025-08-26T18:19:56","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=855471"},"modified":"2025-08-26T20:19:56","modified_gmt":"2025-08-26T18:19:56","slug":"avdullahu-pourrait-faire-ses-debuts-contre-la-suisse","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/avdullahu-pourrait-faire-ses-debuts-contre-la-suisse\/","title":{"rendered":"Avdullahu pourrait faire ses d\u00e9buts contre la Suisse."},"content":{"rendered":"<p data-start=\"203\" data-end=\"379\">Le pr\u00e9sident de la F\u00e9d\u00e9ration de football du Kosovo, Agim Ademi, a d\u00e9clar\u00e9 que le milieu de terrain Leon Avdullahu fera partie de la s\u00e9lection pour les matchs de septembre.<\/p>\n<p data-start=\"381\" data-end=\"473\">Le Kosovo disputera ses deux premiers matchs de qualification pour la Coupe du monde 2026.<\/p>\n<p data-start=\"475\" data-end=\"599\">Les \u201cDardan\u00ebt\u201d affronteront la Suisse le 5 septembre \u00e0 B\u00e2le, puis la Su\u00e8de le 8 septembre \u00e0 Pristina, rapporte albinfo.ch.<\/p>\n<p data-start=\"601\" data-end=\"672\">&#8220;Leoni fera partie de cette s\u00e9lection &#8220;, a d\u00e9clar\u00e9 bri\u00e8vement Ademi.<\/p>\n<p data-start=\"674\" data-end=\"790\">Lundi soir, Ademi a annonc\u00e9 que le milieu de terrain de 21 ans du Hoffenheim avait d\u00e9cid\u00e9 de jouer pour le Kosovo.<\/p>\n<p data-start=\"792\" data-end=\"916\">La d\u00e9cision d\u2019Avdullahu a fait sensation en Suisse. Il avait \u00e9volu\u00e9 auparavant dans les s\u00e9lections de jeunes de la Suisse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Les Dardaniens&#8221; joueront contre la Suisse \u00e0 B\u00e2le le 5 septembre, puis contre la Su\u00e8de \u00e0 Pristina le 8 septembre.<\/p>\n","protected":false},"author":6,"featured_media":829572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24671,1169],"tags":[],"vendi":[],"content_country":[31835,31838,31840],"class_list":["post-855471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-sport-fr","content_country-austria-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/855471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=855471"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/855471\/revisions"}],"predecessor-version":[{"id":855472,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/855471\/revisions\/855472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/829572"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=855471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=855471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=855471"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=855471"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=855471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}