{"id":844922,"date":"2025-07-11T00:56:45","date_gmt":"2025-07-10T22:56:45","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=844922"},"modified":"2025-07-11T00:56:45","modified_gmt":"2025-07-10T22:56:45","slug":"nouveau-classement-fifa-le-kosovo-progresse-lalbanie-recule","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/nouveau-classement-fifa-le-kosovo-progresse-lalbanie-recule\/","title":{"rendered":"Nouveau classement FIFA: le Kosovo progresse, l\u2019Albanie recule"},"content":{"rendered":"<p data-start=\"251\" data-end=\"334\">Classement FIFA, le Kosovo grimpe de deux places, l\u2019Albanie tombe \u00e0 la 68e position<\/p>\n<p data-start=\"336\" data-end=\"440\">La FIFA a publi\u00e9 le nouveau classement des \u00e9quipes nationales pour le mois de juin, rapporte albinfo.ch.<\/p>\n<p data-start=\"442\" data-end=\"543\">Apr\u00e8s un mois marqu\u00e9 par plusieurs matchs des s\u00e9lections, le classement a connu quelques changements.<\/p>\n<p data-start=\"545\" data-end=\"749\">L\u2019\u00e9quipe nationale du Kosovo a r\u00e9alis\u00e9 une progression historique en gagnant deux places, passant de la 97e \u00e0 la 95e position, gr\u00e2ce \u00e0 ses deux victoires en matchs amicaux contre l\u2019Arm\u00e9nie et les Comores.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/reporteri.net\/wp-content\/uploads\/2025\/07\/IMG_9244-768x1057-1.jpeg\" width=\"510\" height=\"702\" \/><\/p>\n<p data-start=\"751\" data-end=\"855\">De son c\u00f4t\u00e9, l\u2019\u00e9quipe nationale d\u2019Albanie a recul\u00e9 dans le classement, passant de la 66e \u00e0 la 68e place.<\/p>\n<p data-start=\"857\" data-end=\"986\">Les Rouge et Noir ont fait match nul contre la Serbie et la Lettonie en juin lors des qualifications pour la Coupe du monde 2026.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/reporteri.net\/wp-content\/uploads\/2025\/07\/IMG_9243-768x1262-1.jpeg\" width=\"507\" height=\"833\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Classement FIFA, le Kosovo grimpe de deux places, l\u2019Albanie tombe \u00e0 la 68e position<\/p>\n","protected":false},"author":6,"featured_media":765580,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24630,24671,1169],"tags":[],"vendi":[],"content_country":[31835,31838,31840],"class_list":["post-844922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nouvelles","category-football","category-sport-fr","content_country-austria-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/844922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=844922"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/844922\/revisions"}],"predecessor-version":[{"id":844923,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/844922\/revisions\/844923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/765580"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=844922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=844922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=844922"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=844922"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=844922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}