{"id":825308,"date":"2025-04-26T21:46:55","date_gmt":"2025-04-26T19:46:55","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=825308"},"modified":"2025-04-26T21:46:55","modified_gmt":"2025-04-26T19:46:55","slug":"xherdan-shaqiri-figure-parmi-les-joueurs-delite-mondiale-issus-de-17-ligues-europeennes","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/xherdan-shaqiri-figure-parmi-les-joueurs-delite-mondiale-issus-de-17-ligues-europeennes\/","title":{"rendered":"Xherdan Shaqiri figure parmi les joueurs d&#8217;\u00e9lite mondiale issus de 17 ligues europ\u00e9ennes"},"content":{"rendered":"<p class=\"x_gmail-\" data-olk-copy-source=\"MessageBody\">Il est rapport\u00e9 que Xherdan Shaqiri r\u00e9alise actuellement l\u2019une des saisons les plus r\u00e9ussies de sa carri\u00e8re et qu\u2019il a retrouv\u00e9 son meilleur niveau depuis son retour dans son club formateur \u00e0 l\u2019\u00e9t\u00e9 dernier, rapporte\u00a0<a title=\"http:\/\/albinfo.ch\" href=\"http:\/\/albinfo.ch\/\" data-auth=\"NotApplicable\" data-linkindex=\"0\">albinfo.ch<\/a>.<\/p>\n<p class=\"x_gmail-\">En effet, Shaqiri est le joueur le plus titr\u00e9 de l\u2019histoire du football suisse, avec deux troph\u00e9es de la Ligue des champions remport\u00e9s avec le Bayern Munich et Liverpool.<\/p>\n<p class=\"x_gmail-\">Il a \u00e9galement gagn\u00e9 des titres en Allemagne et en Angleterre.<\/p>\n<p class=\"x_gmail-\">Il est le deuxi\u00e8me joueur avec le plus grand nombre de s\u00e9lections en \u00e9quipe nationale suisse, juste derri\u00e8re Granit Xhaka, et a remport\u00e9 trois titres de Super League suisse avec le FC B\u00e2le.<\/p>\n<p class=\"x_gmail-\">Avec le FC B\u00e2le, Shaqiri se bat actuellement pour un nouveau titre, auquel il contribue de mani\u00e8re significative.<\/p>\n<p class=\"x_gmail-\">\u00c0 33 ans, il a inscrit 16 buts et d\u00e9livr\u00e9 18 passes d\u00e9cisives, se positionnant parmi les adversaires directs des trois attaquants les plus en forme du moment pour la plus grande contribution \u00e0 leurs \u00e9quipes respectives : Mohamed Salah, Viktor Gy\u00f6keres et Harry Kane.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2025\/04\/img_9702.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-825199\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2025\/04\/img_9702.webp\" alt=\"\" width=\"640\" height=\"800\" srcset=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702.webp 980w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702-240x300.webp 240w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702-819x1024.webp 819w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702-768x960.webp 768w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702-317x396.webp 317w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702-80x100.webp 80w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2025\/04\/img_9702-140x175.webp 140w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p class=\"x_gmail-\" data-olk-copy-source=\"MessageBody\">\u00ab Xherdan Shaqiri figure parmi les joueurs d\u2019\u00e9lite mondiale issus de 17 ligues europ\u00e9ennes en termes de buts et de passes d\u00e9cisives \u00bb, a \u00e9crit samedi la Ligue suisse de football.<\/p>\n<p class=\"x_gmail-\">En r\u00e9alit\u00e9, Shaqiri a \u00e9t\u00e9 impliqu\u00e9 dans 31 buts, tandis que Mohamed Salah de Liverpool m\u00e8ne la liste.<\/p>\n<p class=\"x_gmail-\">Salah a marqu\u00e9 32 buts et d\u00e9livr\u00e9 23 passes d\u00e9cisives en 47 matches toutes comp\u00e9titions confondues.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est rapport\u00e9 que Xherdan Shaqiri r\u00e9alise actuellement l\u2019une des saisons les plus r\u00e9ussies de sa carri\u00e8re et qu\u2019il a retrouv\u00e9 son meilleur niveau depuis son retour dans son club formateur \u00e0 l\u2019\u00e9t\u00e9 dernier, rapporte\u00a0albinfo.ch. En effet, Shaqiri est le joueur le plus titr\u00e9 de l\u2019histoire du football suisse, avec deux troph\u00e9es de la Ligue [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":823936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23271,23270,24630,24671,1169],"tags":[],"vendi":[],"content_country":[31835,31838,31840],"class_list":["post-825308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kosovo","category-at-balkani-fr","category-nouvelles","category-football","category-sport-fr","content_country-austria-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/825308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=825308"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/825308\/revisions"}],"predecessor-version":[{"id":825309,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/825308\/revisions\/825309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/823936"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=825308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=825308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=825308"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=825308"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=825308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}