{"id":71106,"date":"2015-01-15T08:58:23","date_gmt":"2015-01-15T08:58:23","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=71106"},"modified":"2015-01-19T10:52:24","modified_gmt":"2015-01-19T09:52:24","slug":"lambassadeur-lang-soutient-le-ministere-des-finances","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/lambassadeur-lang-soutient-le-ministere-des-finances\/","title":{"rendered":"L\u2019ambassadrice Lang soutient le minist\u00e8re des finances"},"content":{"rendered":"<p>L\u2019ambassadrice de Suisse au Kosovo, Krystyne Marty Lang, a rencontr\u00e9 le ministre des finances Avdullah Hoti, \u00e0 qui elle a promis son soutien et une collaboration \u00e9troite pour la p\u00e9riode \u00e0 venir. L\u2019ambassadrice helv\u00e8te s\u2019est int\u00e9ress\u00e9e de tr\u00e8s pr\u00e8s au d\u00e9veloppement \u00e9conomiques ainsi qu\u2019\u00e0 la strat\u00e9gie du gouvernement pour d\u00e9velopper le pays.<\/p>\n<p>Le ministre Hoti a tenu \u00e0 remercier l\u2019ambassadrice Marty Lang pour son travail, sa contribution ainsi que pour la collaboration qu\u2019elle entretient avec les institutions \u00a0du Kosovo, et surtout avec le minist\u00e8re des finances. Hoti a rassur\u00e9 sur le fait que cette collaboration se poursuivra dans le futur.<\/p>\n<p>Le ministre a \u00e9galement inform\u00e9 l\u2019ambassadeur suisse au niveau de la situation financi\u00e8re du pays et de l\u2019engagement du gouvernement dans la cr\u00e9ation de meilleures conditions pour l\u2019attraction d\u2019investissements \u00e9trangers au Kosovo, ainsi que des efforts du minist\u00e8re des finances dans le combat contre l\u2019\u00e9conomie souterraine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ambassadrice Marty Lang a f\u00e9licit\u00e9 le minist\u00e8re Hoti pour sa nomination au poste de minist\u00e8re des finances. Elle a \u00e9galement exprim\u00e9 sa volont\u00e9 \u00e0 soutenir le Kosovo sur le chemin du d\u00e9veloppement \u00e9conomique<\/p>\n","protected":false},"author":10,"featured_media":71061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-71106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/71106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=71106"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/71106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/71061"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=71106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=71106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=71106"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=71106"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=71106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}