{"id":65485,"date":"2014-10-05T10:40:19","date_gmt":"2014-10-05T08:40:19","guid":{"rendered":""},"modified":"2014-10-09T09:53:32","modified_gmt":"2014-10-09T07:53:32","slug":"le-depart-des-kosovars-na-pas-de-fin","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-depart-des-kosovars-na-pas-de-fin\/","title":{"rendered":"Le d\u00e9part des Kosovars n\u2019a pas de fin"},"content":{"rendered":"<p>Des milliers de Kosovars continuent \u00e0 quitter le Kosovo chaque ann\u00e9e, et&nbsp; ce, malgr\u00e9 les appels r\u00e9guliers des leaders institutionnels du pays \u00e0 ne pas le faire.<\/p>\n<p>Les statistiques signalent pr\u00e8s de 4\u2019500 demandes d\u2019asile dans les pays de l\u2019UE. Parmi eux, plus de 500 sont des communaut\u00e9s RAE (Roms, Ashkali, et Egyptiens). Le ministre sortant de l\u2019int\u00e9rieur, Bajram Rexhepi, explique pour \u00ab&nbsp;Z\u00ebri&nbsp;\u00bb que l\u2019asile n\u2019est plus accord\u00e9 aux Kosovars, mais que malgr\u00e9 cela, un d\u00e9put\u00e9 soutien l\u2019\u00e9migration ill\u00e9gale, \u00e0 cause de la pauvret\u00e9. <\/p>\n<p>Les donn\u00e9es du minist\u00e8re de l\u2019int\u00e9rieur au Kosovo affirment que durant la p\u00e9riode janvier-juin, le nombre de jeunes requ\u00e9rants d\u2019asile du Kosovo vers les pays de l\u2019Union Europ\u00e9enne s\u2019\u00e9l\u00e8ve \u00e0 &nbsp;4\u2019455.<\/p>\n<p>\u00ab&nbsp;Malheureusement, cette tendance est en hausse, surtout durant les mois de juillet et ao\u00fbt. L\u2019ambassadeur hongrois au Kosovo a \u00e9galement exprim\u00e9 son inqui\u00e9tude quant aux flux d\u2019\u00e9migrants vers la Hongrie. Les deux villes principales desquelles ces gens partent sont Ferizaj et Fush\u00eb Kosov\u00eb. La majorit\u00e9 viennent des communaut\u00e9s RAE, mais il y a \u00e9galement des Albanais qui se d\u00e9clarent comme Ashkali et se servent de cet alibi pour passer la fronti\u00e8re&nbsp;et obtenir l\u2019asile&nbsp;\u00bb, indique le ministre Rexhepi.<\/p>\n<p>L\u2019ann\u00e9e pass\u00e9e, ils \u00e9taient au total 17\u2019755 requ\u00e9rants d\u2019asile du Kosovo. Malgr\u00e9 la baisse significative de cette ann\u00e9e, les chiffres restent inqui\u00e9tants selon le minist\u00e8re de l\u2019int\u00e9rieur.<\/p>\n<p>\u00ab&nbsp;Nous avions d\u2019autre priorit\u00e9s, peut-\u00eatre que le fait d\u2019avoir \u00e9t\u00e9 concentr\u00e9s sur le combat contre l\u2019islamisme radical a eu un certain effet&nbsp;\u00bb, affirme-t-il. Le flux d\u2019\u00e9migrants vers l\u2019UE doit cesser selon lui.<\/p>\n<p>Cependant, le d\u00e9put\u00e9 du parlement du Kosovo, l\u2019Ashkali Danush Ahmeti, soutient le fait que la communaut\u00e9 RAE parte du Kosovo.<\/p>\n<p>Il explique soutenir ceux qui fuient le pays car selon lui, le gouvernement du Kosovo a rendu difficile l\u2019obtention des prestations sociales pour les familles en besoin.<\/p>\n<p>\u00ab&nbsp;Je soutiens ceux qui sont partis, car nous n\u2019avons pas la possibilit\u00e9 de les aider&nbsp;\u00bb insiste Ademi, en \u00e9voquant les 500 familles RAE parties du Kosovo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durant les six derniers mois, pr\u00e8s de 4\u2019500 citoyens du Kosovo ont demand\u00e9 l\u2019asile aupr\u00e8s des pays de l\u2019Union Europ\u00e9enne<\/p>\n","protected":false},"author":24223,"featured_media":54169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/24223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65485"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/54169"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65485"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65485"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}