{"id":65458,"date":"2014-09-11T20:42:53","date_gmt":"2014-09-11T18:42:53","guid":{"rendered":""},"modified":"2014-09-12T09:53:24","modified_gmt":"2014-09-12T07:53:24","slug":"session-constitutive-reportee-la-crise-politique-continue","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/session-constitutive-reportee-la-crise-politique-continue\/","title":{"rendered":"Session constitutive report\u00e9e: la crise politique continue"},"content":{"rendered":"<p>La tant attendue session de l\u2019Assembl\u00e9e du Kosovo, pr\u00e9vue pour le 12 septembre, a finalement \u00e9t\u00e9 report\u00e9e \u00e0 &nbsp;jeudi prochain (18 septembre). Cette d\u00e9cision a \u00e9t\u00e9 prise suite \u00e0 la demande des d\u00e9put\u00e9s minoritaires serbes, \u00e9galement connus sous le nom de \u201cLista Srpska (Liste Serbe&nbsp;)\u201d. Avec un tel verdict, la crise institutionnelle continue sans donner un quelconque signe de r\u00e9solution.<\/p>\n<p>La d\u00e9cision a \u00e9t\u00e9 prise par Mme Flora Brovina suite \u00e0 la &nbsp;r\u00e9union du mercredi &nbsp;qui s\u2019est tenue avec certains membres du parti au pouvoir le PDK &nbsp;ainsi que les autres &nbsp;partis de l\u2019Assembl\u00e9e du Kosovo.<\/p>\n<p>Etant la d\u00e9put\u00e9e la plus \u00e2g\u00e9e de la nomenclature , Mme Brovina est la pr\u00e9sidente de la premi\u00e8re session . Conform\u00e9ment &nbsp;la l\u00e9gislatin, la session d\u2019inauguration doit \u00eatre dirig\u00e9e par le\/la d\u00e9put\u00e9(e) la plus \u00e2g\u00e9(e), aid\u00e9 par le\/la plus jeune. Cette derni\u00e8re est Teuta Rugova, la fille du c\u00e9l\u00e8bre pr\u00e9sident du Kosovo, Ibrahim Rugova.<\/p>\n<p>Les repr\u00e9sentants des trois partis politiques, \u00e0 pr\u00e9sent connus sous LAN (LDK,&nbsp; AAK, et Nisma), ainsi que le repr\u00e9sentant du parti Autod\u00e9termination ( VV) ont d\u00e9cid\u00e9 de ne pas prendre part \u00e0 cette r\u00e9union. Tous les partis consid\u00e8rent que le fait de reporter la session est une d\u00e9cision totalement politique.<\/p>\n<p>C\u2019est en raison &nbsp;\u201c de toutes les remarques de la \u00ab&nbsp;Liste Serbe&nbsp;\u00bb, laquelle a besoin de plus de temps pour consulter ses membres, qu\u2019il a \u00e9t\u00e9 d\u00e9cid\u00e9 de repousser la session \u00e0 jeudi de la semaine prochaine\u201d, &nbsp;a expliqu\u00e9 Mme Brovina.<\/p>\n<p>La r\u00e9action de Vet\u00ebvendosje (VV) ne s\u2019est pas fait attendre. Le parti, qui vient tout juste de signer un accord avec les partis du LAN, a r\u00e9torqu\u00e9 dans un communiqu\u00e9 de presse:\u201c Le parti du PDK a aujourd\u2019hui dress\u00e9 la derni\u00e8re barri\u00e8re \u00e0 la cr\u00e9ation des institutions: ensemble avec la liste serbe, ils repoussent d\u2019une semaine la session constitutive du parlement du Kosovo\u201d.<\/p>\n<p>Le communiqu\u00e9 de presse continue: \u201cNous sommes convaincus que l\u2019action d\u2019aujourd\u2019hui ne constitue en rien une d\u00e9cision personnelle de Mme Brovina, mais bel et bien une strat\u00e9gie de son parti. Nous sommes profond\u00e9ment d\u00e9\u00e7us que Mme Brovina et le PDK se soient soumis \u00e0 une demande totalement d\u00e9raisonnable de la \u00ab&nbsp;Liste serbe&nbsp;\u00bb. Aucune justification ne permettait de reporter une session qui tarde depuis maintenant tr\u00e8s longtemps, simplement parce que Hashim Tha\u00e7i ne veut pas abandonner le pouvoir\u201d.<\/p>\n<p>Aleksandar Jabllanoviq, de la \u201cListe Serbe\u201d a fait savoir que son parti avait besoin de temps de r\u00e9flexion, surtout apr\u00e8s l\u2019accord politique sign\u00e9 entre LAN et VV, ainsi que l\u2019inclusion de cette derni\u00e8re dans le processus de n\u00e9gociation.<\/p>\n<p>Lista Srpska est repr\u00e9sent\u00e9e au parlement par neuf d\u00e9put\u00e9s. Initialement, elle s\u2019\u00e9tait exprim\u00e9e en faveur d\u2019une collaboration avec LAN.<\/p>\n<p>\u201cEn tenant compte du fait que Vet\u00ebvendosje (VV)) est un parti qui a demand\u00e9 la r\u00e9vision de l\u2019accord de Bruxelles et qu\u2019il demande \u00e0 prendre part activement au processus du dialogue, nous consid\u00e9rons que ce sont de nouvelles circonstances qui se sont cr\u00e9\u00e9es, et nous avons besoin d\u2019un temps de r\u00e9flexion\u201d a soulign\u00e9 Jabllanoviq.<\/p>\n<p>Le temps additionnel demand\u00e9 par les d\u00e9put\u00e9s serbes afin de consulter le gouvernement de Belgrade n\u2019a pas inqui\u00e9t\u00e9 le mandataire de LAN pour le poste de premier ministre, Ramush Haradinaj. Ce dernier explique en effet que le rapport avec la Liste Serbe ne change pas. &nbsp;<\/p>\n<p>La cr\u00e9ation rapide des institutions du Kosovo a \u00e9t\u00e9 demand\u00e9e par la pr\u00e9sidente Atifete Jahjaga. Cette derni\u00e8re a mis en \u00e9vidence le fait que le pays entrait dans une p\u00e9riode importante et d\u00e9cisive, et que les d\u00e9put\u00e9s du Kosovo doivent d\u00e9montrer une maturit\u00e9 politique afin de surmonter cette situation.<\/p>\n<p>De son c\u00f4t\u00e9, l\u2019analyste Halil Matoshi a affirm\u00e9 que Mme &nbsp;Flora Brovina a abus\u00e9 de son r\u00f4le de pr\u00e9sidente du parlement.<\/p>\n<p>\u201cC\u2019est une usurpation du parlement de la part de la pr\u00e9sidente ad hoc, laquelle ne poss\u00e8de pas de mandat du peuple afin d\u2019appeler \u00e0 la s\u00e9ance, de n\u00e9gocier avec les leaders politiques ou m\u00eame de repousser ou n\u00e9gliger la session. En tant que d\u00e9put\u00e9e la plus \u00e2g\u00e9e, elle est \u00e9gale aux 120 autres d\u00e9put\u00e9s du parlement du Kosovo\u201d s\u2019est exprim\u00e9 Mme Matoshi.<\/p>\n<p>Par ailleurs, c\u2019est depuis le mois de mai que le Kosovo fonctionne sans parlement mais avec un gouvernement. Les \u00e9lections du Kosovo ont \u00e9t\u00e9 remport\u00e9es par le parti du PDK, mais aucun des partis politiques n\u2019est dispos\u00e9 \u00e0 partager la gouvernance avec ce parti, notamment \u00e0 cause des abus durant leur mandat pass\u00e9.<\/p>\n<p>L\u2019\u00e9chiquier politique, c\u2019est-\u00e0-dire la majorit\u00e9 des si\u00e8ges du parlement, dans son enti\u00e8ret\u00e9 s\u2019est exprim\u00e9 contre le PDK. Malgr\u00e9 cela, la Cour constitutionnelle a reconnu le droit au PDK de former le gouvernement. Ce parti ne poss\u00e8de toutefois que 35 d\u00e9put\u00e9s sur 120 au total, et c\u2019est principalement pour cette raison que le processus est bloqu\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9cision de reporter la session constitutive a \u00e9t\u00e9 prise par la pr\u00e9sidente et d\u00e9put\u00e9e la plus \u00e2g\u00e9e, Flora Brovina. Les partis de l\u2019opposition consid\u00e8rent que cette d\u00e9cision est politique<\/p>\n","protected":false},"author":19,"featured_media":53707,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65458"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/53707"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65458"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65458"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}