{"id":65453,"date":"2014-09-08T14:26:37","date_gmt":"2014-09-08T12:26:37","guid":{"rendered":""},"modified":"2014-09-11T09:14:09","modified_gmt":"2014-09-11T07:14:09","slug":"hausse-des-remittences-au-kosovo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/hausse-des-remittences-au-kosovo\/","title":{"rendered":"Hausse des r\u00e9mittences au Kosovo"},"content":{"rendered":"<div dir=\"ltr\">L\u2019argent de la diaspora continue d\u2019\u00eatre la source la plus importante pour la survie et le d\u00e9veloppement \u00e9conomique du Kosovo. Apr\u00e8s beaucoup de sp\u00e9culations sur une \u00ab baisse \u00bb de cette source, ce sont des nouvelles plut\u00f4t optimistes qui nous arrivent : selon la banque centrale du Kosovo, la hausse s\u2019\u00e9levait \u00e0 2.4% par rapport \u00e0 l\u2019ann\u00e9e pass\u00e9e.<\/p>\n<p>La diaspora kosovare reste le pilier principal de la stabilit\u00e9 sociale. Les entr\u00e9es d\u2019argent sont d\u00e9pens\u00e9es principalement dans la consommation, selon lajmi.net. Les statistiques bancaires indiquent que les r\u00e9mittences de la diaspora atteignent la somme de 650 millions d\u2019euros, ou alors 18 pourcent du produit int\u00e9rieur brut.<\/p>\n<p>Les pr\u00e9visions de la banque centrale parlent d\u2019une tendance \u00e0 la hausse pour la fin de ce mois \u00e9galement, selon Sokol Havolli, vice-directeur des analyses macro-\u00e9conomiques \u00e0 la banque centrale.<\/p>\n<p>Ibrahim Makolli, le ministre de la diaspora, consid\u00e8re qu\u2019un facteur cl\u00e9 au d\u00e9veloppement \u00e9conomique du pays est l\u2019argent envoy\u00e9 par la diaspora kosovare. Le ministre consid\u00e8re que cette aide peut \u00e0 pr\u00e9sent servir au d\u00e9veloppement des PME.<\/p>\n<p>Les experts en questions \u00e9conomiques demandent \u00e0 ce que les rentr\u00e9es d\u2019argent venant de la diaspora soient r\u00e9orient\u00e9es vers le d\u00e9veloppement \u00e9conomique.<\/p>\n<p>La diaspora kosovare a exprim\u00e9 son int\u00e9r\u00eat derni\u00e8rement pour cr\u00e9er des fonds de d\u00e9veloppement uniques. Jusqu\u2019\u00e0 pr\u00e9sent, rien de concret n\u2019a \u00e9t\u00e9 r\u00e9alis\u00e9.<\/p>\n<p>L\u2019analyste Naim Gashi estime quant \u00e0 lui que l\u2019investissement de la diaspora dans les PME pourrait avoir un impact important sur l\u2019\u00e9conomie.<\/p>\n<p>Depuis 2004 et jusqu\u2019en d\u00e9cembre 2013, les migrants ont envoy\u00e9 au Kosovo un total de 5 milliards 347 millions 800 milles euros. Le premier trimestre indique un total de 130.8 millions d\u2019euros envoy\u00e9s par la diaspora. \u00c0 la m\u00eame p\u00e9riode de l\u2019ann\u00e9e pass\u00e9e, la somme \u00e9tait de 127.8 millions. C\u2019est une hausse 3 millions que nous montre le rapport de la banque centrale du Kosovo.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u3000<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>\u3000<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 2004 jusqu&#8217;en d\u00e9cembre 2013, la diaspora a envoy\u00e9 au Kosovo plus de 5 millards d&#8217;euros. Le premier trimestre 2014 indique un chiffre de 127.8 millions.  <\/p>\n","protected":false},"author":40,"featured_media":49984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65453"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49984"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65453"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65453"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}