{"id":65428,"date":"2014-08-08T12:31:53","date_gmt":"2014-08-08T10:31:53","guid":{"rendered":""},"modified":"2014-08-27T15:05:26","modified_gmt":"2014-08-27T13:05:26","slug":"des-suisses-promettent-une-usine-de-plastique-a-gjilan","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/des-suisses-promettent-une-usine-de-plastique-a-gjilan\/","title":{"rendered":"Des Suisses promettent une usine de plastique \u00e0 Gjilan"},"content":{"rendered":"<p>Des entrepreneurs de Suisse sont int\u00e9ress\u00e9s \u00e0 construire une usine de traitement de plastique destin\u00e9e aux automobiles. Cet int\u00e9r\u00eat des H\u00e9lv\u00e8tes est soutenu par le maire de Gjilan, Lutfi Haziri.<\/p>\n<p>Ce dernier a affirm\u00e9 que c\u2019est avec grand plaisir qu\u2019il accueillait les entrepreneurs puissants venant d\u2019Europe, lesquels sont int\u00e9ress\u00e9s \u00e0 investir dans diff\u00e9rents secteurs de la municipalit\u00e9. M. Haziri a prononc\u00e9 ces mots apr\u00e8s avoir rencontr\u00e9 l\u2019un des hommes d\u2019affaires les plus importants de Suisse, Jurg Gehrig, de l\u2019entreprise \u201cAgd Swiss Plastic\u201d.<\/p>\n<p>Le maire de Gjilan&nbsp;a indiqu\u00e9 que la municipalit\u00e9 de Gjilan accueillait \u00e0 bras ouverts les investisseurs d\u2019Europe et du monde entier, dans l\u2019int\u00e9r\u00eat d\u2019une collaboration fructueuse.<\/p>\n<p>De son c\u00f4t\u00e9, l\u2019homme d\u2019affaires de Suisse Jurg Gehring a remerci\u00e9 Haziri pour son accueil, et a expliqu\u00e9 que sa venue \u00e0 Gjilan avait pour but d\u2019\u00e9valuer les possibilit\u00e9s de construire une usine pour le traitement d&#8217;une plastique de qualit\u00e9, sp\u00e9cifiquement d\u00e9di\u00e9e aux voitures.<\/p>\n<p>Le maire Haziri a par ailleurs tenu a donner des garanties quant aux conditions d\u2019investissements. Monsieur Gehring s\u2019est dit impression\u00e9 par l\u2019accueil et la possibilit\u00e9 qui lui a \u00e9t\u00e9 offerte d\u2019investir \u00e0 Gjilan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monsieur Jurg Gehrig de l&#8217;entreprise &#8220;Agd Swiss Plastic&#8221; a exprim\u00e9 son int\u00e9r\u00eat pour la construction d&#8217;une usine pour le traitement du plastique de qualit\u00e9<\/p>\n","protected":false},"author":40,"featured_media":53225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1161,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-investissement","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65428"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/53225"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65428"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65428"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}