{"id":65375,"date":"2014-05-27T20:52:46","date_gmt":"2014-05-27T18:52:46","guid":{"rendered":""},"modified":"2014-05-29T22:15:18","modified_gmt":"2014-05-29T20:15:18","slug":"les-preuves-du-passe-pour-ramener-la-paix-dans-lavenir","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/les-preuves-du-passe-pour-ramener-la-paix-dans-lavenir\/","title":{"rendered":"Les preuves du pass\u00e9 pour ramener la paix dans l&#8217;avenir"},"content":{"rendered":"<p>C&#8217;est au cours de la Semaine de la Tol\u00e9rance et de la R\u00e9conciliation que l&#8217;ouvrage intitul\u00e9 \u00ab&nbsp;La destruction du patrimoine historique durant la guerre du Kosovo 1998-1999&nbsp;\u00bb a \u00e9t\u00e9 lanc\u00e9 \u00e0 Prishtina. Le livre documente le processus de r\u00e9conciliation entre les diff\u00e9rentes communaut\u00e9s religieuses du pays. L&#8217;auteur du livre, Sabri Bajgora, est l&#8217;imam le plus r\u00e9put\u00e9 du pays. Le livre a \u00e9t\u00e9 publi\u00e9 par Robert Elsie, une figure \u00e9minente de l&#8217;\u00e9tude de l&#8217;histoire et de la culture albanaise ainsi que par Petrit Selimi, vice-ministre kosovar des Affaires ext\u00e9rieures.<\/p>\n<p>Le livre est pr\u00e9fac\u00e9 par Andras Riedlmayer, du programme Aga Khan pour l&#8217;Architecture islamique \u00e0 l&#8217;Universit\u00e9 de Harvard. La publication de l&#8217;ouvrage a \u00e9t\u00e9 soutenue par le minist\u00e8re kosovar des Affaires ext\u00e9rieures ainsi que par plusieurs donateurs internationaux, dont Intefaith Kosova.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nouvelle parution de Sabri Bajgora, \u00e9dit\u00e9e par Robert Elsie et Petrit Selimi et intitul\u00e9e \u00ab La destruction du patrimoine islamique durant la guerre du Kosovo 1998-1999 \u00bb vient d&#8217;\u00eatre inaugur\u00e9e \u00e0 Prishtina. <\/p>\n","protected":false},"author":19,"featured_media":51826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65375"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/51826"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65375"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65375"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}