{"id":65368,"date":"2014-05-20T20:23:56","date_gmt":"2014-05-20T18:23:56","guid":{"rendered":""},"modified":"2014-05-21T09:14:12","modified_gmt":"2014-05-21T07:14:12","slug":"des-produits-de-qualites-differentes-pour-leurope-et-pour-les-balkans","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/des-produits-de-qualites-differentes-pour-leurope-et-pour-les-balkans\/","title":{"rendered":"Des  produits de qualit\u00e9s diff\u00e9rentes pour l\u2019Europe, et pour les Balkans"},"content":{"rendered":"<p>Selon les experts cit\u00e9s par le journal mac\u00e9donien \u00ab&nbsp;Koha&nbsp;\u00bb, les producteurs ne seraient pas tenus de vendre des produits d&#8217;une qualit\u00e9 similaire dans tous les pays de l&#8217;Union europe\u0301enne, tant qu&#8217;ils s&#8217;assurent de respecter les principes fondamentaux garantissant la s\u00e9curit\u00e9 des produits alimentaires et qu&#8217;ils respectent la v\u00e9racit\u00e9 de l&#8217;\u00e9tiquetage.<em> <br \/><\/em><\/p>\n<p>L&#8217;association des consommateurs de Mac\u00e9doine explique que les cas de plaintes concernant cette question sont relativement rares. Cela ne signifie cependant pas que ce ph\u00e9nom\u00e8ne ne soit pas pr\u00e9sent. \u00ab&nbsp;Nous avons effectivement remarqu\u00e9 une diff\u00e9rence dans la qualit\u00e9 des produits que l&#8217;on trouve sur nos march\u00e9s, par rapport aux m\u00eames produits vendus dans les pays de l&#8217;UE&nbsp;\u00bb, explique Marija Llon\u00e7ar-Vellkova, pr\u00e9sidente de l&#8217;Organisation des Consommateurs de Mac\u00e9doine. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une partie des produits vendus dans les Balkans ne seraient pas d&#8217;aussi bonne qualit\u00e9 que les produits similaires que l&#8217;on trouve sur les march\u00e9s des pays europ\u00e9ens<\/p>\n","protected":false},"author":19,"featured_media":51716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65368"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/51716"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65368"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65368"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}