{"id":65345,"date":"2014-04-28T08:13:27","date_gmt":"2014-04-28T06:13:27","guid":{"rendered":""},"modified":"2014-04-29T12:57:32","modified_gmt":"2014-04-29T10:57:32","slug":"le-vmro-et-le-bdi-vainqueurs-des-elections-en-macedoine","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-vmro-et-le-bdi-vainqueurs-des-elections-en-macedoine\/","title":{"rendered":"Le VMRO et le BDI, vainqueurs des \u00e9lections en Mac\u00e9doine"},"content":{"rendered":"<p>En Mac\u00e9doine, le d\u00e9pouillement des votes s\u2019est cl\u00f4tur\u00e9 ce lundi aux aurores. Les r\u00e9sultats pr\u00e9liminaires annoncent une victoire du parti de Nikola Gruevski, le VMRO DPMNE, avec 42% des voix. Il est suivi du LSDM, qui recueille 24% des voix. Du c\u00f4t\u00e9 de la communaut\u00e9 albanaise, c\u2019est le BDI de Ali Ahmeti qui sort gagnant, avec 13,4% des voix. Le PDSH a remport\u00e9 5,82% des voix, le DM 0,83%, le RDK 1,56%, et le GROM 2,72%.&nbsp;<\/p>\n<p>Il s\u2019agissait l\u00e0 des cinqui\u00e8mes \u00e9lections parlementaires en Mac\u00e9doine, depuis l\u2019ind\u00e9pendance du pays. Le taux de participation aux \u00e9lections parlementaires a \u00e9t\u00e9 de 63% et tout le processus s\u2019est d\u00e9roul\u00e9 sans incident notable. Pour la Commission centrale des \u00e9lections, il s\u2019agit d\u2019un v\u00e9ritable succ\u00e8s.<\/p>\n<p>Le candidat du VMRO-DPMNE, Gjorgje Ivanov, a \u00e9t\u00e9 \u00e9lu au si\u00e8ge de pr\u00e9sident. Il a remport\u00e9 le titre en ballotage, avec 54,4% des voix. Il a battu son adversaire de LSDM, Stevo Pendarovski. Les citoyens albanais ont quant \u00e0 eux tr\u00e8s largement boycott\u00e9 les \u00e9lections pr\u00e9sidentielles.<\/p>\n<p>Avant m\u00eame la fin du d\u00e9pouillement des votes, les deux leaders des grands partis albanais, Ali Ahmeti (BDI) et Menduh Tha\u00e7i (PDSH) ont annonc\u00e9 leur victoire et se sont d\u00e9clar\u00e9s pr\u00eats \u00e0 faire partie du nouveau gouvernement. Ali Ahmeti a d\u00e9clar\u00e9 que son parti f\u00eatait une des victoires les plus \u00e9clatantes de son histoire, dont le d\u00e9but remonte \u00e0 la sortie du conflit de 2001 en Mac\u00e9doine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon les r\u00e9sultats pr\u00e9liminaires, ce sont le parti nationaliste VMRO DPMNE et le BDI qui sortent vainqueurs des derni\u00e8res \u00e9lections mac\u00e9doniennes. Gjorgje Ivanov a \u00e9t\u00e9 \u00e9lu pr\u00e9sident \u00e0 une grande majorit\u00e9. <\/p>\n","protected":false},"author":40,"featured_media":51238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65345"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65345\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/51238"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65345"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65345"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}