{"id":65333,"date":"2014-04-14T10:55:37","date_gmt":"2014-04-14T08:55:37","guid":{"rendered":""},"modified":"2014-04-15T09:10:42","modified_gmt":"2014-04-15T07:10:42","slug":"macedoine-ivanov-et-pendarovksi-partent-en-ballotage","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/macedoine-ivanov-et-pendarovksi-partent-en-ballotage\/","title":{"rendered":"Mac\u00e9doine, Ivanov et Pendarovksi partent en ballotage"},"content":{"rendered":"<p>Le candidat du VMRO DPMNE, Gjorgje Ivanov, est le vainqueur des \u00e9lections pr\u00e9liminaires mac\u00e9doniennes de ce dimanche. Selon les r\u00e9sultats annon\u00e7\u00e9s par la commission centrale des \u00e9lections, il a remport\u00e9 25% des voix. Stevo Pendarovski, quant \u00e0 lui, remporte 18,3% des voix. Le candidat albanais Iljaz Halimi (PDSH) est \u00e9limin\u00e9 avec 2,19% des voix, tout comme Zoran Popovski (GROM), avec 1,76% des votes. <\/p>\n<p>Selon les donn\u00e9es officielles, la participation \u00e9lectorale a \u00e9t\u00e9 de pr\u00e8s de 49%. Le deuxi\u00e8me tour des \u00e9lections est pr\u00e9vu pour le 27 avril prochain.<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9sultats des \u00e9lections pr\u00e9sidentielles en Mac\u00e9doine annoncent une t\u00eate d&#8217;avance pour Gjorgje Ivanov, qui remporte une majorit\u00e9 des votes. Il ira en ballotage avec son adversaire Stevo Pendarovski. Iljaz Halimi est arriv\u00e9 en troisi\u00e8me position. <\/p>\n","protected":false},"author":19,"featured_media":51017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65333"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/51017"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65333"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65333"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}