{"id":65302,"date":"2014-03-21T08:37:12","date_gmt":"2014-03-21T07:37:12","guid":{"rendered":""},"modified":"2014-03-31T10:23:37","modified_gmt":"2014-03-31T08:23:37","slug":"le-kosovo-en-mal-dinvestissements-etrangers-directs","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-kosovo-en-mal-dinvestissements-etrangers-directs\/","title":{"rendered":"Le Kosovo en mal d&#8217;investissements \u00e9trangers directs"},"content":{"rendered":"<p>L&#8217;ann\u00e9e pass\u00e9e a \u00e9t\u00e9 marqu\u00e9e par le taux d&#8217;investissements \u00e9trangers directs le plus bas depuis 2005. Pour les experts de l&#8217;\u00e9conomie, cette mauvaise passe peut s&#8217;expliquer par la crise \u00e9conomique ainsi que par des lois mal adapt\u00e9es.<\/p>\n<p>Si le minist\u00e8re kosovar du Commerce et de l&#8217;Industrie affirme avoir fait des efforts afin d&#8217;am\u00e9liorer le climat entrepreneurial du pays, les chiffres montrent le contraire&nbsp;: les investissements \u00e9trangers directs sont tomb\u00e9s \u00e0 4,3&nbsp;% du PIB. Pour Valdrin Llula, responsable de l&#8217;Agence pour la Promotion des Investissements, cette baisse est li\u00e9e \u00e0 la crise \u00e9conomique en Europe.<\/p>\n<p><strong>Croissance \u00e9conomique de 4,5&nbsp;%<\/strong><\/p>\n<p>A l&#8217;occasion d&#8217;une conf\u00e9rence de la Banque europ\u00e9enne pour les Investissements, le Premier ministre Hashim Tha\u00e7i a d\u00e9clar\u00e9 que le Kosovo avait sensiblement am\u00e9lior\u00e9 le climat entrepreneurial du mondes des affaires et que le pays connaissait actuellement une croissance \u00e9conomique de 4,5&nbsp;%.<\/p>\n<p>Cependant, selon les experts du Groupe d&#8217;Etude juridique et politique (GSJP), les chiffres positifs de la derni\u00e8re d\u00e9cennie ne permettraient pas de croire \u00e0 une croissance \u00e9conomique sans qu&#8217;il ne soit n\u00e9cessaire de stimuler le secteur priv\u00e9 et les investissements. Pour Arb\u00ebresha Loxha, du GSJP, l&#8217;arriv\u00e9e d&#8217;investisseurs \u00e9trangers est une n\u00e9cessit\u00e9. \u00ab&nbsp;Les investisseurs continuent \u00e0 regarder le Kosovo d&#8217;un mauvais oeil&nbsp;\u00bb, a-t-elle d\u00e9plor\u00e9 lors d&#8217;une conf\u00e9rence du GSJP<\/p>\n<p>Le ministre du Commerce et de l&#8217;Industrie, Bernard Nikaj, a quant \u00e0 lui expliqu\u00e9 que le gouvernement avait facilit\u00e9 les processus administratifs n\u00e9cessaires pour l&#8217;enregistrement d&#8217;une entreprise&nbsp;: ces formalit\u00e9s auraient \u00e9t\u00e9 raccourcies, passant de 52 \u00e0 3 jours seulement.<\/p>\n<p><strong>La crise \u00e9conomique a endormi le Kosovo<\/strong><\/p>\n<p>Naim Gashi est professeur d&#8217;\u00e9conomie \u00e0 l&#8217;Universit\u00e9 de Mitrovica. Selon lui, la crise \u00e9conomique qui s\u00e9vit en Europe et dans le monde depuis quelques ann\u00e9es n&#8217;a pas touch\u00e9 uniquement les investissements \u00e9trangers au Kosovo, mais s&#8217;\u00e9tend \u00e9galement dans les pays de la r\u00e9gion. \u00ab&nbsp;Lorsqu&#8217;il y a des turbulences sur le march\u00e9 financier global, les investisseurs prennent peur&nbsp;\u00bb, a-t-il expliqu\u00e9. Selon lui, les pays d&#8217;Europe de l&#8217;Est comme le Kosovo attirent les investissements \u00e9trangers lors de grandes privatisations dans les secteurs de l&#8217;\u00e9nergie, des minerais ou de la t\u00e9l\u00e9communication. Dans le cas du Kosovo, l&#8217;\u00e9chec de la privatisation des PTK l&#8217;ann\u00e9e pass\u00e9e a port\u00e9 un coup aux chiffres mesurant l&#8217;entr\u00e9e des investissements \u00e9trangers sur le territoire national.<\/p>\n<p>Pour l&#8217;\u00e9conomiste, le probl\u00e8me ne r\u00e9side pas dans la fuite des investissements \u00e9trangers, mais dans leur h\u00e9sitation \u00e0 venir s&#8217;installer dans le pays. \u00ab&nbsp;Le probl\u00e8me principal r\u00e9side dans la loi. Il faudrait baisser les taux d&#8217;int\u00e9r\u00eats bancaires, am\u00e9liorer les infrastructures, stabiliser les syst\u00e8mes de distribution en \u00e9nergie, simplifier les proc\u00e9dures bureaucratiques, etc&nbsp;\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>Pour le pr\u00e9sident de la Chambre \u00e9conomique am\u00e9ricaine au Kosovo, Arian Zeka, le statut politique un peu flou du Kosovo fait \u00e9galement partie du probl\u00e8me. \u00ab&nbsp;Ce qui est paradoxal, c&#8217;est que l&#8217;arriv\u00e9e d&#8217;investissements \u00e9trangers \u00e9tait plus forte durant les quelques ann\u00e9es pr\u00e9c\u00e9dant la d\u00e9claration de l&#8217;ind\u00e9pendante que durant les quelques ann\u00e9es apr\u00e8s. Evidemment, cela correspond \u00e9galement \u00e0 l&#8217;av\u00e8nement de la crise \u00e9conomique dans le monde et notamment en Europe, l\u00e0 d&#8217;o\u00f9 une part tr\u00e8s importante des investissements directs viennent&nbsp;\u00bb, a expliqu\u00e9 Zeka.<\/p>\n<p><strong>Le Kosovo, mal en point au niveau de la loi<\/strong><\/p>\n<p>Selon lui, les pays de la r\u00e9gion auraient men\u00e9 une campagne plus agressive afin d&#8217;attirer les investisseurs \u00e9trangers. \u00ab&nbsp;Cette campagne a \u00e9t\u00e9 accompagn\u00e9e d&#8217;avantages fiscaux et mon\u00e9taires importants qui ont plu aux investisseurs \u00e9trangers. Chez nous, les avanc\u00e9es se sont faites au niveau de la simplification des d\u00e9marches bureaucratiques, mais dans la pratique, notamment au niveau de la loi et du respect des contrats, nous n&#8217;avons pas effectu\u00e9 de grands progr\u00e8s&nbsp;\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>Pour lui le gouvernement kosovar devrait mettre en place un nouveau plan afin de rendre le pays attractif, notamment au niveau fiscal. \u00ab&nbsp;Les politiques fiscales doivent \u00eatre revues afin d&#8217;\u00eatre attractives pour le secteur de la production, un des domaines ayant le plus de potentiel aux yeux des investisseurs \u00e9trangers&nbsp;\u00bb, a-t-il conclu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon les donn\u00e9es de la Banque centrale du Kosovo (BQK), les investissements \u00e9trangers directs au Kosovo auraient baiss\u00e9 de 200 millions d&#8217;euros entre 2007 et 2013. Le Kosovo reste le pays de la r\u00e9gion le moins bien loti en la mati\u00e8re. <\/p>\n","protected":false},"author":19,"featured_media":50550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65302"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65302\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/50550"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65302"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65302"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}