{"id":65274,"date":"2014-03-02T08:59:38","date_gmt":"2014-03-02T07:59:38","guid":{"rendered":""},"modified":"2014-03-03T11:14:58","modified_gmt":"2014-03-03T09:14:58","slug":"les-eleves-de-gostivar-rentrent-de-suisse-avec-de-nouvelles-experiences","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/les-eleves-de-gostivar-rentrent-de-suisse-avec-de-nouvelles-experiences\/","title":{"rendered":"Les \u00e9l\u00e8ves de Gostivar rentrent de Suisse avec de nouvelles exp\u00e9riences"},"content":{"rendered":"<p>Ce projet a \u00e9t\u00e9 organis\u00e9 en partenariat avec l&#8217;organisation des jeunes \u00ab&nbsp;Sega&nbsp;\u00bb. Il a \u00e9t\u00e9 soutenu par le minist\u00e8re de l&#8217;Enseignement et des Sciences de la R\u00e9publique de Mac\u00e9doine. Dans le cadre de ce projet, huit \u00e9l\u00e8ves s\u00e9lectionn\u00e9s par leur \u00e9cole, ont repr\u00e9sent\u00e9 la ville de Gostivar lors d&#8217;un s\u00e9jour de 3 semaines en Suisse.<\/p>\n<p>\u00ab&nbsp;Ils \u00e9taient nos ambassadeurs en Suisse. Ils repr\u00e9sentaient notre \u00e9cole, notre commune et notre pays. L&#8217;objectif \u00e9tait qu&#8217;ils rentrent avec de nouvelles exp\u00e9riences \u00e0 transmettre et \u00e0 partager. Le but \u00e9tait \u00e9galement d&#8217;encourager la coexistence multiculturelle pacifique&nbsp;\u00bb, a d\u00e9clar\u00e9 Jovanka Ognjanoska, directrice de l&#8217;\u00e9cole.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des \u00e9l\u00e8ves du lyc\u00e9e \u00e9conomique de la ville de Gostivar (Mac\u00e9doine) ont particip\u00e9 pour la deuxi\u00e8me ann\u00e9e de suite \u00e0 un \u00ab camps pour enfants \u00bb en Suisse. Ces \u00e9l\u00e8ves ont ainsi eu l&#8217;occasion de montrer qu&#8217;ils venaient d&#8217;un pays multilingue, un pays de tol\u00e9rance interethnique et interreligieuse.<\/p>\n","protected":false},"author":19,"featured_media":50142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65274"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/50142"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65274"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65274"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}