{"id":65265,"date":"2014-02-23T15:16:29","date_gmt":"2014-02-23T14:16:29","guid":{"rendered":""},"modified":"2014-02-24T08:38:07","modified_gmt":"2014-02-24T06:38:07","slug":"des-janvier-2015-les-kosovars-disposeront-dune-assurance-maladie","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/des-janvier-2015-les-kosovars-disposeront-dune-assurance-maladie\/","title":{"rendered":"D\u00e8s janvier 2015, les Kosovars disposeront d&#8217;une assurance maladie"},"content":{"rendered":"<p>La R\u00e9publique du Kosovo est le seul pays en Europe qui ne fonctionne pas sur le mod\u00e8le des assurances-maladie. Depuis la fin de la guerre (1999), la plupart des services m\u00e9dicaux sont gratuits. Cette ann\u00e9e, le gouvernement kosovar a pr\u00e9par\u00e9 une nouvelle loi sur la question. Elle entrera en vigueur le 1er&nbsp;janvier 2015.<\/p>\n<p>Le projet pour les assurances-maladie, mont\u00e9 par le Minist\u00e8re de la sant\u00e9, a \u00e9t\u00e9 ratifi\u00e9 par le Parlement kosovar il y a maintenant deux semaines. Faik Hoti, directeur du D\u00e9partement Communication du minist\u00e8re, a d\u00e9clar\u00e9 que ce projet de loi allait offrir des services de qualit\u00e9 aux citoyens. \u00abLes citoyens vont payer des primes (sauf les cat\u00e9gories de personnes exempt\u00e9es) et auront acc\u00e8s \u00e0 un syst\u00e8me de soins de bien meilleure qualit\u00e9 qu&#8217;aujourd&#8217;hui\u00bb, a d\u00e9clar\u00e9 Faik Hoti au journal \u00abZ\u00ebri\u00bb. Selon lui, ce projet de loi n&#8217;alourdira pas le budget de l&#8217;Etat. Le syst\u00e8me est sens\u00e9 \u00eatre financ\u00e9 par les primes r\u00e9colt\u00e9es.<\/p>\n<p>Certaines cat\u00e9gories de personnes seront exempt\u00e9es de primes, et auront un acc\u00e8s gratuit au soin. Il s&#8217;agit des familles pauvres b\u00e9n\u00e9ficiant de l&#8217;aide sociale, des prisonniers, des individus vivant au sein d&#8217;institutions \u00e9tatiques (les orphelinats et autres foyers), des personnes \u00e0 capacit\u00e9s limit\u00e9es, des personnes \u00e2g\u00e9es vivant en maison de retraite, etc.<\/p>\n<p>La loi pr\u00e9voit \u00e9galement que les employ\u00e9s et les employeurs verseront 3,5% du salaire brut \u00e0 la caisse de l&#8217;assurance-maladie. Dans les soci\u00e9t\u00e9s ou organisations priv\u00e9es dont le chiffre d\u2019affaires ne d\u00e9passe pas les 50 mille euros annuels, c&#8217;est uniquement l&#8217;employ\u00e9 qui paiera sa participation \u00e0 hauteur de 3,5% du salaire brut. Par ailleurs, des assurances compl\u00e9mentaires priv\u00e9es pourront \u00eatre contract\u00e9es aupr\u00e8s des soci\u00e9t\u00e9s qui en proposent.<\/p>\n<p>Le projet de loi devrait \u00eatre soumis \u00e0 une deuxi\u00e8me lecture au Parlement d&#8217;ici un ou deux mois. Le minist\u00e8re esp\u00e8re que le texte passera cette deuxi\u00e8me lecture.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le projet de loi sur les assurances-maladie offrira un service de qualit\u00e9 aux citoyens kosovars. C&#8217;est ce que promet le Minist\u00e8re de la sant\u00e9. Ces assurances entreront en vigueur d\u00e8s janvier 2015.<\/p>\n","protected":false},"author":40,"featured_media":50002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65265"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/50002"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65265"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65265"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}