{"id":65263,"date":"2014-02-20T09:03:42","date_gmt":"2014-02-20T08:03:42","guid":{"rendered":""},"modified":"2014-03-03T11:13:27","modified_gmt":"2014-03-03T09:13:27","slug":"la-diaspora-soutient-les-petits-commerces","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/la-diaspora-soutient-les-petits-commerces\/","title":{"rendered":"La diaspora soutient les petits commerces"},"content":{"rendered":"<p>Au d\u00e9but du mois de f\u00e9vrier l\u2019Agence du d\u00e9veloppement r\u00e9gional \u2013 l\u2019EST (AZHR l\u2019EST) a tenu la r\u00e9union du Bord des partenaires, des membres duquel proviennent les onze municipalit\u00e9s de la r\u00e9gion de l\u2019Est du Kosovo: Gjilan, Ferizaj, Ka\u00e7anik, Kamenic\u00eb, Kllokot, Viti, Partesh, Ranillug\u00eb, Han i Elezit, Novob\u00ebrd\u00eb et Sht\u00ebrpc\u00eb. Cette rencontre constituait la premi\u00e8re r\u00e9union avec les nouveaux \u00e9lus des derni\u00e8res \u00e9lections municipales de novembre dernier.<\/p>\n<p>Lors de cette r\u00e9union, le directeur ex\u00e9cutif de l\u2019Agence du d\u00e9veloppement r\u00e9gional, Almir Hyseni, a pr\u00e9sent\u00e9 un r\u00e9sum\u00e9 en informant les participants de la r\u00e9alisation avec plein succ\u00e8s du plan de travail. A eu lieu lors de cette r\u00e9union, une pr\u00e9sentation de ces activit\u00e9s, mises en \u0153uvre dans le cadre du programme <em>D\u00e9veloppement \u00e9conomique r\u00e9gional <\/em>soutenu par le Bureau de l\u2019Union Europ\u00e9en, de m\u00eame qu\u2019une pr\u00e9sentation des activit\u00e9s \u00e0 venir que l\u2019AZHR &#8211; EST projette d\u2019entreprendre afin d\u2019aider les mairies, les ONG et la communaut\u00e9 du business dans le but d\u2019absorber le plus de subventions possibles. Fait important de cette r\u00e9union fut l\u2019\u00e9lection du maire de la commune de Kamenica, Begzad Sinani comme pr\u00e9sident du Bord des partenaires, \u00e0 un mandat annuel.<\/p>\n<p>Etait \u00e9galement pr\u00e9sent, lors de cette derni\u00e8re r\u00e9union, le chef du Secteur de coop\u00e9ration du Bureau de l\u2019UE au Kosovo, Christof Stock, qui, en les invitant, a encourag\u00e9 les participants \u00e0 travailler ensemble sur les projets communs financ\u00e9s par le Bureau de l\u2019UE au Kosovo.<\/p>\n<p>Le Bord des partenaires est un des principaux organes d\u00e9cisionnaires dans le processus de d\u00e9veloppement \u00e9conomique durable dans la r\u00e9gion de l&#8217;Est. De ce fait, l\u2019AZHR reste tr\u00e8s actif \u00e0 la recherche des possibilit\u00e9s de coop\u00e9ration avec des organisations internationales, mais aussi avec la diaspora kosovare. Il est ouvert avec les citoyens, et les invite \u00e0 exprimer leurs id\u00e9es dans le but d\u2019agrandir leurs commerces existants, voire cr\u00e9er de nouveaux commerces.<\/p>\n<p>Ainsi, en novembre dernier, l\u2019Agence avait ouvert un concours pour le meilleur business plan. Le meilleur projet b\u00e9n\u00e9ficierait d\u2019une subvention de 3000&nbsp;\u20ac \u00e0 condition que 50% de la valeur totale puisse \u00eatre cofinanc\u00e9e par la diaspora. De plus les candidats devraient \u00eatre d\u00e9pendants de leurs membres de famille vivants en Europe. Pour mieux pr\u00e9parer cet \u00e9v\u00e8nement, l\u2019AZHR a organis\u00e9 une formation afin d&#8217;entra\u00eener les candidats \u00e0 cr\u00e9er un business plan ainsi qu\u2019un projet marketing, deux domaines tr\u00e8s utiles.<\/p>\n<p>Parmi 18&nbsp;candidats, seul huit candidat&nbsp; ont \u00e9t\u00e9 retenus. Puur la majorit\u00e9, leurs business plans traitent de la production de confiseries, du traitement des d\u00e9chets, de la fourniture d\u2019\u00e9quipements de d\u00e9coration de l\u2019int\u00e9rieur, ou encore, des \u00e9quipements de vid\u00e9oprojecteurs.<\/p>\n<p>\u2018<em>\u2019Ce projet a \u00e9t\u00e9 financ\u00e9 par le Minist\u00e8re des affaires \u00e9trang\u00e8res de la Finlande par le biais de l&#8217;UNDP DEED <\/em>(Programme de d\u00e9veloppement de l\u2019ONU.l\u2019Engagement de la diaspora au d\u00e9veloppement \u00e9conomique<em>), mais nous esp\u00e9rons que cela va continuera\u2019&#8217;<\/em>&nbsp; fait remarquer Mme Dinora Klaiqi-Mehmet, manager des projets \u00e0 l\u2019AZHR \u2013 EST, qui a son si\u00e8ge \u00e0 Gjilan. Mme Klaiqi-Mehmet&nbsp; affirme que la r\u00e9gion a besoin de coop\u00e9rer avec l\u2019agence,parce que des projets il y en a, mais aussi&nbsp; parce la r\u00e9gion a besoin des petites et moyennes entreprises.<\/p>\n<p>A peine inform\u00e9e de l\u2019existence de ce concours, Feime Rexhepaj, habitante de Kopernic\u00eb, un village de la Municipalit\u00e9 de Kamenica, a aussit\u00f4t pr\u00e9sent\u00e9 sa candidature pour la participation dudit atelier sur la pr\u00e9paration des business plans. En pr\u00e9sentant la preuve de cofinancement de ce projet, par son fr\u00e8re Ejup Bi\u00e7kaj, r\u00e9sidant \u00e0 Francfort en Allemagne, Mme&nbsp;Rexhepaj a pu obtenir une subvention de 2.800\u20ac. Avec cette somme d\u00e9doubl\u00e9e elle compte \u00e9largir son commerce d\u2019alimentation traditionnelle. Actuellement, dans son magasin \u2018\u2019Tradita\u2019\u2019, elle s\u2019est focalis\u00e9e \u00e0 proposer de la confiserie traditionnelle, telle que les fameuses: <em>bakllava, trileqe<\/em>, ou encore&nbsp; diff\u00e9rentes sortes de tatlive; des gourmandises qu\u2019elle pr\u00e9pare chez elle pour ensuite les distribuer sur demande.<\/p>\n<p>\u2018<em>\u2019Depuis 2008 j\u2019ai travaill\u00e9 pour des particuliers de des restaurants de la r\u00e9gion. Mais, depuis l\u2019ann\u00e9e 2010, je fournie continuellement certains supermarch\u00e9s \u00e0 Kamenica. Je suis tr\u00e8s fi\u00e8re d\u2019avoir \u00e9t\u00e9 r\u00e9compens\u00e9e pour mes excellents produits que j\u2019ai pr\u00e9sent\u00e9s \u00e0 l\u2019occasion du salon municipal de 2012, ainsi qu\u2019au salon organis\u00e9 dans le cadre des Jours de la diaspora, en 2013&nbsp;\u2018\u2019<\/em>, confie Mme&nbsp;Rexhepaj pour albinfo.ch. D\u00e9sormais elle esp\u00e8re obtenir le soutien des autorit\u00e9s municipales pour trouver un local o\u00f9 elle pourra embaucher quatre nouveaux employ\u00e9s.<\/p>\n<p>A partir de l\u2019id\u00e9e d\u2019une petite entreprise, les b\u00e9n\u00e9ficiaires du soutien de l\u2019AZHR sont d\u00e9sormais encourag\u00e9s \u00e0 d\u00e9velopper leurs activit\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de l\u2019id\u00e9e d\u2019une petite entreprise, les b\u00e9n\u00e9ficiaires du soutien de l\u2019AZHR sont encourag\u00e9s \u00e0 d\u00e9velopper leurs activit\u00e9s.<\/p>\n","protected":false},"author":19,"featured_media":49942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65263"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49942"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65263"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65263"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}