{"id":65259,"date":"2014-02-18T09:54:30","date_gmt":"2014-02-18T08:54:30","guid":{"rendered":""},"modified":"2014-02-19T16:32:06","modified_gmt":"2014-02-19T14:32:06","slug":"les-relations-kosovo-suisse-vont-au-dela-du-football","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/les-relations-kosovo-suisse-vont-au-dela-du-football\/","title":{"rendered":"Les relations Kosovo-Suisse vont au-del\u00e0 du football"},"content":{"rendered":"<p>Le succ\u00e8s et la renomm\u00e9e des joueurs albanais \u00e9voluant dans l&#8217;\u00e9quipe de football suisse continue \u00e0 \u00eatre la principale r\u00e9f\u00e9rence lorsqu&#8217;il est question de la bonne int\u00e9gration de la communaut\u00e9 kosovare en Suisse. C&#8217;est l&#8217;exemple mobilis\u00e9 par l&#8217;ambassadeur kosovar \u00e0 Berne, Naim Malaj, dans son discours lors de la soir\u00e9e organis\u00e9e en l&#8217;honneur du 6\u00e8me anniversaire de l&#8217;ind\u00e9pendance kosovare.<\/p>\n<p>\u00ab&nbsp;Plus de la moiti\u00e9 des joueurs de l&#8217;\u00e9quipe suisse sont d&#8217;origine albanaise. Plus que cela, ils sont les meilleurs parmi les meilleurs&nbsp;\u00bb, a d\u00e9clar\u00e9 l&#8217;ambassadeur, ajoutant que \u00ab&nbsp;les Kosovars de Suisse et les Suisses du Kosovo, tous se r\u00e9jouissent des r\u00e9sultats de l&#8217;\u00e9quipe helv\u00e9tique&nbsp;\u00bb. Le Kosovo n&#8217;ayant pas l&#8217;opportunit\u00e9 de prendre part \u00e0 la prochaine Coupe du Monde, \u00ab&nbsp;il sera indirectement repr\u00e9sent\u00e9 au Br\u00e9sil par l&#8217;\u00e9quipe Suisse&nbsp;\u00bb.<\/p>\n<p>Mais les footballeurs ne sont de loin pas les seuls \u00e0 faire ce lien entre les deux pays. \u00ab&nbsp;Beaucoup d&#8217;associations contribuent \u00e0 faire ce travail, comme Albinfo.ch, Iseal, UPA, Lapsh, l&#8217;Assembl\u00e9e des Albanais de Suisse, etc&nbsp;\u00bb, a d\u00e9clar\u00e9 l&#8217;ambassadeur Malaj. Parmi les invit\u00e9s venant du Kosovo, le ministre du D\u00e9veloppement \u00e9conomique, Fadil Ismajli et le d\u00e9put\u00e9 Elmi Re\u00e7ica \u00e9taient pr\u00e9sents.<\/p>\n<p>Parmi les invit\u00e9s de la soir\u00e9e, l&#8217;ambassadeur de la R\u00e9publique Dominicaine, Huan Alcantara. Il a r\u00e9pondu avec plaisir aux questions d&#8217;albinfo.ch. \u00ab&nbsp;La R\u00e9publique Dominicaine est le premier Etat \u00e0 avoir reconnu l&#8217;ind\u00e9pendance du Kosovo. Nous sommes tr\u00e8s heureux d&#8217;avoir reconnu ce pays formidable, et je pense que le Kosovo a fait beaucoup de progr\u00e8s en six ans. Je ne pense pas qu&#8217;il doive faire face \u00e0 des probl\u00e8mes insurmontables. Je lui souhaite un excellent anniversaire, et j&#8217;esp\u00e8re avoir un jour l&#8217;occasion de visiter le pays&nbsp;\u00bb, a-t-il conclu.<\/p>\n<p>Rolf Debrunner connait bien le Kosovo. Il y a quelques ann\u00e9es de cela, il a contribu\u00e9 \u00e0 ce que soit pos\u00e9 une plaque avec la mention \u00ab&nbsp;Merci, Suisse&nbsp;\u00bb sur une avenue dans la ville de Zurich. \u00ab&nbsp;J&#8217;appr\u00e9cie le fait que la nouvelle g\u00e9n\u00e9ration de Kosovars soit de plus en plus impliqu\u00e9e dans la soci\u00e9t\u00e9 et la vie \u00e9conomique suisse. Il est bon pour l&#8217;avenir du Kosovo que le pays se tourne vers les valeurs occidentales. Mais malheureusement, un nombre important de dipl\u00f4m\u00e9s souhaitent quitter le pays pour travailler \u00e0 l&#8217;\u00e9tranger. Il faut faire en sorte que ces personnes retournent au Kosovo pour contribuer au d\u00e9veloppement du pays&nbsp;\u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n<p>Omer Xhemajli, le premier m\u00e9decin albanais \u00e0 avoir effectu\u00e9 une transplantation cardiaque \u00e9tait \u00e9galement pr\u00e9sent \u00e0 cette c\u00e9r\u00e9monie. Le dr. Xhemajli travaille \u00e0 l&#8217;h\u00f4pital de Zurich. Pour lui, ce 6\u00e8me anniversaire est un signe de succ\u00e8s pour les ann\u00e9es \u00e0 venir. \u00ab&nbsp;Lorsque l&#8217;on prend en consid\u00e9ration les \u00e9l\u00e9ments historiques, et les outils dont dispose le Kosovo, l&#8217;on remarque que le pays a fait de grands pas en avant. Nous, en tant qu&#8217;Albanais de Mac\u00e9doine, nous regardons le Kosovo avec admiration. Nous esp\u00e9rons pouvoir en arriver l\u00e0 un jour, nous aussi&nbsp;\u00bb, a d\u00e9clar\u00e9 le dr Xhemajli \u00e0 albinfo.ch<\/p>\n<p>Le professeur de sciences politiques de l&#8217;Universit\u00e9 de Prishtina, Afrim Hoti, \u00e9tait pr\u00e9sent en qualit\u00e9 de conseiller du ministre kosovar du D\u00e9veloppement \u00e9conomique. Pour Hoti, le seul fait que ce sixi\u00e8me anniversaire soit c\u00e9l\u00e9br\u00e9 dans une ambassade kosovare est un signe de succ\u00e8s. \u00ab&nbsp;Cependant, ces six ann\u00e9es ont \u00e9t\u00e9 marqu\u00e9es par de grandes opportunit\u00e9s et des r\u00e9sultats modestes. Il faut mentionner les obstacles objectifs, tel que la difficult\u00e9 de se faire reconnaitre comme Etat souverain&nbsp;\u00bb, a expliqu\u00e9 Hoti. Pour lui, les probl\u00e8mes rencontr\u00e9s par le Kosovo sont ceux des soci\u00e9t\u00e9s en transition.<\/p>\n<p>L&#8217;avocat Jeton Kryeziu, pr\u00e9sident de l&#8217;Assembl\u00e9e des Albanais de Suisse, ne partage pas cet optimisme. Selon lui, le Kosovo aurait pu aller beaucoup plus loin en six ans. Il regarde d&#8217;un oeil particuli\u00e8rement critique la n\u00e9gligence dont font preuve les autorit\u00e9s publiques du pays. Les autorisations donn\u00e9es \u00e0 des institutions \u00e9trang\u00e8res pour que celles-ci enqu\u00eatent au Kosovo est l&#8217;un des exemples de l&#8217;avocat, ainsi que l&#8217;annulation de la part de la Suisse de la convention de s\u00e9curit\u00e9 sociale avec le Kosovo. Une autre d\u00e9ception&nbsp;: \u00ab&nbsp;Cela fait des ann\u00e9es que l&#8217;on entend parler de si\u00e8ges r\u00e9serv\u00e9s \u00e0 des repr\u00e9sentants de la diaspora au Parlement kosovar. Mais rien n&#8217;a \u00e9t\u00e9 encore fait dans cette direction&nbsp;\u00bb. Pour Jeton Kryeziu, s&#8217;il y a quelques succ\u00e8s \u00e0 souligner, il reste cependant encore beaucoup de travail \u00e0 faire au Kosovo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l&#8217;occasion du 6\u00e8me anniversaire de l&#8217;ind\u00e9pendance kosovare, une r\u00e9ception a \u00e9t\u00e9 organis\u00e9e \u00e0 l&#8217;Ambassade kosovare \u00e0 Berne. Un nombre important d&#8217;ambassadeurs accr\u00e9dit\u00e9s en Suisse, de personnalit\u00e9s politiques suisses et kosovares s&#8217;y sont rencontr\u00e9es. <\/p>\n","protected":false},"author":19,"featured_media":49871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65259"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49871"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65259"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65259"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}