{"id":65226,"date":"2014-01-25T13:34:06","date_gmt":"2014-01-25T12:34:06","guid":{"rendered":""},"modified":"2014-01-27T12:13:09","modified_gmt":"2014-01-27T10:13:09","slug":"lange-de-lalbanie-marianne-graff-est-honoree-dun-prix-prestigieux","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/lange-de-lalbanie-marianne-graff-est-honoree-dun-prix-prestigieux\/","title":{"rendered":"\u00abL&#8217;Ange de l&#8217;Albanie\u00bb, Marianne Graff, est honor\u00e9e d&#8217;un prix prestigieux"},"content":{"rendered":"<p>La c\u00e9r\u00e9monie de remise des prix aura lieu le 13 mars prochain \u00e0 Vienne, \u00e0 l&#8217;occasion de l&#8217;anniversaire de la mort du Cardinal Franz K\u00f6nig (d\u00e9c\u00e9d\u00e9 2004). Marianne Graf est la pr\u00e9sidente de l&#8217;association humanitaire \u00ab&nbsp;Albania-Austria Partneschaft&nbsp;\u00bb. Depuis son arriv\u00e9e dans le pays, en 1992, elle a entrepris et r\u00e9ussi \u00e0 mettre sur pied un r\u00e9seau impressionnant d&#8217;activit\u00e9s sociales, peut-on lire sur la page Internet de la fondation \u0153cum\u00e9nique du Cardinal Graf.<\/p>\n<p>Ainsi que l&#8217;indique kleinezeitung.at, Graf s&#8217;est notamment impliqu\u00e9e dans le domaine de l&#8217;\u00e9ducation, des assurances sociales, des droits des enfants, ainsi que dans la construction de ponts et de fontaines dans les villages des montagnes albanaises.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marianne Graf, rebaptis\u00e9e \u00ab l&#8217;Ange de l&#8217;Albanie \u00bb a \u00e9t\u00e9 r\u00e9compens\u00e9e du prix Cardinal K\u00f6nig 2014 (Autriche) pour ses actions humanitaires. Avec l&#8217;aide de son mari, l&#8217;entrepreneuse sociale et ancienne consule apporte son son soutien \u00e0 l&#8217;Albanie depuis maintenant 1992.<\/p>\n","protected":false},"author":40,"featured_media":49448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65226"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49448"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65226"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65226"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}