{"id":65223,"date":"2014-01-23T19:30:33","date_gmt":"2014-01-23T18:30:33","guid":{"rendered":""},"modified":"2014-01-24T08:52:55","modified_gmt":"2014-01-24T06:52:55","slug":"le-kosovo-aura-un-bureau-de-conseil-pour-les-investisseurs-etrangers","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-kosovo-aura-un-bureau-de-conseil-pour-les-investisseurs-etrangers\/","title":{"rendered":"Le Kosovo aura un \u00ab bureau de conseil \u00bb pour les investisseurs \u00e9trangers"},"content":{"rendered":"<p>Les investissements europ\u00e9ens \u00e9taient rares au Kosovo durant l&#8217;ann\u00e9e qui vient de s&#8217;\u00e9couler. Afin de stimuler l&#8217;int\u00e9r\u00eats que certains entrepreneurs pourraient porter au pays, le repr\u00e9sentant europ\u00e9en \u00e0 Prishtina, Samuel Zhbogar, a d\u00e9cid\u00e9 de mettre sur pied un bureau de conseil destin\u00e9 aux entrepreneurs europ\u00e9en potentiellement int\u00e9ress\u00e9s. Il a annonc\u00e9 ce projet lors d&#8217;une r\u00e9union avec le gouvernement kosovar et des investisseurs europ\u00e9ens.<\/p>\n<p>Selon lui, les investisseurs \u00e9trangers d\u00e9j\u00e0 sur place pourraient se r\u00e9v\u00e9ler \u00eatre les meilleurs promoteurs du Kosovo aupr\u00e8s des entrepreneurs europ\u00e9ens. \u00ab&nbsp;Ce bureau sera en contact direct avec les minist\u00e8res, afin de favoriser au mieux l&#8217;arriv\u00e9e d&#8217;investissements \u00e9trangers&nbsp;\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le repr\u00e9sentant de l&#8217;Union europ\u00e9enne au Kosovo, Samuel Zhbogar, a promis la cr\u00e9ation d&#8217;un bureau de conseil destin\u00e9 aux investisseurs \u00e9trangers d\u00e9sirant investir au Kosovo. <\/p>\n","protected":false},"author":40,"featured_media":49424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1161,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-investissement","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65223"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49424"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65223"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65223"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}