{"id":65189,"date":"2014-01-05T10:25:42","date_gmt":"2014-01-05T09:25:42","guid":{"rendered":""},"modified":"2014-01-06T09:02:00","modified_gmt":"2014-01-06T07:02:00","slug":"la-retraite-des-emigres-albanais-vivant-en-belgique","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/la-retraite-des-emigres-albanais-vivant-en-belgique\/","title":{"rendered":"La retraite des \u00e9migr\u00e9s albanais vivant en Belgique"},"content":{"rendered":"<p>La Belgique est le premier pays avec lequel l&#8217;Albanie a sign\u00e9 une entente sur la reconnaissance des retraites, permettant aux travailleurs de toucher une rente dans le pays o\u00f9 ils ont travaill\u00e9. Le ministre albanais du Bien-\u00eatre social et de la Jeunesse, Erion Valiaj a expliqu\u00e9 aux m\u00e9dias albanais que de tels accords avec d&#8217;autres pays \u00e9taient tr\u00e8s compliqu\u00e9s \u00e0 mettre en place.<\/p>\n<p>La Gr\u00e8ce et l&#8217;Italie sont deux pays tr\u00e8s importants pour l&#8217;\u00e9migration albanaise. Au vu de leur situation financi\u00e8re, ils ont tous deux refus\u00e9 de signer ce type d&#8217;accord concernant les retraites avec l&#8217;Etat albanais. Les autorit\u00e9s albanaises sont notamment en pourparlers avec le Luxembourg afin de garantir une rente aux travailleurs ayant atteint l&#8217;\u00e2ge de la retraite.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e8s de 35 mille \u00e9migrants albanais r\u00e9sidant \u00e0 Bruxelles pourraient recevoir leur pension cette ann\u00e9e s&#8217;ils atteignent ou ont d\u00e9j\u00e0 atteint l&#8217;\u00e2ge de la retraite. <\/p>\n","protected":false},"author":19,"featured_media":49089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65189"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49089"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65189"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65189"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}