{"id":65187,"date":"2014-01-02T16:37:58","date_gmt":"2014-01-02T15:37:58","guid":{"rendered":""},"modified":"2014-01-20T12:12:35","modified_gmt":"2014-01-20T10:12:35","slug":"pacolli-le-politicien-le-plus-riche-du-kosovo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/pacolli-le-politicien-le-plus-riche-du-kosovo\/","title":{"rendered":"Pacolli, le politicien le plus riche du Kosovo"},"content":{"rendered":"<div class=\"bdy\">\n<div>Le politicien kosovar Behgjet Pacolli est \u00e9galement un homme d&#8217;affaire, notamment connu en Suisse. Son entreprise, Mabetex, est aussi active dans plusieurs pays de l&#8217;Europe de l&#8217;est.<\/div>\n<div>&nbsp;<\/div>\n<div>Pacolli est pr\u00e9sident de la Nouvelle Alliance du Kosovo, parti politique membre de la coalition gouvernementale dirig\u00e9e par le Premier ministre Hashim Tha\u00e7i.<\/div>\n<div>&nbsp;<\/div>\n<div>Apr\u00e8s Pacolli, c&#8217;est Ramiz Kelmendi qui se profile dans la liste des politiciens les plus riches du pays. Kelmendi est d\u00e9put\u00e9 de l&#8217;Alliance pour l&#8217;Avenir du Kosovo et \u00e9galement propri\u00e9taire de la chaine de supermarch\u00e9s ETC, pr\u00e9sente sur tout le territoire. Il a d\u00e9clar\u00e9 une fortune de 56 millions d&#8217;euros.<\/div>\n<div>&nbsp;<\/div>\n<div>Le Premier-ministre Hashim Tha\u00e7i, quant \u00e0 lui, d\u00e9clare une fortune bien moindre que celle de certains d\u00e9put\u00e9s.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En 2013, le vice-Premier ministre kosovar Behgjet Pacolli a d\u00e9clar\u00e9 disposer d&#8217;une fortune de 176 millions d&#8217;euros, ce qui le classe dans la liste des politiciens les plus riches du pays<\/p>\n","protected":false},"author":19,"featured_media":49063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65187"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/49063"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65187"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65187"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}