{"id":65172,"date":"2013-12-15T18:11:48","date_gmt":"2013-12-15T17:11:48","guid":{"rendered":""},"modified":"2014-01-21T12:04:47","modified_gmt":"2014-01-21T10:04:47","slug":"nouvelle-augmentation-du-droit-daccise-sur-le-tabac","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/nouvelle-augmentation-du-droit-daccise-sur-le-tabac\/","title":{"rendered":"Nouvelle augmentation du droit d&#8217;accise sur le tabac"},"content":{"rendered":"<p>A partir du premier janvier prochain, les autorit\u00e9s kosovares augmentent le droit d&#8217;accise sur le tabac de 2 euros par kilogramme. Selon cette nouvelle norme, les commer\u00e7ant vendant un kilogramme de tabac devront payer 32 euros d\u2019imp\u00f4t indirect (contre 30 euros aujourd&#8217;hui).<\/p>\n<p>Il s&#8217;agit l\u00e0 de la deuxi\u00e8me augmentation de cette taxe en moins de trois mois. Elle \u00e9tait d\u00e9j\u00e0 pass\u00e9e de 27 \u00e0 30 euros par kilogramme en octobre dernier. Le ministre kosovar des Finances, Besim Beqaj, a d\u00e9clar\u00e9 que ce changement allait \u00eatre le seul pour l&#8217;ann\u00e9e en mati\u00e8re de taxes. \u00ab&nbsp;Nous n&#8217;avons pas pr\u00e9vu de changement dans les taxations pour 2014. Le droit d&#8217;accise sur le tabac r\u00e9pond au d\u00e9veloppement de la situation \u00e0 un niveau r\u00e9gional. Nous n&#8217;avons pas souhait\u00e9 avoir le niveau d&#8217;imposition indirect le plus bas, ce qui aurait pu laisser la porte ouverte \u00e0 un type de trafic ou \u00e0 un autre&nbsp;\u00bb, a d\u00e9clar\u00e9 Beqaj pour la RTK.<\/p>\n<p>L&#8217;augmentation du droit d&#8217;accise sur le tabac de 5 euros en trois mois ne semble pas devoir impliquer une baisse des importations, selon le pr\u00e9sident de l&#8217;Association des importateurs de tabac, Ramadan Kelmend. \u00ab&nbsp;Nous ne pensons pas que nous allons assister \u00e0 une baisse des importations. Il y aura peut-\u00eatre un l\u00e9ger impact sur la circulation des cigarettes au noir, tout d\u00e9pend du droit d&#8217;accise en vigueur dans les pays voisins. Mais cela ne va avoir aucune influence sur nos importations&nbsp;\u00bb, a-t-il assur\u00e9.<\/p>\n<p>L&#8217;augmentation du droit d&#8217;accise aura cependant un impact sur le prix du tabac, continue Kelmendi. Chaque ann\u00e9e, le Kosovo importe pr\u00e8s de 3 mille 200 tonnes de cigarettes.<br \/>albinfo.ch<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En octobre dernier au Kosovo, le droit d&#8217;accise sur le tabac augmentait de 27 \u00e0 30 euros pour un kilogramme. A partir de janvier 2014, cette taxe devrait encore augmenter de 2 euros. <\/p>\n","protected":false},"author":19,"featured_media":48758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65172"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/48758"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65172"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65172"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}