{"id":65169,"date":"2013-12-09T21:46:58","date_gmt":"2013-12-09T20:46:58","guid":{"rendered":""},"modified":"2014-01-21T12:08:24","modified_gmt":"2014-01-21T10:08:24","slug":"le-lancement-des-cartes-didentite-biometriques-a-commence-au-kosovo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-lancement-des-cartes-didentite-biometriques-a-commence-au-kosovo\/","title":{"rendered":"Le lancement des cartes d&#8217;identit\u00e9 biom\u00e9triques a commenc\u00e9 au Kosovo"},"content":{"rendered":"<p>Les papiers d&#8217;identit\u00e9 biom\u00e9triques remplissent les crit\u00e8res du fond technologique et de s\u00e9curit\u00e9, en accord avec les standards de l&#8217;Union europ\u00e9enne en mati\u00e8re de haute s\u00e9curit\u00e9. \u00ab&nbsp;Il s&#8217;agit d&#8217;un jour important pour le Kosovo. A partir d&#8217;aujourd&#8217;hui, nous remplissons un crit\u00e8re de plus sur le chemin nous menant \u00e0 la lib\u00e9ralisation des visas&nbsp;\u00bb, a d\u00e9clar\u00e9 le ministre kosovar de l&#8217;Int\u00e9rieur, Bajram Rexhepi lors de la c\u00e9r\u00e9monie de lancement des cartes d&#8217;identit\u00e9 biom\u00e9triques. Il a gag\u00e9 de la tr\u00e8s haute qualit\u00e9 de ce nouveau type de documents.<\/p>\n<p>\u00ab&nbsp;Les donn\u00e9es stock\u00e9es sur la puce de la nouvelle carte d&#8217;identit\u00e9 sont tr\u00e8s compl\u00e8tes. Elles correspondent \u00e0 ce qui sera exig\u00e9 par les pays membres de l&#8217;UE \u00e0 partir de 2015. Gr\u00e2ce \u00e0 cette nouvelle technologie, les citoyens kosovars vont ainsi pouvoir passer les douanes europ\u00e9ennes munis uniquement de leurs cartes d&#8217;identit\u00e9&nbsp;\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>La compagnie mandat\u00e9e par le minist\u00e8re kosovar de l&#8217;Int\u00e9rieur pour la production de ces documents est la soci\u00e9t\u00e9 allemande Giesecke &amp; Devrient. Le co\u00fbt total de ce projet se monte \u00e0 7 millions 800 mille euros. A l&#8217;achat, ces nouvelles cartes d&#8217;identit\u00e9 co\u00fbteront 10 euros la pi\u00e8ce.<strong><br \/><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de ce mardi, le minist\u00e8re kosovar des Affaires int\u00e9rieures a commenc\u00e9 l&#8217;\u00e9mission de papiers d&#8217;identit\u00e9 biom\u00e9triques. En passant cette \u00e9tape, les autorit\u00e9s kosovares remplissent un crit\u00e8re de plus dans la liste des exigences europ\u00e9ennes en vue de la lib\u00e9ralisation des visas. <\/p>\n","protected":false},"author":40,"featured_media":48664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65169"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/48664"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65169"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65169"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}