{"id":65085,"date":"2013-09-08T16:06:14","date_gmt":"2013-09-08T14:06:14","guid":{"rendered":""},"modified":"2014-01-24T00:07:36","modified_gmt":"2014-01-23T22:07:36","slug":"renforcer-le-pouvoir-des-femmes-kosovares","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/renforcer-le-pouvoir-des-femmes-kosovares\/","title":{"rendered":"Renforcer le pouvoir des femmes kosovares"},"content":{"rendered":"<p>Am\u00e9liorer les r\u00f4les des femmes en politique, dans l&#8217;\u00e9conomie et plus g\u00e9n\u00e9ralement dans la soci\u00e9t\u00e9 est une des priorit\u00e9s du Kosovo ainsi que des pays de la r\u00e9gion. C&#8217;est ce qui a \u00e9t\u00e9 mis en avant lors de la conf\u00e9rence organis\u00e9e par le minist\u00e8re kosovar du<\/p>\n<p>Commerce et de l&#8217;Industrie en collaboration avec le Centre du Sud-Est pour l&#8217;enseignement et entrepreneuriat.<\/p>\n<p>La conf\u00e9rence s&#8217;est ouverte sur un discours de la pr\u00e9sidente kosovare Atefete Jahjaga. \u00ab Je suis heureuse de voir des femmes de pouvoir, chacune dans son domaine, ainsi que de constater le caract\u00e8re r\u00e9gional de cet \u00e9v\u00e8nement et de ces pr\u00e9occupations. Donner du pouvoir aux femmes est un objectif qui d\u00e9passe les fronti\u00e8res et les diff\u00e9rents que nous pouvons par ailleurs rencontrer \u00bb, a-t-elle d\u00e9clar\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans une conf\u00e9rence intitul\u00e9e \u00ab Les femmes et leur pouvoir dans entrepreneuriat \u00bb, organis\u00e9e \u00e0 Prishtina, l&#8217;accent a \u00e9t\u00e9 mis sur le fait que ces derni\u00e8res devraient avoir un plus grand pouvoir d&#8217;action tant au niveau politique qu&#8217;\u00e9conomique. <\/p>\n","protected":false},"author":40,"featured_media":46755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-65085","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=65085"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/65085\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/46755"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=65085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=65085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=65085"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=65085"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=65085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}