{"id":611190,"date":"2022-12-11T19:45:43","date_gmt":"2022-12-11T18:45:43","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=611190"},"modified":"2022-12-11T19:45:43","modified_gmt":"2022-12-11T18:45:43","slug":"le-conseil-federal-entend-agir-contre-le-bruit-routier-inutile","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-conseil-federal-entend-agir-contre-le-bruit-routier-inutile\/","title":{"rendered":"Le Conseil f\u00e9d\u00e9ral entend agir contre le bruit routier inutile"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Lors de sa s\u00e9ance du 9 d\u00e9cembre 2022, le Conseil f\u00e9d\u00e9ral a mis en consultation des mesures visant \u00e0 r\u00e9duire les bruits de moteurs. Celles-ci pr\u00e9voient la possibilit\u00e9 de sanctionner plus simplement et plus s\u00e9v\u00e8rement la production de bruit routier \u00e9vitable. Sont vis\u00e9s non seulement les manipulations de v\u00e9hicules (tuning), mais aussi le comportement des conducteurs. Les nouvelles dispositions permettront \u00e9galement \u00e0 la Conf\u00e9d\u00e9ration de soutenir financi\u00e8rement les cantons qui intensifient les contr\u00f4les du bruit routier.<\/strong><\/p>\n<p>Le Conseil f\u00e9d\u00e9ral entend r\u00e9duire efficacement les bruits de moteurs inutiles. \u00c0 cet effet, il met en consultation diverses mesures qui concernent non seulement des prescriptions relatives aux v\u00e9hicules mais aussi le bon usage de ces derniers. Une motion d\u00e9pos\u00e9e par la Commission de l\u2019environnement, de l\u2019am\u00e9nagement du territoire et de l\u2019\u00e9nergie (CEATE-N) exige un durcissement de cette r\u00e9glementation (motion 20.4339 \u00ab\u00a0R\u00e9duire de mani\u00e8re efficace le bruit excessif des moteurs\u00a0\u00bb).<\/p>\n<p><b>Simplification des sanctions<\/b><b><\/b><\/p>\n<p>La r\u00e9vision propos\u00e9e contient des mesures visant \u00e0 simplifier et \u00e0 durcir les sanctions en cas de manipulations d\u2019un v\u00e9hicule et de production de bruit routier inutile. Le droit en vigueur pr\u00e9voit d\u00e9j\u00e0 que les conducteurs doivent veiller \u00e0 ne pas causer de nuisances sonores qu\u2019ils peuvent \u00e9viter. Aujourd\u2019hui d\u00e9j\u00e0, quiconque g\u00e9n\u00e8re inutilement du bruit avec son v\u00e9hicule peut \u00eatre d\u00e9nonc\u00e9. Dans le cadre de la r\u00e9vision, la liste des manoeuvres consid\u00e9r\u00e9es comme g\u00e9n\u00e9ratrices de bruit inutile est \u00e9tendue et modernis\u00e9e. Tout comportement de ce type sera d\u00e9sormais consid\u00e9r\u00e9 partout et \u00e0 tout moment de la journ\u00e9e comme une nuisance punissable. Afin que ces infractions et les manipulations de v\u00e9hicules ayant une incidence sur le bruit puissent \u00eatre sanctionn\u00e9es plus simplement, de nouveaux faits r\u00e9prim\u00e9s par une amende d\u2019ordre ont \u00e9t\u00e9 d\u00e9finis. Les conducteurs seront par exemple amend\u00e9s s\u2019ils font vrombir leur moteur inutilement.<\/p>\n<p>Par ailleurs, la production de bruit \u00e9vitable pourra d\u00e9sormais \u00eatre sanctionn\u00e9e par un retrait du permis de conduire. Cependant, les personnes qui commettront cette infraction pour la premi\u00e8re fois ne recevront qu\u2019un simple avertissement. Elles ne s\u2019exposeront \u00e0 un retrait du permis de conduire d\u2019au moins un mois qu\u2019en cas de r\u00e9cidive dans les deux ans qui suivent.<\/p>\n<p>Le projet de r\u00e9vision propose en outre une interdiction des silencieux de remplacement, qui g\u00e9n\u00e8rent des \u00e9missions sonores plus \u00e9lev\u00e9es que les composants install\u00e9s \u00e0 l\u2019origine. Il pr\u00e9voit d\u2019interdire \u00e9galement l\u2019admission en Suisse de v\u00e9hicules modifi\u00e9s de la sorte. Si des manipulations ayant une incidence sur le bruit sont constat\u00e9es \u00e0 plusieurs reprises lors de contr\u00f4les, des contr\u00f4les subs\u00e9quents officiels pourront \u00eatre exig\u00e9s p\u00e9riodiquement.<\/p>\n<p>Enfin, la r\u00e9glementation propos\u00e9e cr\u00e9e les bases l\u00e9gales permettant de soutenir financi\u00e8rement les cantons qui intensifient les contr\u00f4les du bruit routier.<\/p>\n<p>Afin de faciliter l\u2019ex\u00e9cution de la r\u00e9glementation, des analyses techniques et juridiques ont \u00e9galement \u00e9t\u00e9 r\u00e9alis\u00e9es en vue de la mise en place de radars acoustiques. Il n\u2019est pour l\u2019heure pas encore possible d\u2019\u00e9valuer dans quelle mesure et dans quel d\u00e9lai des dispositifs fiables pourront \u00eatre op\u00e9rationnels.<\/p>\n<p>La consultation durera jusqu\u2019au 23 mars 2023.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sont vis\u00e9s non seulement les manipulations de v\u00e9hicules (tuning), mais aussi le comportement des conducteurs<\/p>\n","protected":false},"author":4,"featured_media":386447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1187,1170,1411,2014],"tags":[],"vendi":[],"content_country":[31835,31838,31840],"class_list":["post-611190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-breves","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr","content_country-austria-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/611190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=611190"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/611190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/386447"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=611190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=611190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=611190"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=611190"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=611190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}