{"id":539015,"date":"2022-02-10T22:50:24","date_gmt":"2022-02-10T21:50:24","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=539015"},"modified":"2022-02-10T22:39:56","modified_gmt":"2022-02-10T21:39:56","slug":"la-suisse-et-le-royaume-uni-souhaitent-renforcer-la-cooperation-en-matiere-de-sciences-de-recherche-et-dinnovation","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/la-suisse-et-le-royaume-uni-souhaitent-renforcer-la-cooperation-en-matiere-de-sciences-de-recherche-et-dinnovation\/","title":{"rendered":"La Suisse et le Royaume-Uni souhaitent renforcer la coop\u00e9ration en mati\u00e8re de sciences, de recherche et d\u2019innovation"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Le 7 f\u00e9vrier 2022, le conseiller f\u00e9d\u00e9ral Guy Parmelin a re\u00e7u George Freeman, ministre britannique de la Science, de la Recherche et de l\u2019Innovation, dans le cadre d\u2019une visite de courtoisie qui s\u2019est prolong\u00e9e par un d\u00eener avec des repr\u00e9sentants du monde scientifique et \u00e9conomique \u00e0 Berne. Le lendemain, le ministre a pris part \u00e0 une r\u00e9union de travail avec Martina Hirayama, secr\u00e9taire d\u2019\u00c9tat \u00e0 la formation, \u00e0 la recherche et \u00e0 l\u2019innovation. Les discussions ont port\u00e9 sur la coop\u00e9ration bilat\u00e9rale dans les domaines de la recherche et de l\u2019innovation.<\/strong><\/p>\n<p>La Suisse et le Royaume-Uni entretiennent des relations bilat\u00e9rales intensives dans les domaines de la recherche et de l\u2019innovation. De nombreuses coop\u00e9rations directes se sont instaur\u00e9es entre les universit\u00e9s, les chercheurs et les infrastructures de recherche. Les deux parties se sont f\u00e9licit\u00e9es de ces liens \u00e9troits tant lors de la visite de courtoisie que lors de la r\u00e9union de travail, et ont exprim\u00e9 leur volont\u00e9 de les approfondir. Le dialogue a permis d\u2019\u00e9voquer diff\u00e9rentes possibilit\u00e9s d\u2019intensifier la coop\u00e9ration en mati\u00e8re de recherche et d\u2019innovation, et d\u2019envisager \u00e0 cet \u00e9gard la signature d\u2019un m\u00e9morandum d\u2019entente.<\/p>\n<p>La coop\u00e9ration entre les deux pays dans le cadre des infrastructures de recherche internationales, dans le domaine spatial et entre les agences charg\u00e9es d\u2019encourager la recherche et l\u2019innovation a \u00e9t\u00e9 au c\u0153ur des discussions. La Suisse et le Royaume-Uni envisagent de coop\u00e9rer dans le domaine des \u00ab\u00a0fellowships\u00a0\u00bb ainsi que dans celui de la \u00ab\u00a0deep science\u00a0\u00bb, comme la m\u00e9canique quantique, les affaires spatiales et la fusion nucl\u00e9aire. Les \u00e9changes ont \u00e9galement port\u00e9 sur le programme-cadre de l\u2019UE pour la recherche et l\u2019innovation, notamment sur l\u2019\u00e9tat de l\u2019association des deux pays au programme Horizon Europe.<\/p>\n<p>Un d\u00eener r\u00e9unissant des repr\u00e9sentants des milieux acad\u00e9miques, scientifiques et \u00e9conomiques \u2013 parmi lesquels les t\u00eates dirigeantes du Fonds national suisse (FNS) et d\u2019Innosuisse, ou encore les pr\u00e9sidents du Conseil des EPF, de l\u2019EPFZ, de l\u2019EPFL, de swiss\u00aduniversities et de scienceindustries\u00a0\u2013 a en outre eu lieu le soir du 7\u00a0f\u00e9vrier, \u00e0 Berne, \u00e0 l\u2019invitation du conseiller f\u00e9d\u00e9ral Guy\u00a0Parmelin. Il y a \u00e9t\u00e9 largement question de la coop\u00e9ration dans les domaines de l\u2019enseignement sup\u00e9rieur, de la recherche et de l\u2019innovation.<\/p>\n<p>Le Royaume-Uni est l\u2019un des principaux partenaires de la Suisse dans le domaine de la formation, de la recherche et de l\u2019innovation, tant sur le plan bilat\u00e9ral que multilat\u00e9ral. Un grand nombre de coop\u00e9rations directes se sont \u00e9tablies entre les chercheurs et les institutions. Depuis 2011, le FNS a soutenu quelque 2600\u00a0projets de recherche comportant un volet de coop\u00e9ration avec le Royaume-Uni. Si l\u2019on se r\u00e9f\u00e8re au nombre de projets communs men\u00e9s dans le cadre d\u2019Horizon 2020, le Royaume-Uni figure en deuxi\u00e8me position. La Suisse et le Royaume-Uni sont \u00e9galement membres de la plupart des grandes infrastructures de recherche internationales, comme le CERN, h\u00e9berg\u00e9 en Suisse, ou le Square Kilometre Array Observatorium (SKAO), situ\u00e9 au Royaume-Uni. Ce type d\u2019infrastructures offre aux chercheurs des deux pays d\u2019excellentes plateformes de coop\u00e9ration.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La coop\u00e9ration entre les deux pays dans le cadre des infrastructures de recherche internationales, dans le domaine spatial et entre les agences charg\u00e9es d\u2019encourager la recherche et l\u2019innovation a \u00e9t\u00e9 au c\u0153ur des discussions<\/p>\n","protected":false},"author":4,"featured_media":424896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-539015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/539015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=539015"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/539015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/424896"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=539015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=539015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=539015"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=539015"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=539015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}