{"id":485964,"date":"2021-07-10T18:25:35","date_gmt":"2021-07-10T16:25:35","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=485964"},"modified":"2021-07-13T16:58:41","modified_gmt":"2021-07-13T14:58:41","slug":"la-situation-sur-le-marche-du-travail-en-juin-2021","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/la-situation-sur-le-marche-du-travail-en-juin-2021\/","title":{"rendered":"La situation sur le march\u00e9 du travail en juin 2021"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>Les ch\u00f4meurs inscrits en juin 2021 &#8211; Selon les relev\u00e9s du Secr\u00e9tariat d&#8217;Etat \u00e0 l&#8217;\u00e9conomie (SECO), \u00e0 fin juin 2021, 131\u2019821 personnes \u00e9taient inscrites au ch\u00f4mage aupr\u00e8s des offices r\u00e9gionaux de placement (ORP), soit 11\u2019145 de moins que le mois pr\u00e9c\u00e9dent. Le taux de ch\u00f4mage a diminu\u00e9, passant de 3,1% en mai 2021 \u00e0 2,8% pendant le mois sous revue. Le ch\u00f4mage a diminu\u00e9 de 18\u2019468 personnes (-12,3%) par rapport au mois correspondant de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente.<\/strong><\/p>\n<p><strong>Le ch\u00f4mage des jeunes en juin 2021<\/strong><br \/>\nLe ch\u00f4mage des jeunes (de 15 \u00e0 24 ans) a diminu\u00e9 de 991 personnes (-7,8%), passant \u00e0 11\u2019763. Par rapport au m\u00eame mois de l\u2019ann\u00e9e pr\u00e9c\u00e9dente, il a diminu\u00e9 de 5\u2019554 personnes (-32,1%).<\/p>\n<p><strong>Ch\u00f4meurs de 50-64 ans en juin 2021<\/strong><br \/>\nLe nombre des ch\u00f4meurs de 50-64 ans a diminu\u00e9 de 2\u2019526 personnes (-5,9%) pour s\u2019\u00e9tablir \u00e0 40\u2019433 personnes. Par rapport au m\u00eame mois de l\u2019ann\u00e9e pr\u00e9c\u00e9dente, cela correspond \u00e0 une augmentation de 749 personnes (+1,9%).<\/p>\n<p><strong>Demandeurs d&#8217;emploi en juin 2021<\/strong><br \/>\nL\u2019ensemble des demandeurs d\u2019emploi inscrits se chiffre \u00e0 226\u2019637 personnes, soit 10\u2019730 de moins que le mois pr\u00e9c\u00e9dent et 6\u2019817 (-2,9%) de moins qu&#8217;au m\u00eame mois de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p><strong>Places vacantes annonc\u00e9es en juin 2021<\/strong><br \/>\nLe 1er juillet 2018, l\u2019obligation d\u2019annoncer les postes vacants pour les genres de professions dont le taux de ch\u00f4mage national atteint au moins 8% a \u00e9t\u00e9 introduite dans toute la Suisse; depuis le 1er janvier 2020, cette valeur seuil est pass\u00e9e \u00e0 5%. Il a augment\u00e9 de 5\u2019462 en juin, passant \u00e0 60\u2019717. Parmi ces 60\u2019717 places, 45\u2019580 \u00e9taient soumises \u00e0 l\u2019obligation d\u2019annonce.<\/p>\n<p><strong>R\u00e9ductions de l&#8217;horaire de travail d\u00e9compt\u00e9es en avril 2021<\/strong><br \/>\nEn avril 2021, les r\u00e9ductions de l\u2019horaire de travail (ch\u00f4mage partiel) ont touch\u00e9 304\u2019284 personnes, soit 36\u2019669 de moins (-10,8%) que le mois pr\u00e9c\u00e9dent. Le nombre d\u2019entreprises ayant eu recours \u00e0 de telles mesures a diminu\u00e9 de 3\u2019574 unit\u00e9s (-8,0%), passant \u00e0 41\u2019019, celui des heures de travail perdues de 6\u2019126\u2019247 unit\u00e9s (-22,6%), pour s\u2019\u00e9tablir \u00e0 20\u2019973\u2019688 heures. L\u2019ann\u00e9e pr\u00e9c\u00e9dente \u00e0 la m\u00eame \u00e9poque (avril 2020), le ch\u00f4mage partiel avait s\u00e9vi dans 131\u2019069 entreprises, touchant 1\u2019077\u2019041 personnes et entra\u00eenant la perte de 90\u2019185\u2019271 heures de travail.<\/p>\n<p><strong>Personnes arriv\u00e9es en fin de droits en avril 2021<\/strong><br \/>\nSelon les donn\u00e9es provisoires fournies par les caisses de ch\u00f4mage, 28 personnes ont \u00e9puis\u00e9 leurs droits aux prestations de l\u2019assurance-ch\u00f4mage dans le courant du mois d\u2019avril 2021. Tout assur\u00e9 qui n\u2019a pas encore \u00e9puis\u00e9 son droit \u00e0 l\u2019indemnit\u00e9 au 1er mars 2021 re\u00e7oit au maximum 66 indemnit\u00e9s journali\u00e8res suppl\u00e9mentaires pour la p\u00e9riode du 1er mars au 31 mai 2021.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le ch\u00f4mage a diminu\u00e9 de 18\u2019468 personnes (-12,3%) par rapport au mois correspondant de l&#8217;ann\u00e9e pr\u00e9c\u00e9dente<\/p>\n","protected":false},"author":4,"featured_media":462550,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014],"tags":[],"vendi":[],"content_country":[31835,31838,31840],"class_list":["post-485964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr","content_country-austria-fr","content_country-germany-fr","content_country-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/485964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=485964"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/485964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/462550"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=485964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=485964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=485964"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=485964"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=485964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}