{"id":469235,"date":"2021-05-13T23:50:45","date_gmt":"2021-05-13T21:50:45","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=469235"},"modified":"2021-05-23T23:09:28","modified_gmt":"2021-05-23T21:09:28","slug":"le-conseil-federal-nomme-un-delegue-a-la-migration-et-a-la-securite-interieure","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-conseil-federal-nomme-un-delegue-a-la-migration-et-a-la-securite-interieure\/","title":{"rendered":"Le Conseil f\u00e9d\u00e9ral nomme un d\u00e9l\u00e9gu\u00e9 \u00e0 la migration et \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Aspect essentiel de toute politique migratoire globale, l&#8217;interaction entre la migration et la s\u00e9curit\u00e9 gagne en importance. Au niveau national, le SEM a d\u00e9j\u00e0 tenu compte de cette \u00e9volution en cr\u00e9ant une unit\u00e9 charg\u00e9e des questions relatives \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure et \u00e0 la lutte contre le terrorisme. Au vu de l&#8217;importance croissante de la coop\u00e9ration dans ce domaine avec les \u00c9tats de provenance et de transit, le SEM estime qu&#8217;il doit se renforcer en mati\u00e8re de s\u00e9curit\u00e9 internationale li\u00e9e aux migrations.<\/p>\n<h3>Axes prioritaires de cette nouvelle fonction<\/h3>\n<p>La principale t\u00e2che du d\u00e9l\u00e9gu\u00e9 \u00e0 la migration et \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure consistera \u00e0 renforcer, \u00e0 l&#8217;\u00e9chelle internationale et en collaboration avec les autorit\u00e9s partenaires, les efforts convergents d\u00e9ploy\u00e9s dans le cadre des politiques de migration et de s\u00e9curit\u00e9. Le d\u00e9l\u00e9gu\u00e9 s&#8217;int\u00e9ressera en particulier \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure et \u00e0 la lutte contre le terrorisme, ainsi qu&#8217;\u00e0 la lutte contre la traite des \u00eatres humains et le trafic de migrants.<\/p>\n<p>En se fondant sur l&#8217;analyse de d\u00e9veloppements li\u00e9s \u00e0 la s\u00e9curit\u00e9 dans le domaine des migrations en Suisse et \u00e0 l&#8217;\u00e9tranger, il proposera des mesures, identifiera des partenaires et mettra en \u0153uvre des projets. De plus, il repr\u00e9sentera le secr\u00e9taire d&#8217;\u00c9tat aux migrations pour les questions de migration et de s\u00e9curit\u00e9 int\u00e9rieure au sein d&#8217;organes strat\u00e9giques suisses ou internationaux s&#8217;occupant de s\u00e9curit\u00e9. \u00c0 cet effet, Urs von Arb conservera le titre d&#8217;ambassadeur qu&#8217;il poss\u00e9dait d\u00e9j\u00e0 dans son ancienne fonction. \u00c2g\u00e9 de 60 ans, Urs von Arb est d\u00e9l\u00e9gu\u00e9 aux questions migratoires pour le Moyen-Orient depuis\u00a02016. Ce poste ne sera pas repourvu sous cette forme compte tenu de la situation actuelle dans la r\u00e9gion.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil f\u00e9d\u00e9ral nomme un d\u00e9l\u00e9gu\u00e9 \u00e0 la migration et \u00e0 la s\u00e9curit\u00e9 int\u00e9rieure au Secr\u00e9tariat d\u2019\u00c9tat aux migrations (SEM), qui sera charg\u00e9 de se concentrer sur la lutte contre le terrorisme, la traite des \u00eatres humains et le trafic de migrants. Il tient ainsi compte de l\u2019importance croissante des questions de s\u00e9curit\u00e9 dans le domaine des migrations. Lors de sa s\u00e9ance du 12 mai 2021, il a confi\u00e9 cette mission \u00e0 Urs von Arb<\/p>\n","protected":false},"author":4,"featured_media":352683,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-469235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/469235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=469235"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/469235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/352683"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=469235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=469235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=469235"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=469235"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=469235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}