{"id":441735,"date":"2021-02-04T14:02:05","date_gmt":"2021-02-04T13:02:05","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=441735"},"modified":"2021-02-04T14:02:05","modified_gmt":"2021-02-04T13:02:05","slug":"vos-voix-comptent-a-lausanne","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/vos-voix-comptent-a-lausanne\/","title":{"rendered":"\u00ab\u00a0Vos voix comptent \u00e0 Lausanne\u00a0\u00bb"},"content":{"rendered":"<p><strong>Dans le cadre de la campagne lausanne.vote au sujet des \u00e9lections du 7 mars 2021 lanc\u00e9e par la Ville de Lausanne, Albinfo.ch a r\u00e9alis\u00e9 un entretien avec le syndic de la capitale vaudoise, Gr\u00e9goire Junod. <\/strong><\/p>\n<p>Lausanne compte une forte population d\u2019origine albanaise. C\u2019est aussi est une ville proche des villes albanaises comme Tirana, Ferizaj ou Prishtina, \u00e0 travers les liens que les d\u00e9cideurs lausannois ont su nouer. En 2019, le monde albanophone \u00e9tait l\u2019h\u00f4te de l\u2019\u00e9dition Lausanne M\u00e9diterran\u00e9e. Entretien\u00a0 avec le patron de l\u2019ex\u00e9cutif lausannois, que l\u2019on nomme syndic dans le pays de Vaud, Gr\u00e9goire Junod.<\/p>\n<p><strong><em>Allbinfo.ch\u00a0: Lausanne est une ville ouverte \u00e0 la diversit\u00e9. Comment vous voyez la question de la participation politique des \u00e9trangers jouissant du droit de vote. Autrement dit, ces personnes votent peu, en tout cas en comparaison avec les lausannois suisses. Pourquoi\u00a0?<\/em><\/strong><\/p>\n<p>Gr\u00e9goire Junod\u00a0: Le syst\u00e8me politique suisse n\u2019est pas des plus simples, il faut se mettre dedans.\u00a0Le vocabulaire utilis\u00e9 dans les documents de vote est bien souvent trop complexe. Et puis, de trop nombreuses personnes ne savent m\u00eame pas qu\u2019elles ont le droit de vote. Il faut absolument atteindre les Lausannoises et Lausannois d\u2019origine \u00e9trang\u00e8re, leur permettre de comprendre les enjeux facilement, ainsi que de se sentir inclus.es notamment \u00e0 travers cette possibilit\u00e9 de participer aux d\u00e9cisions de la collectivit\u00e9. Nous ne pourrons r\u00e9pondre aux besoins de l\u2019ensemble des Lausannoises et Lausannois qu\u2019avec la participation de toutes et tous.<\/p>\n<p><strong><em>La campagne lausanne.vote vise pr\u00e9cis\u00e9ment \u00e0 mobiliser les personnes migrantes d\u2019utiliser davantage ce droit de vote. Quelles sont les particularit\u00e9s de cette campagne\u00a0? Pensez-vous qu\u2019elle mobilisera davantage cette partie de l\u2019\u00e9lectorat\u00a0?<\/em><\/strong><\/p>\n<p>GJ\u00a0: C\u2019est en tous cas l\u2019objectif. Il s\u2019agit d\u2019encourager l\u2019ensemble de la population \u00e0 participer \u00e0 cet important rendez-vous que repr\u00e9sentent les \u00e9lections communales du 7 et du 28 mars prochains. La campagne se veut accessible, dynamique et inclusive, \u00e0 l\u2019image du cadre de vie que la Ville de Lausanne ambitionne d\u2019offrir \u00e0 ses citoyennes et citoyens.<\/p>\n<p><strong><em>Avec le contexte de pand\u00e9mie, y a-t \u2019il un risque de davantage de marginalisation socio-politique des personnes migrantes, pr\u00e9caris\u00e9es par les cons\u00e9quences de la pand\u00e9mie. Si oui, quelle est la politique de la Ville de Lausanne pour les inclure davantage dans le processus.<\/em><\/strong><\/p>\n<p>GJ\u00a0: Oui, il y a un risque de marginalisation, y compris des personnes migrantes plus nombreuses dans les cat\u00e9gories modestes et vuln\u00e9rables. \u00a0Nous devons y \u00eatre tr\u00e8s attentifs et agir. Cette campagne comme les mesures prises par la Ville de Lausanne pour soutenir les personnes vuln\u00e9rables et les secteurs \u00e9conomiques en difficult\u00e9 vont dans ce sens.<\/p>\n<p><strong><em>Un membre du conseil communal actuel, M. Kamenica, est de nouveau candidat. Avez-vous des informations si d\u2019autres candidatEs issuEs de cette importante communaut\u00e9 figurent sur les listes des formations politiques.<\/em><\/strong><\/p>\n<p>GJ\u00a0: Musa Kamenica est devenu en 2016 le premier conseiller communal albanais \u00e0 si\u00e9ger \u00e0 Lausanne. C\u2019est un signal fort pour les Lausannoises et Lausannois d\u2019origine albanaise, un exemple d\u2019int\u00e9gration qui je l\u2019esp\u00e8re va ouvrir la voie dans tous les partis politiques et permettre une meilleure repr\u00e9sentation de la population dans toute sa diversit\u00e9 au sein du corps d\u00e9lib\u00e9rant.<\/p>\n<p><strong><em>La communaut\u00e9 d\u2019origine albanaise est importante dans votre ville. Vous avez nou\u00e9 des liens proches avec cette population lausannoise, mais aussi avec des villes du Kosovo et la capitale albanaise Tirana. Quel messages adressez-vous \u00e0 cette population \u00e0 Lausanne pour qu\u2019elle fasse usage de ce droit de vote\u00a0\u00e0 Lausanne\u00a0?<\/em><\/strong><\/p>\n<p>GJ\u00a0: C\u2019est gr\u00e2ce aux Lausannoises et Lausannois d\u2019origine albanaise que la Ville de Lausanne a pu tisser les liens importants que vous \u00e9voquez, ici comme l\u00e0-bas. Les membres des associations li\u00e9\u00e9s \u00e0 cette communaut\u00e9 sont tr\u00e8s actifs et font un travail remarquable. Cette communaut\u00e9 nous a permis de conna\u00eetre bien mieux le monde albanophone, ses richesses, sa culture passionnante. Cette ouverture et ces nombreux \u00e9changes doivent avoir un \u00e9cho dans les d\u00e9cisions prises collectivement. Leur voix doivent \u00eatre entendues\u00a0; leur voix comptent\u00a0!<\/p>\n<p>Sevdail Tahiri<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la campagne lausanne.vote au sujet des \u00e9lections du 7 mars 2021 lanc\u00e9e par la Ville de Lausanne, Albinfo.ch a r\u00e9alis\u00e9 un entretien avec le syndic de la capitale vaudoise, Gr\u00e9goire Junod. Lausanne compte une forte population d\u2019origine albanaise. C\u2019est aussi est une ville proche des villes albanaises comme Tirana, Ferizaj ou [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":441737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1164,3951,1163,1170],"tags":[],"vendi":[],"content_country":[31835,31838],"class_list":["post-441735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-integration-fr","category-intervista-fr","category-fr-e-diaspora","category-vivre-en-suisse","content_country-austria-fr","content_country-germany-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/441735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=441735"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/441735\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/441737"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=441735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=441735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=441735"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=441735"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=441735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}