{"id":415202,"date":"2020-10-16T19:08:44","date_gmt":"2020-10-16T17:08:44","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=415202"},"modified":"2020-10-16T19:08:44","modified_gmt":"2020-10-16T17:08:44","slug":"vaccin-contre-le-covid-19-la-confederation-signe-un-contrat-avec-astrazeneca","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/vaccin-contre-le-covid-19-la-confederation-signe-un-contrat-avec-astrazeneca\/","title":{"rendered":"Vaccin contre le COVID-19 : la Conf\u00e9d\u00e9ration signe un contrat avec AstraZeneca"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p><strong>La Conf\u00e9d\u00e9ration souhaite que la population suisse ait rapidement acc\u00e8s aux vaccins contre le COVID-19. On ignore encore lesquels s\u2019imposeront \u00e0 terme. C\u2019est pourquoi la Conf\u00e9d\u00e9ration adopte une strat\u00e9gie diversifi\u00e9e. Entre-temps, elle a conclu un contrat avec l\u2019entreprise pharmaceutique britannique AstraZeneca et le gouvernement su\u00e9dois pour la livraison pouvant aller jusqu\u2019\u00e0 5,3 millions de doses. La population suisse aura ainsi acc\u00e8s \u00e0 un autre vaccin contre le COVID-19 si l\u2019essai clinique et l\u2019autorisation par Swissmedic aboutissent.<\/strong><\/p>\n<p>L\u2019accord entre la Commission europ\u00e9enne et AstraZeneca sur la livraison allant jusqu\u2019\u00e0 400\u00a0millions de doses en Europe constitue la base du contrat. Ces doses peuvent \u00eatre command\u00e9es par les \u00c9tats en fonction de leur population et \u00eatre retir\u00e9es en cas d\u2019autorisation. La Su\u00e8de commandera les doses pour les pays de l\u2019EEE et de l\u2019AELE qui ne sont pas membres de l&#8217;UE et les revendra aux \u00c9tats correspondants sans profit. S\u2019il est autoris\u00e9, le vaccin d\u2019AstraZeneca sera livr\u00e9 directement en Suisse. D\u00e9but octobre, AstraZeneca a d\u00e9j\u00e0 soumis une demande d\u2019autorisation \u00e0 Swissmedic.<\/p>\n<h2>Technologie bas\u00e9e sur des vecteurs<\/h2>\n<p>L\u2019entreprise britannique a d\u00e9velopp\u00e9 le vaccin AZD1222 en collaboration avec l\u2019Universit\u00e9 d\u2019Oxford et sa soci\u00e9t\u00e9 d\u00e9riv\u00e9e Vaccitech. Il s\u2019agit d\u2019un vaccin bas\u00e9 sur des vecteurs (ad\u00e9novirus), qui exprime la prot\u00e9ine de surface du coronavirus (prot\u00e9ine spike de SARS-COV 2). Il pr\u00e9pare le syst\u00e8me immunitaire \u00e0 attaquer le virus du SARS-CoV-2 lorsqu\u2019il infecte le corps.<\/p>\n<h2>Strat\u00e9gie diversifi\u00e9e<\/h2>\n<p>La Conf\u00e9d\u00e9ration mise sur l\u2019acquisition de plusieurs vaccins contre le COVID-19 issus de diverses technologies (ARNm, bas\u00e9 sur des prot\u00e9ines, bas\u00e9 sur des vecteurs), car on ignore encore quels vaccins s\u2019imposeront. Elle m\u00e8ne actuellement des n\u00e9gociations avec les fabricants d\u2019autres vaccins candidats prometteurs en vue de conclure des contrats suppl\u00e9mentaires le cas \u00e9ch\u00e9ant.<\/p>\n<p>En ao\u00fbt 2020, la Conf\u00e9d\u00e9ration a sign\u00e9 un contrat avec la soci\u00e9t\u00e9 Moderna pour 4,5 millions de doses de vaccins. En outre, elle participe \u00e0 l\u2019initiative internationale COVAX afin de se procurer des vaccins couvrant jusqu\u2019\u00e0 20\u00a0% de la population. La strat\u00e9gie et les recommandations en mati\u00e8re de vaccination d\u00e9pendront des vaccins retenus et tiendront compte des derni\u00e8res connaissances scientifiques.<\/p>\n<p>Outre la pr\u00e9vention, il est aussi important de traiter les infections au COVID-19. En \u00e9t\u00e9 2020, la Conf\u00e9d\u00e9ration s\u2019est donc assur\u00e9 l\u2019acc\u00e8s \u00e0 un m\u00e9dicament immunoth\u00e9rapeutique produit par Molecular Partners. Dans certains cas, le m\u00e9dicament pourrait \u00e9galement \u00eatre administr\u00e9 \u00e0 titre prophylactique pour prot\u00e9ger contre une infection (immunisation passive), par exemple pour le personnel hospitalier expos\u00e9 ou d\u2019autres groupes \u00e0 risque.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Conf\u00e9d\u00e9ration mise sur l\u2019acquisition de plusieurs vaccins contre le COVID-19 issus de diverses technologies (ARNm, bas\u00e9 sur des prot\u00e9ines, bas\u00e9 sur des vecteurs), car on ignore encore quels vaccins s\u2019imposeront<\/p>\n","protected":false},"author":4,"featured_media":395337,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18826,22521,24630,1170],"tags":[4418],"vendi":[],"content_country":[],"class_list":["post-415202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lajme-jeta-ne-zvicer-fr","category-coronavirus-minutes-par-minutes","category-nouvelles","category-vivre-en-suisse","tag-zvicra-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/415202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=415202"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/415202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/395337"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=415202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=415202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=415202"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=415202"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=415202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}