{"id":412736,"date":"2020-10-02T17:12:02","date_gmt":"2020-10-02T15:12:02","guid":{"rendered":"https:\/\/www.albinfo.ch\/u-ndane-cmimet-e-konkursit-letrar-te-huaj-vendore-autoktone-nga-gjetiu\/"},"modified":"2020-10-06T18:36:34","modified_gmt":"2020-10-06T16:36:34","slug":"les-prix-du-concours-litteraire-etrangers-dici-autochtones-dailleurs-ont-ete-decernes","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/les-prix-du-concours-litteraire-etrangers-dici-autochtones-dailleurs-ont-ete-decernes\/","title":{"rendered":"Les prix du concours litt\u00e9raire &#8220;Etrangers d\u2019ici, autochtones d\u2019ailleurs&#8221; ont \u00e9t\u00e9 d\u00e9cern\u00e9s"},"content":{"rendered":"<p>Les amateurs de litt\u00e9rature se sont r\u00e9unis au Coll\u00e8ge B\u00e9thusy, \u00e0 Lausanne, en pr\u00e9sence de nombreuses personnalit\u00e9s de la vie publique, institutionnelle, acad\u00e9mique et litt\u00e9raire suisse. C\u2019est la deuxi\u00e8me ann\u00e9e cons\u00e9cutive que l\u2019ISEAL collabore avec le centre (CRLR), et ce, gr\u00e2ce au soutien de la ville de Lausanne. Cette collaboration a d\u2019ailleurs \u00e9t\u00e9 salu\u00e9e par le Dr Olivier Meuwly au nom du Conseil de la Fondation ISEAL. Ce sont les membres du jury provenant de diff\u00e9rents cantons et institutions litt\u00e9raires et acad\u00e9miques qui ont donn\u00e9 une cr\u00e9dibilit\u00e9 particuli\u00e8re \u00e0 ce prix litt\u00e9raire, a-t-il affirm\u00e9.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-411930\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal-5.jpg\" alt=\"\" width=\"556\" height=\"417\" \/><\/a><\/p>\n<p>Oscar Tosato, conseiller municipal en charge des sports et de la coh\u00e9sion sociale, s\u2019est exprim\u00e9 avec enthousiasme.\u00a0 Il a soulign\u00e9 l\u2019engagement exceptionnel ainsi que l\u2019esprit novateur de l\u2019institut : ISEAL est un exemple unique en son genre, non seulement pour les Albanais, mais pour toute la Suisse et ses communaut\u00e9s \u00e9trang\u00e8res. Pour lui, c\u2019est gr\u00e2ce au travail exceptionnel d\u2019ISEAL et de son directeur, Driton Kajtazi, que l\u2019Institut est devenu une r\u00e9f\u00e9rence et une inspiration pour les autorit\u00e9s et institutions lausannoises et suisses.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-411936\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal7.jpg\" alt=\"\" width=\"556\" height=\"417\" \/><\/a><\/p>\n<p>De son c\u00f4t\u00e9, Driton Kajtazi, directeur de l&#8217;ISEAL et enseignant dans un coll\u00e8ge \u00e0 Yverdon, n\u2019a pas manqu\u00e9 d\u2019\u00e9voquer l&#8217;extraordinaire collaboration avec le Centre de Recherches sur les Lettres Romandes et son directeur, le Prof. Dr. Daniele Maggetti. Une telle c\u00e9r\u00e9monie n\u2019aurait pas pu voir le jour sans l\u2019appui de la ville de Lausanne, et en particulier, sans le soutien sans r\u00e9serve de M. Oscar Tosato. Driton Kajtazi a rappel\u00e9 avec gratitude combien le municipal M. Tosato [JL1] avait encourag\u00e9 et appuy\u00e9 la construction et les initiatives d\u2019ISEAL.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal-6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-411939\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal-6.jpg\" alt=\"\" width=\"555\" height=\"647\" \/><\/a><\/p>\n<p>Le Prof. Dr. Daniele Maggetti, Pr\u00e9sident du Jury du Prix Litt\u00e9raire &#8221; Etrangers d\u2019ici, autochtones d\u2019ailleurs &#8220;, et directeur du CSRL[JL2] , est revenu sur la gen\u00e8se du prix ainsi que sur son d\u00e9roulement dont le jury \u00e9tait compos\u00e9 par[JL3]\u00a0 : Prof. Dr. Muriel Zendel Berset, M. Bruno Pellegrino, Mme Camille Luscher, le Pr Dr Nerimane Kamberi et M. Julien Burri. Le professeur s&#8217;est f\u00e9licit\u00e9 du grand nombre de participants au concours qui ont pr\u00e9sent\u00e9 des textes dont l\u2019originalit\u00e9 et la qualit\u00e9 devaient \u00eatre salu\u00e9es. En effet, pour cette \u00e9dition, ce sont plus de vingt auteurs suisses et \u00e9trangers \u00e9tablis dans les r\u00e9gions suisse-romande, qui ont tent\u00e9 leur chance.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-411951\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal-2.jpg\" alt=\"\" width=\"554\" height=\"364\" \/><\/a><\/p>\n<p>Cette ann\u00e9e, le premier prix a \u00e9t\u00e9 partag\u00e9 par deux auteurs. En effet, il \u00e9tait impossible pour le jury de les d\u00e9partager. Le premier prix a donc \u00e9t\u00e9 remis, ex aequo, \u00e0 Mme Myriam Bolliger pour le texte: &#8220;Un dr\u00f4le de roi&#8221; et au Prof. Dr. Shyhrete Rexhaj pour son texte intitul\u00e9: &#8220;Retour sur le chemin de l\u2019\u00e9cole \u00bb. Le deuxi\u00e8me prix a \u00e9t\u00e9 d\u00e9cern\u00e9 \u00e0 Hugo Carrard pour son texte: &#8220;L\u2019Homme bleu&#8221;, alors que le troisi\u00e8me a \u00e9t\u00e9 emport\u00e9 par Mme Ang\u00e9lique Eggenschwiler pour son texte: &#8220;R\u00f4le de composition&#8221;. Le jury a \u00e9galement d\u00e9cern\u00e9 un prix sp\u00e9cial \u00e0 Mme Valbona Mulliqi qui s\u2019est pr\u00e9sent\u00e9e avec son texte: &#8220;Nous reviendrons \u00e0 nouveau&#8221;.<\/p>\n<p>Les auteurs r\u00e9compens\u00e9s ont eu l\u2019occasion de s\u2019exprimer sur le contexte et la vis\u00e9e de leur \u00e9crit. A travers leur prise de parole, on pouvait percevoir combien leur \u00e9motion avait cristallis\u00e9 celle du public.<\/p>\n<p>A l\u2019instar des \u00e9ditions pr\u00e9c\u00e9dentes, ISEAL publiera un ouvrage avec les textes des laur\u00e9ats du concours litt\u00e9raire.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-411945\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal4.jpg\" alt=\"\" width=\"555\" height=\"416\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-411948\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2020\/10\/iseal3.jpg\" alt=\"\" width=\"559\" height=\"271\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeudi 30 septembre 2020 a eu lieu la c\u00e9r\u00e9monie de remise des prix du concours litt\u00e9raire : Etrangers  d\u2019ici, autochtones d\u2019ailleurs, organis\u00e9 par l\u2019Institut Suisse d\u2019Etudes Albanaises (ISEAL) et le Centre de Recherches sur les Lettres Romandes (CRLR) de l\u2019Universit\u00e9 de Lausanne.  <\/p>\n","protected":false},"author":10,"featured_media":411943,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1164,1163,1168],"tags":[],"vendi":[],"content_country":[],"class_list":["post-412736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integration-fr","category-fr-e-diaspora","category-culture"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/412736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=412736"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/412736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/411943"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=412736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=412736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=412736"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=412736"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=412736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}