{"id":391308,"date":"2020-07-03T19:31:25","date_gmt":"2020-07-03T17:31:25","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=391308"},"modified":"2020-07-03T19:32:38","modified_gmt":"2020-07-03T17:32:38","slug":"allocation-pour-perte-de-gain-en-cas-de-mesures-destinees-a-lutter-contre-le-coronavirus","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/allocation-pour-perte-de-gain-en-cas-de-mesures-destinees-a-lutter-contre-le-coronavirus\/","title":{"rendered":"Allocation pour perte de gain en cas de mesures destin\u00e9es \u00e0 lutter contre le coronavirus"},"content":{"rendered":"<p>Depuis le 20 mars 2020, le Conseil f\u00e9d\u00e9ral a pris de nombreuses mesures pour att\u00e9nuer les cons\u00e9quences \u00e9conomiques qu\u2019occasionne la propagation du coronavirus pour les entre-prises et les employ\u00e9s concern\u00e9s.<\/p>\n<p>Des informations seront r\u00e9guli\u00e8rement actualis\u00e9es sur ce site web et seront relay\u00e9es par les caisses de compensation. Il est possible de faire valoir un droit \u00e0 l\u2019allocation pour perte de gain COVID-19 jusqu\u2019au 16 septembre 2020.<\/p>\n<p>Coronavirus: Allocation pour perte de gain (Informations caisses de compensation AVS)<br \/>\nLes parents qui doivent interrompre leur activit\u00e9 lucrative parce que la garde de leurs enfants par des tiers n\u2019est plus assur\u00e9e.<\/p>\n<p>Les personnes plac\u00e9es en quarantaine qui doivent de ce fait interrompre leur activit\u00e9 lucrative.<br \/>\nLes personnes exer\u00e7ant une activit\u00e9 ind\u00e9pendante qui subissent une perte de revenu en raison des \u2019mesures destin\u00e9es \u00e0 lutter contre le coronavirus.<\/p>\n<p>Les artistes ind\u00e9pendants dont les engagements ont \u00e9t\u00e9 annul\u00e9s ou qui ont d\u00fb annuler leurs propres manifestations en raison des mesures visant \u00e0 lutter contre le coronavirus.<br \/>\n\u00c0 partir du 1er juin 2020, les personnes travaillant dans le domaine de l\u2019\u00e9v\u00e9nementiel et ayant une position assimilable \u00e0 celle d\u2019un employeur ainsi que leurs conjointes et conjoints et leurs parte-naires enregistr\u00e9s.<\/p>\n<p><strong>Informations sur les prestations vers\u00e9es<\/strong><\/p>\n<p>Les informations se fondent sur les annonces des caisses de compensation, qui sont g\u00e9n\u00e9ralement recens\u00e9es \u00e0 un rythme hebdomadaire. Elles sont fournies sans garantie d\u2019exactitude et d\u2019exhaustivit\u00e9. Depuis l\u2019introduction de la nouvelle prestation, les caisses de compensation sont confront\u00e9es \u00e0 un nombre important de demandes, dont le traitement prend un certain temps. Ces informations ne refl\u00e8tent que les prestations d\u00e9j\u00e0 vers\u00e9es \u00e0 la date du recensement et non l\u2019ensemble des prestations dues.<\/p>\n<p>https:\/\/www.bsv.admin.ch\/bsv\/fr\/home\/assurances-sociales\/eo-msv\/grundlagen-und-gesetze\/eo-corona.html#-1708523843<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est possible de faire valoir un droit \u00e0 l\u2019allocation pour perte de gain COVID-19 jusqu\u2019au 16 septembre 2020<\/p>\n","protected":false},"author":4,"featured_media":362544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,22521,24633,1170,1411,2014],"tags":[1671],"vendi":[],"content_country":[],"class_list":["post-391308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-coronavirus-minutes-par-minutes","category-nouvelles-fr-2","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr","tag-zvicer-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/391308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=391308"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/391308\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/362544"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=391308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=391308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=391308"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=391308"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=391308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}