{"id":307164,"date":"2019-09-04T18:34:14","date_gmt":"2019-09-04T16:34:14","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=307164"},"modified":"2019-09-06T13:31:49","modified_gmt":"2019-09-06T11:31:49","slug":"investissements-dans-les-systemes-dinformation-pour-la-securite-dans-lespace-schengen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/investissements-dans-les-systemes-dinformation-pour-la-securite-dans-lespace-schengen\/","title":{"rendered":"Investissements dans les syst\u00e8mes d\u2019information pour la s\u00e9curit\u00e9 dans l\u2019espace Schengen"},"content":{"rendered":"<p>La coop\u00e9ration au titre de Schengen et Dublin est r\u00e9guli\u00e8rement adapt\u00e9e pour faire face aux nouveaux d\u00e9fis. Les efforts en ce sens se sont intensifi\u00e9s ces trois derni\u00e8res ann\u00e9es. Des investissements importants sont pr\u00e9vus dans diff\u00e9rents syst\u00e8mes d&#8217;information pour accro\u00eetre encore la s\u00e9curit\u00e9 int\u00e9rieure. Il s&#8217;agit concr\u00e8tement de renforcer le contr\u00f4le des fronti\u00e8res ext\u00e9rieures de l&#8217;espace Schengen et de resserrer la coop\u00e9ration des autorit\u00e9s nationales comp\u00e9tentes en mati\u00e8re de s\u00e9curit\u00e9 et de migrations. L&#8217;UE consacrera ces prochaines ann\u00e9es plusieurs milliards d&#8217;euros \u00e0 la r\u00e9alisation de cet objectif.<\/p>\n<h3><strong>Adaptation de diff\u00e9rents syst\u00e8mes d&#8217;information<\/strong><\/h3>\n<p>Les nouveaut\u00e9s faciliteront aussi le travail des autorit\u00e9s suisses comp\u00e9tentes en mati\u00e8re de contr\u00f4le aux fronti\u00e8res, de police, d&#8217;asile et de migrations. Les travaux de nature l\u00e9gislative et organisationnelle ont d&#8217;ores et d\u00e9j\u00e0 d\u00e9but\u00e9. Outre le D\u00e9partement f\u00e9d\u00e9ral de justice et police (DFJP), les projets concernent l&#8217;Administration f\u00e9d\u00e9rale des douanes, le D\u00e9partement f\u00e9d\u00e9ral des affaires \u00e9trang\u00e8res et les cantons.<\/p>\n<p>Des adaptations seront apport\u00e9es \u00e0 des syst\u00e8mes d&#8217;information existants, \u00e0 savoir le syst\u00e8me d&#8217;information Schengen (SIS II), le syst\u00e8me d&#8217;information sur les visas (VIS), la banque de donn\u00e9es europ\u00e9enne sur les empreintes digitales (European Dactyloscopy Database, Eurodac) et le syst\u00e8me d&#8217;information pr\u00e9alable sur les passagers (Advance Passenger Information System, API). Parall\u00e8lement, de nouveaux syst\u00e8mes seront d\u00e9velopp\u00e9s\u00a0: d&#8217;une part, le syst\u00e8me europ\u00e9en d&#8217;information et d&#8217;autorisation concernant les voyages (European Travel Information and Authorisation System, ETIAS), d&#8217;autre part le syst\u00e8me d&#8217;entr\u00e9e et de sortie (Entry\/Exit System, EES).<\/p>\n<p>Les travaux de mise en \u0153uvre de ces projets ont d&#8217;ores et d\u00e9j\u00e0 d\u00e9but\u00e9. Le Parlement a adopt\u00e9 en juin\u00a02019 l&#8217;arr\u00eat\u00e9 f\u00e9d\u00e9ral relatif \u00e0 l&#8217;EES, tandis que les consultations relatives au SIS\u00a0II et \u00e0 l&#8217;ETIAS se sont d\u00e9roul\u00e9es ce printemps. Le Conseil f\u00e9d\u00e9ral pr\u00e9voit d&#8217;adopter les messages au cours des prochains mois. Concernant les autres projets, les bases l\u00e9gales sont en cours de r\u00e9vision dans l&#8217;UE. En sa qualit\u00e9 d&#8217;\u00c9tat associ\u00e9 \u00e0 Schengen, la Suisse participe activement aux discussions et fait valoir ses int\u00e9r\u00eats.<\/p>\n<h3><strong>Interop\u00e9rabilit\u00e9 des syst\u00e8mes existants<\/strong><\/h3>\n<p>Un autre objectif est de garantir l&#8217;interop\u00e9rabilit\u00e9 des syst\u00e8mes d&#8217;information, c&#8217;est-\u00e0-dire les relier entre eux de mani\u00e8re \u00e0 faciliter et cibler la consultation des donn\u00e9es disponibles et ainsi gagner en efficacit\u00e9. Il s&#8217;agit notamment de permettre aux forces de s\u00e9curit\u00e9 de se faire rapidement une id\u00e9e pr\u00e9cise de la situation en acc\u00e9dant, avec une seule requ\u00eate, \u00e0 toutes les informations pertinentes enregistr\u00e9es dans plusieurs banques de donn\u00e9es. Les droits d&#8217;acc\u00e8s respectifs des autorit\u00e9s aux divers syst\u00e8mes ne sont toutefois pas \u00e9tendus et un niveau \u00e9lev\u00e9 de protection des donn\u00e9es est garanti. Le projet visant \u00e0 \u00e9tablir l&#8217;interop\u00e9rabilit\u00e9 sera mis en consultation au cours des prochains mois.<\/p>\n<h3><strong>Cr\u00e9dit en deux tranches<\/strong><\/h3>\n<p>Pour la mise en \u0153uvre de ces d\u00e9veloppements de l&#8217;acquis de Schengen et Dublin pendant la p\u00e9riode 2020 \u00e0 2025, le DFJP table sur des co\u00fbts globaux de 121,7\u00a0millions de francs. Le DFJP fournira des prestations propres importantes sous forme de ressources en personnel et participera aux co\u00fbts sous forme de biens et services propres. Dans son message, le Conseil f\u00e9d\u00e9ral propose donc un cr\u00e9dit d&#8217;engagement de 98,7\u00a0millions de francs, \u00e0 lib\u00e9rer en deux tranches.<\/p>\n<p>Un programme central sera \u00e9tabli au Secr\u00e9tariat g\u00e9n\u00e9ral du DFJP pour le pilotage et la conduite des projets. C\u00f4t\u00e9 UE, l&#8217;Agence eu-LISA, l&#8217;agence europ\u00e9enne pour la gestion op\u00e9rationnelle des syst\u00e8mes d&#8217;information \u00e0 grande \u00e9chelle, est charg\u00e9e de d\u00e9velopper les composants essentiels des syst\u00e8mes d&#8217;information. Les droits de participation dont b\u00e9n\u00e9ficie la Suisse dans le cadre de ce programme sont plus \u00e9tendus que pr\u00e9vu dans l&#8217;accord d&#8217;association \u00e0 Schengen, puisqu&#8217;elle peut aussi, dans certains cas, prendre part aux d\u00e9cisions. Le Conseil f\u00e9d\u00e9ral a adopt\u00e9 en f\u00e9vrier\u00a02019 le message relatif \u00e0 la participation de la Suisse \u00e0 eu-LISA.<\/p>\n<h3><strong>Coop\u00e9ration tr\u00e8s fructueuse<\/strong><\/h3>\n<p>La Suisse retire d&#8217;importants avantages de la coop\u00e9ration instaur\u00e9e par Schengen et Dublin. Ces avantages vont au-del\u00e0 du seul aspect de la s\u00e9curit\u00e9 int\u00e9rieure. Comme le montre un rapport de 2018 du Conseil f\u00e9d\u00e9ral fond\u00e9 sur une \u00e9tude externe (&#8220;Les cons\u00e9quences \u00e9conomiques et financi\u00e8res de l&#8217;association de la Suisse \u00e0 Schengen&#8221;), la coop\u00e9ration au titre de Schengen et Dublin permet \u00e0 la Suisse d&#8217;\u00e9conomiser annuellement quelque 270\u00a0millions de francs dans le domaine de l&#8217;asile notamment.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le contr\u00f4le des fronti\u00e8res ext\u00e9rieures en Europe sera renforc\u00e9 et la coop\u00e9ration des autorit\u00e9s nationales comp\u00e9tentes en mati\u00e8re de s\u00e9curit\u00e9 et de migrations, resserr\u00e9e. Les projets pr\u00e9vus b\u00e9n\u00e9ficieront aussi \u00e0 la Suisse, qui profitera d\u2019une s\u00e9curit\u00e9 accrue. Les travaux de mise en \u0153uvre ont d\u2019ores et d\u00e9j\u00e0 d\u00e9but\u00e9. Lors de sa s\u00e9ance du 4 septembre 2019, le Conseil f\u00e9d\u00e9ral a transmis au Parlement le message relatif au cr\u00e9dit d\u2019engagement n\u00e9cessaire.<\/p>\n","protected":false},"author":4,"featured_media":283953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-307164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/307164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=307164"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/307164\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/283953"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=307164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=307164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=307164"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=307164"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=307164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}