{"id":234333,"date":"2018-12-04T16:30:03","date_gmt":"2018-12-04T15:30:03","guid":{"rendered":"https:\/\/www.albinfo.ch\/eja-ne-berne-me-miqte-tuaj-zvicerane-prezantoja-shqiperine\/"},"modified":"2018-12-13T22:32:02","modified_gmt":"2018-12-13T21:32:02","slug":"soiree-de-promotion-du-tourisme-albanais-a-berne","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/soiree-de-promotion-du-tourisme-albanais-a-berne\/","title":{"rendered":"Soir\u00e9e de Promotion du tourisme albanais \u00e0 Berne"},"content":{"rendered":"<p>L\u2019ambassade d\u2019Albanie \u00e0 Berne et la plateforme Albinfo.ch, en\u00a0collaboration avec Balkans.ch &#8211; Destination touristique, ont le\u00a0plaisir de vous inviter \u00e0 une rencontre consacr\u00e9e au th\u00e8me du\u00a0tourisme albanais. Dans le cadre de cette r\u00e9union sera promu le\u00a0num\u00e9ro sp\u00e9cial du magazine Albinfo.ch \u00abL\u2019Albanie au-del\u00e0 de la\u00a0mer\u00bb, consacr\u00e9 au tourisme durable de l\u2019aire albanaise.<\/p>\n<p>Cet \u00e9v\u00e8nement aura lieu le vendredi<br \/>\n14 d\u00e9cembre 2018 \u00e0 18 h 30, \u00e0<br \/>\n<a href=\"https:\/\/www.google.ch\/maps\/place\/Musikschule+Muri-G%C3%BCmligen\/@46.9287028,7.4797916,17z\/data=!3m1!4b1!4m5!3m4!1s0x478e379fa6727655:0x381175c5e3f051eb!8m2!3d46.9287028!4d7.4819803?hl=de\">Villa Mettlen<\/a>,<br \/>\n<a href=\"https:\/\/www.google.ch\/maps\/place\/Pourtal\u00e8sstrasse+35,+3074+Muri+bei+Bern\/@46.9285365,7.4799327,17z\/data=!3m1!4b1!4m5!3m4!1s0x478e379fa73be4a9:0x91859f0cc316daf2!8m2!3d46.9285329!4d7.4821214?hl=de\">Pourtal\u00e8sstrasse 35,<\/a><br \/>\n3074 Muri bei Bern.<\/p>\n<p>Intervenants de la soir\u00e9e:<br \/>\nIlir Gjoni, Ambassadeur de l\u2019Albanie \u00e0 Berne<br \/>\nLars Haefner, Pr\u00e9sident de l\u2018association Albanie-Suisse<br \/>\nAleksandra Hiltmann, Journaliste<br \/>\nBashkim Iseni, Directeur de la plate-forme Albinfo.ch<\/p>\n<p>Pr\u00e9sentation du plus grand groupe d&#8217;investissements dans le domaine du tourisme en Albanie, &#8220;Balfin Group&#8221; par ses repr\u00e9sentants MM. Ermal Demaj et Miri Troka.<\/p>\n<p>Aina Hoti, Cheffe du projet Balkans.ch<br \/>\nA cette occasion, sera servi un ap\u00e9ritif dinatoire avec des<br \/>\nsp\u00e9cialit\u00e9s culinaires traditionnelles, accompagn\u00e9 de partitions<br \/>\nmusicales des artistes Morgane Gallay et Gjon Guralumi.<br \/>\nVotre participation nous honore!<\/p>\n<p>Merci de confirmer votre pr\u00e9sence \u00e0 l\u2018adresse:<br \/>\naina.hoti@albinfo.ch<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/events\/736916186673338\/\">https:\/\/www.facebook.com\/events\/736916186673338\/<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ambassade d\u2019Albanie \u00e0 Berne et la plateforme Albinfo.ch, en\u00a0collaboration avec Balkans.ch &#8211; Destination touristique, ont le\u00a0plaisir de vous inviter \u00e0 une rencontre consacr\u00e9e au th\u00e8me du\u00a0tourisme albanais. Dans le cadre de cette r\u00e9union sera promu le\u00a0num\u00e9ro sp\u00e9cial du magazine Albinfo.ch \u00abL\u2019Albanie au-del\u00e0 de la\u00a0mer\u00bb, consacr\u00e9 au tourisme durable de l\u2019aire albanaise. Cet \u00e9v\u00e8nement aura lieu [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":234190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1182,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-234333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/234333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=234333"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/234333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/234190"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=234333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=234333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=234333"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=234333"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=234333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}