{"id":233447,"date":"2018-12-01T23:16:28","date_gmt":"2018-12-01T22:16:28","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=233447"},"modified":"2018-12-02T22:15:32","modified_gmt":"2018-12-02T21:15:32","slug":"message-concernant-une-nouvelle-convention-de-securite-sociale-avec-le-kosovo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/message-concernant-une-nouvelle-convention-de-securite-sociale-avec-le-kosovo\/","title":{"rendered":"Message concernant une nouvelle convention de s\u00e9curit\u00e9 sociale avec le Kosovo"},"content":{"rendered":"<p>Apr\u00e8s une interruption de plusieurs ann\u00e9es, la nouvelle convention permettra de r\u00e9gler \u00e0 nouveau la coordination des assurances sociales entre la Suisse et le Kosovo.<\/p>\n<p>Par son contenu, elle correspond aux autres conventions de s\u00e9curit\u00e9 sociale conclues par la Suisse et est conforme aux standards internationaux en la mati\u00e8re. La nouvelle convention de s\u00e9curit\u00e9 sociale vise notamment \u00e0 coordonner les syst\u00e8mes de pr\u00e9voyance vieillesse, survivants et invalidit\u00e9 des \u00c9tats partenaires et concerne en particulier l\u2019AVS et l\u2019AI pour le c\u00f4t\u00e9 suisse ; son objectif est d\u2019\u00e9viter aux ressortissants de l\u2019un ou de l\u2019autre des \u00c9tats d\u2019\u00eatre d\u00e9savantag\u00e9s ou de subir des discriminations. La convention garantit par cons\u00e9quent une large \u00e9galit\u00e9 de traitement des assur\u00e9s et r\u00e9glemente le versement des rentes \u00e0 l\u2019\u00e9tranger. De plus, elle offre une base pour la lutte contre les abus.<\/p>\n<p>Le Kosovo est le seul \u00c9tat issu de l\u2019ancienne Yougoslavie avec lequel la Suisse n\u2019a pas conclu d\u2019accord dans le domaine de la s\u00e9curit\u00e9 sociale. La convention de s\u00e9curit\u00e9 sociale conclue avec l\u2019ex-Yougoslavie n\u2019est plus appliqu\u00e9e dans les relations avec le Kosovo depuis le 1er avril 2010. Par cons\u00e9quent, les ressortissants kosovars ne peuvent pas, pour le moment, percevoir de rentes AVS et AI suisses \u00e0 l\u2019\u00e9tranger. Un remboursement des cotisations AVS peut \u00eatre demand\u00e9 \u00e0 la place du versement d\u2019une rente de vieillesse ou d\u2019une rente de survivants.<\/p>\n<p>Les ressortissants kosovars qui ont atteint l\u2019\u00e2ge de la retraite et qui n\u2019ont pas demand\u00e9 le remboursement de leurs cotisations pourront demander le versement de leur rente \u00e0 l\u2019\u00e9tranger une fois que la convention de s\u00e9curit\u00e9 sociale sera entr\u00e9e en vigueur. Cependant, ils ne pourront pas se pr\u00e9valoir de droits r\u00e9troactifs pour la p\u00e9riode pr\u00e9c\u00e9dant la convention.<\/p>\n<p>Une fois les n\u00e9gociations achev\u00e9es, la convention a \u00e9t\u00e9 sign\u00e9e par les \u00c9tats parties le 8 juin 2018. Son entr\u00e9e en vigueur requiert l\u2019approbation pr\u00e9alable des parlements des \u00c9tats contractants.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La conclusion d\u2019une nouvelle convention doit permettre de r\u00e9tablir les relations juridiques en mati\u00e8re de s\u00e9curit\u00e9 sociale entre la Suisse et le Kosovo. Lors de sa s\u00e9ance du 30 novembre 2018, le Conseil f\u00e9d\u00e9ral a adopt\u00e9, \u00e0 l\u2019attention du Parlement, le message relatif \u00e0 cette convention. Celle-ci coordonne en particulier les syst\u00e8mes de pr\u00e9voyance vieillesse, survivants et invalidit\u00e9 des \u00c9tats partenaires et r\u00e9glemente le versement des rentes \u00e0 l\u2019\u00e9tranger<\/p>\n","protected":false},"author":14,"featured_media":233448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-233447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/233447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=233447"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/233447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/233448"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=233447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=233447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=233447"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=233447"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=233447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}