{"id":219630,"date":"2018-09-28T00:34:50","date_gmt":"2018-09-27T22:34:50","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=219630"},"modified":"2018-09-28T00:34:50","modified_gmt":"2018-09-27T22:34:50","slug":"lengagement-de-la-suisse-au-conseil-des-droits-de-lhomme","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/lengagement-de-la-suisse-au-conseil-des-droits-de-lhomme\/","title":{"rendered":"L\u2019engagement de la Suisse au Conseil des droits de l\u2019homme"},"content":{"rendered":"<p>La 39e session ordinaire du Conseil des droits de l\u2019homme, qui se tenait du 10 au 28 septembre \u00e0 Gen\u00e8ve, \u00e9tait la premi\u00e8re de la nouvelle Haut-Commissaire aux droits de l\u2019homme, Mme Michelle Bachelet.<\/p>\n<p>La Suisse s\u2019est activement engag\u00e9e lors de cette session. Elle a saisi diverses opportunit\u00e9s de dialogues et d\u00e9bats pour faire avancer ses int\u00e9r\u00eats et consid\u00e9rations. Quelques exemples: \u00e0 l\u2019occasion du 70\u00e8me anniversaire de la Convention sur la pr\u00e9vention du g\u00e9nocide, elle a rappel\u00e9 la responsabilit\u00e9 collective de veiller \u00e0 ce que les crimes de g\u00e9nocide soient non seulement punis mais aussi pr\u00e9venus. Lors d\u2019un \u00e9change sur les droits \u00e0 l\u2019eau potable et \u00e0 l\u2019assainissement, la Suisse a insist\u00e9 sur l\u2019acc\u00e8s \u00e0 l\u2019eau comme \u00e9tant un facteur cl\u00e9 de la r\u00e9silience des populations et de la pr\u00e9vention de leurs d\u00e9placements. Elle s\u2019est \u00e9galement inqui\u00e9t\u00e9e de l\u2019augmentation des cas de disparitions forc\u00e9es et de d\u00e9tentions arbitraires dans le cadre d\u2019un dialogue sur ce th\u00e8me. Enfin, elle a particip\u00e9 \u00e0 la discussion annuelle sur l\u2019int\u00e9gration d\u2019une perspective genre dans le travail des m\u00e9canismes du Conseil des droits de l\u2019homme charg\u00e9s de documenter et d\u2019enqu\u00eater sur les violations des droits de l\u2019homme et du droit humanitaire.<\/p>\n<p>Par ailleurs, la Suisse s\u2019est engag\u00e9e lors des n\u00e9gociations de plusieurs r\u00e9solutions sur des th\u00e8mes sp\u00e9cifiques comme la pr\u00e9vention de la mortalit\u00e9 maternelle, la s\u00e9curit\u00e9 des journalistes ou encore la protection des droits des paysans.<\/p>\n<p>La Suisse, enfin, a particip\u00e9 aux d\u00e9bats et n\u00e9gociations de r\u00e9solutions sur la situation des droits de l\u2019homme dans des pays \u00e0 l\u2019agenda du Conseil des droits de l\u2019homme, tels que le Burundi, le Myanmar, la R\u00e9publique D\u00e9mocratique du Congo la Syrie, et le Venezuela. Dans ce contexte, et en ligne avec son engagement traditionnel en faveur du respect, de la protection et de la mise en \u0153uvre des droits de l\u2019homme et du droit international humanitaire, la Suisse s\u2019est engag\u00e9e pour que les violations du droit international soient document\u00e9es par des m\u00e9canismes internationaux d\u2019enqu\u00eate. Ces m\u00e9canismes cherchent \u00e0 assurer que les responsables puissent un jour \u00eatre tenus p\u00e9nalement responsables de leurs actes.<\/p>\n<p>Il s\u2019agit pour la Suisse de la derni\u00e8re session de son troisi\u00e8me mandat au sein du Conseil des droits de l\u2019homme, un organe intergouvernemental compos\u00e9 de 47 Etats membres. Le mandat de la Suisse se termine au 31 d\u00e9cembre 2018. Elle b\u00e9n\u00e9ficiera ensuite du statut d\u2019observateur. Sans droit de vote dans cette position, la Suisse continuera toutefois \u00e0 s\u2019engager activement pour le respect, la protection et la mise en \u0153uvre des droits de l\u2019homme dans l\u2019enceinte du Conseil des droits de l\u2019homme, et au-del\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Conseil des droits de l\u2019homme cl\u00f4t ce vendredi 28 septembre \u00e0 Gen\u00e8ve sa 39\u00e8me session. Alors que les droits de l\u2019homme sont sous pression dans le monde, l\u2019engagement de la Suisse pour le respect, la protection et la mise en \u0153uvre des droits de l\u2019homme est d\u2019autant plus fondamental<\/p>\n","protected":false},"author":14,"featured_media":219631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-219630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/219630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=219630"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/219630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/219631"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=219630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=219630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=219630"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=219630"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=219630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}