{"id":217858,"date":"2018-09-18T14:36:28","date_gmt":"2018-09-18T12:36:28","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=217858"},"modified":"2018-09-19T12:36:17","modified_gmt":"2018-09-19T10:36:17","slug":"suisse-kosovo-le-dur-retour-des-retraites","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/suisse-kosovo-le-dur-retour-des-retraites\/","title":{"rendered":"Suisse-Kosovo, le dur retour des retrait\u00e9s"},"content":{"rendered":"<p>Ils ont travaill\u00e9 toute une vie en Suisse, depuis les ann\u00e9es 80 d\u00e9j\u00e0, parfois au prix de leur sant\u00e9. Ils ont accumul\u00e9 une \u00e9pargne, de l\u2019AVS, mais quand vient le temps de la retraite bien m\u00e9rit\u00e9e et du retour au Kosovo, c\u2019est le choc : leurs rentes n\u2019ont jamais \u00e9t\u00e9 vers\u00e9es. Des milliers de retrait\u00e9s kosovars ont perdu leur argent et se retrouvent d\u00e9munis.<\/p>\n<p><a href=\"https:\/\/pages.rts.ch\/emissions\/temps-present\/9759414-suissekosovo-le-dur-retour-des-retraites.html#9816603\">rts.ch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Temps Pr\u00e9sent du jeudi 20 septembre revient sur les retrait\u00e9s kosovars de Suisse, injustement p\u00e9nalis\u00e9s<\/p>\n","protected":false},"author":10,"featured_media":217842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1164,1163,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-217858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integration-fr","category-fr-e-diaspora","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/217858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=217858"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/217858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/217842"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=217858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=217858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=217858"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=217858"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=217858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}