{"id":173373,"date":"2017-12-01T13:19:23","date_gmt":"2017-12-01T12:19:23","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=173373\/"},"modified":"2017-12-01T13:24:23","modified_gmt":"2017-12-01T12:24:23","slug":"loi-federale-sur-les-etrangers-et-lintegration-des-mesures-incitatives-pour-renforcer-lintegration","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/loi-federale-sur-les-etrangers-et-lintegration-des-mesures-incitatives-pour-renforcer-lintegration\/","title":{"rendered":"Loi f\u00e9d\u00e9rale sur les \u00e9trangers et l\u2019int\u00e9gration : des mesures incitatives pour renforcer l\u2019int\u00e9gration"},"content":{"rendered":"<p>Le 16\u00a0d\u00e9cembre 2016, le Parlement a approuv\u00e9 la modification de la LEtr visant \u00e0 am\u00e9liorer l\u2019int\u00e9gration. La mise en \u0153uvre de la modification de la loi est divis\u00e9e en deux volets. Le premier volet, qui entrera en vigueur au d\u00e9but de l\u2019ann\u00e9e 2018, inclut notamment la suppression de la taxe sp\u00e9ciale sur le revenu de l\u2019activit\u00e9 lucrative pour les personnes relevant du domaine de l\u2019asile et une modification d\u2019ordre technique de la disposition relative au financement du forfait d\u2019int\u00e9gration.<\/p>\n<p>Le Conseil f\u00e9d\u00e9ral a ouvert aujourd\u2019hui la consultation sur le deuxi\u00e8me volet. Elle prendra fin le 19\u00a0mars 2018. Ce deuxi\u00e8me volet comprend des adaptations de l\u2019ordonnance relative \u00e0 l\u2019admission, au s\u00e9jour et \u00e0 l\u2019exercice d\u2019une activit\u00e9 lucrative (OASA), ainsi que la r\u00e9vision totale de l\u2019ordonnance sur l\u2019int\u00e9gration des \u00e9trangers (OIE). Ces modifications entreront en vigueur \u00e0 l\u2019\u00e9t\u00e9 2018. La LEtr sera par ailleurs rebaptis\u00e9e &#8220;loi f\u00e9d\u00e9rale sur les \u00e9trangers et l\u2019int\u00e9gration&#8221; (LEI).<\/p>\n<h3><strong>Faciliter l\u2019acc\u00e8s au march\u00e9 du travail<\/strong><\/h3>\n<p>L\u2019actuelle proc\u00e9dure d\u2019autorisation que les r\u00e9fugi\u00e9s reconnus et les personnes admises \u00e0 titre provisoire doivent suivre pour pouvoir exercer une activit\u00e9 lucrative est remplac\u00e9e par une simple proc\u00e9dure d\u2019annonce. Cette derni\u00e8re pourra \u00eatre men\u00e9e par un tiers que les autorit\u00e9s cantonales charg\u00e9es d\u2019encourager l\u2019int\u00e9gration auront mandat\u00e9 pour trouver des stages ou des postes. Cette mani\u00e8re de proc\u00e9der facilitera l\u2019acc\u00e8s au march\u00e9 du travail et soulagera les employeurs. Elle permettra \u00e9galement de mieux exploiter le potentiel des travailleurs en Suisse et de r\u00e9duire ainsi les d\u00e9penses de l\u2019aide sociale. Les organes de contr\u00f4le existants se chargeront de v\u00e9rifier si les conditions de travail sont respect\u00e9es.<\/p>\n<p>Par ailleurs, les crit\u00e8res d\u2019int\u00e9gration que les autorit\u00e9s comp\u00e9tentes en mati\u00e8re de migration doivent prendre en compte dans les d\u00e9cisions relevant du droit des \u00e9trangers sont d\u00e9sormais pr\u00e9cis\u00e9s dans une ordonnance. L\u2019octroi et la prolongation d\u2019une autorisation requerront d\u00e9sormais des connaissances linguistiques d\u00e9finies. Plus le statut vis\u00e9 accorde de droits, plus les exigences linguistiques augmentent.<\/p>\n<p>Les mesures d\u00e9cid\u00e9es par le Parlement \u00e0 l\u2019\u00e9gard des \u00e9trangers qui ne manifestent aucune volont\u00e9 de contribuer \u00e0 leur int\u00e9gration ont \u00e9galement \u00e9t\u00e9 pr\u00e9cis\u00e9es. Les autorit\u00e9s comp\u00e9tentes en mati\u00e8re de migration peuvent ainsi lier l\u2019octroi d\u2019une autorisation de s\u00e9jour \u00e0 l\u2019application d\u2019une convention d\u2019int\u00e9gration, qui mentionnera les attentes \u00e0 l\u2019\u00e9gard des personnes concern\u00e9es. Cette convention rev\u00eatira un caract\u00e8re obligatoire et pourra donner lieu \u00e0 des sanctions. En outre, l\u2019autorisation d\u2019\u00e9tablissement (permis C) pourra \u00eatre remplac\u00e9e par une autorisation de s\u00e9jour (permis B) si les crit\u00e8res d\u2019int\u00e9gration ne sont pas remplis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors de sa s\u00e9ance du 1er d\u00e9cembre 2017, le Conseil f\u00e9d\u00e9ral a ouvert la consultation relative au deuxi\u00e8me volet de modifications des ordonnances li\u00e9es \u00e0 la nouvelle loi f\u00e9d\u00e9rale sur les \u00e9trangers (LEtr). T\u00e2che commune \u00e0 la Conf\u00e9d\u00e9ration et aux cantons, l\u2019int\u00e9gration des \u00e9trangers doit \u00eatre renforc\u00e9e gr\u00e2ce \u00e0 des mesures incitatives et appropri\u00e9es. Il est ainsi pr\u00e9vu, entre autres, d\u2019encourager l\u2019acquisition de connaissances linguistiques et de faciliter l\u2019acc\u00e8s des r\u00e9fugi\u00e9s et des personnes admises \u00e0 titre provisoire au march\u00e9 du travail<\/p>\n","protected":false},"author":4,"featured_media":108947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1171,1170,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-173373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-thematique","category-vivre-en-suisse","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/173373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=173373"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/173373\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/108947"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=173373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=173373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=173373"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=173373"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=173373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}