{"id":151402,"date":"2017-06-02T12:30:41","date_gmt":"2017-06-02T10:30:41","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=151402\/"},"modified":"2017-06-06T09:15:46","modified_gmt":"2017-06-06T07:15:46","slug":"bd-jazz-et-journalisme-le-genie-humaniste-de-gani-jakupi","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/bd-jazz-et-journalisme-le-genie-humaniste-de-gani-jakupi\/","title":{"rendered":"BD, Jazz et Journalisme: le g\u00e9nie humaniste de Gani Jakupi"},"content":{"rendered":"<div class=\"galery-slider\"><ul class=\"slides\"><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Havana 2014\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g4.png\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g4-586x389.png\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Havana 2014<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Barcelona\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g1.png\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g1-586x389.png\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Barcelona<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Caen 2013\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g2.png\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g2-586x389.png\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Caen 2013<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Jamboree 2016\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g3.png\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g3-586x389.png\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Jamboree 2016<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Connections\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g5.png\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g5-586x389.png\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Connections<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Prishitn\u00eb 2010\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g6.png\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/g6-586x389.png\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Prishitn\u00eb 2010<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><\/ul><div class=\"slidesounter\"><span class=\"slide-current-slide\"><\/span><span class=\"slide-total-slides\"><\/span><\/div><\/div><link href=\"https:\/\/www.albinfo.at\/wp-content\/themes\/albinfo\/assets\/css\/litebox.css\" rel=\"stylesheet\" type=\"text\/css\" media=\"all\" \/><script src=\"https:\/\/www.albinfo.at\/wp-content\/themes\/albinfo\/assets\/js\/images-loaded.min.js\" type=\"text\/javascript\"><\/script><script src=\"https:\/\/www.albinfo.at\/wp-content\/themes\/albinfo\/assets\/js\/litebox.min.js\" type=\"text\/javascript\"><\/script>\n        <script type=\"text\/javascript\">\n            jQuery(window).load(function() {\n              jQuery(\".flexslider7\").flexslider({\n                animation: \"slide\",\n                controlNav: false,\n                animationLoop: false,\n                slideshow: false,\n              });\n            });\n\t\t\tjQuery(\".litebox\").liteBox();\n        <\/script>\n<p><strong>Albinfo.ch: \u00a0Pourriez-vous nous parler de vos origines?<\/strong><\/p>\n<p><strong>Gani Jakupi:<\/strong> Je suis n\u00e9 dans les montagnes du Nord du Kosovo. J&#8217;ai grandi et fait mes \u00e9tudes au Kosovo. Je suis ing\u00e9nieur en \u00e9lectronique et t\u00e9l\u00e9communications\u00a0; malheureusement, je ne suis jamais parvenu \u00e0 mettre en pratique mes connaissance, car mon dipl\u00f4me n&#8217;\u00e9tait pas reconnu en France, et moi je n&#8217;avais pas les moyens pour reprendre les \u00e9tudes. Je ne me rappelle plus de l&#8217;ann\u00e9e exacte o\u00f9 je suis parti \u00e0 l&#8217;\u00e9tranger pour la premi\u00e8re fois, mais en tout cas, en 1978 je sillonnais d\u00e9j\u00e0 l&#8217;Europe occidentale avec un sac \u00e0 dos.<\/p>\n<p><strong>Albinfo.ch: \u00a0Selon Wikip\u00e9dia, vous avez publi\u00e9 votre premi\u00e8re BD \u00e0 13 ans. Comment avez-vous commenc\u00e9?<\/strong><\/p>\n<p><strong>Gani Jakupi:<\/strong> Au d\u00e9part, je publiais des po\u00e9sies. J&#8217;ai toujours dessin\u00e9, et je me rappelle qu&#8217;\u00e0 huit ans, pendant une maladie, comme on me laissait rien faire, j&#8217;ai pris du papier et j&#8217;ai fait une page de BD. Effectivement, \u00e0 treize ans, j&#8217;ai r\u00e9alis\u00e9 une petite histoire de trois pages, publi\u00e9e par un magazine d&#8217;enfants. J&#8217;ai encha\u00een\u00e9 la collaboration avec la presse r\u00e9gionale,\u00a0ensuite celle des autres r\u00e9publique de l\u2019ex-Yougoslavie.<\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/retour.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-151421\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/retour.png\" alt=\"\" width=\"525\" height=\"470\" srcset=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/retour.png 689w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/retour-300x269.png 300w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/retour-442x396.png 442w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/a><\/p>\n<p><strong>Albinfo.ch: \u00a0Ensuite, vous \u00eates parti \u00e0 l&#8217;\u00e9tranger?<\/strong><\/p>\n<p><strong>Gani Jakupi:<\/strong> J&#8217;\u00e9tais bien na\u00eff: je me suis rendu \u00e0 Paris avec six dessins sous le bras! Et au lieu d&#8217;aborder des petites journaux, je suis all\u00e9 directement \u00e0 &#8220;Jour de France&#8221;, &#8220;Figaro&#8221;, France Soir&#8221;, et je ne me rappelle plus o\u00f9 encore! Ils devaient trouver \u00e7a amusant, sympathique m\u00eame, car on me donna des conseils et on me redirigea vers des publications plus modestes. Durant quelques ann\u00e9es, j&#8217;ai fait du dessin de presse, avant de m&#8217;introduire graduellement dans le monde de la BD. J&#8217;ai d\u00e9but\u00e9 dans des fanzines, en collaborant avec un sc\u00e9nariste. \u00c7a m&#8217;a surtout permis d&#8217;apprendre les ficelles du m\u00e9tier, et de proposer un projet de s\u00e9rie avec Hugues Labiano au dessin.<\/p>\n<p><strong>Albinfo.ch: Quels ont \u00e9t\u00e9 vos premiers succ\u00e8s en France?<\/strong><\/p>\n<p>Gani Jakupi\u00a0: La trilogie &#8220;Matador&#8221; (1991-1994), avec Hugues Labiano, eut un retentissement certain. H\u00e9las, par la suite, j&#8217;ai gaspill\u00e9 ma chance, avec des collaborations malencontreuses, en me trouvant au bon endroit mais au mauvais moment (notamment lors de l&#8217;achat de la maison d&#8217;\u00e9dition Dargaud par un group qu&#8217;on consid\u00e9rait religieux et qui provoqua la d\u00e9bandade des grands auteurs). Parall\u00e8lement, je commen\u00e7ais \u00e0 ressentir un d\u00e9senchantement avec les th\u00e8mes que traitait la BD de l&#8217;\u00e9poque.<\/p>\n<p><strong>Albinfo.ch: Vous avez abandonn\u00e9 la France pour vous installer en Espagne. Que vous attira-t-il \u00e0 Barcelone?<\/strong><\/p>\n<p><strong>Gani Jakupi\u00a0:<\/strong> J&#8217;abandonnai Paris pour des raisons sentimentales: la s\u00e9paration de ma premi\u00e8re compagne. La raison inverse m&#8217;amena \u00e0 Barcelone. Ma vie personnelle s&#8217;en voyait enrichie, mais je ratais le train des grands changements qui survinrent dans la BD fran\u00e7aise des ann\u00e9es &#8217;90! Bien que, \u00e0 quelque chose malheur est toujours bon\u00a0: je m&#8217;engageai dans le journalisme, le th\u00e9\u00e2tre, le design, la photographie, la traduction, etc. Disons que je me constituais un bagage qui allait m&#8217;\u00eatre tr\u00e8s utile plus tard.<\/p>\n<p><strong>Albinfo.ch: \u00a0\u00c7a fait plus de 20 ans que vous vivez en Espagne. Vous \u00eates vite retomb\u00e9 sur vos pieds ou avez-vous exp\u00e9riment\u00e9 des difficult\u00e9s?<\/strong><\/p>\n<p><strong>Gani Jakupi\u00a0:<\/strong> Au d\u00e9part, il y avait surtout des d\u00e9boires. J&#8217;ai m\u00eame abandonn\u00e9 des projets de BD d\u00e9j\u00e0 sign\u00e9s, en apprenant les tirages qu&#8217;on pr\u00e9conisait. J&#8217;acceptais d&#8217;\u00eatre mal pay\u00e9, mais pas d&#8217;\u00eatre mal distribu\u00e9. Finalement, en 2005, en association avec le critique du jazz du principal quotidien espagnol, &#8220;El Pa\u00eds&#8221;, j\u2019ai mont\u00e9 une collection de livres sur des grands noms de la musique. Ils comprenaient une BD, des chroniques musicales et deux CD&#8217;s avec des morceaux soigneusement s\u00e9lectionn\u00e9s. La presse, les radios et les t\u00e9l\u00e9s s&#8217;int\u00e9ress\u00e8rent aux titres que j\u2019y r\u00e9alisais moi-m\u00eame, malheureusement, la logistique de l&#8217;\u00e9diteur s&#8217;av\u00e9ra bancale. Les livres \u00e9taient introuvables au moment o\u00f9 l\u2019on jouissait de la meilleure visibilit\u00e9 m\u00e9diatique! Mais, j&#8217;eu la chance que mon travail soit remarqu\u00e9 par un \u00e9diteur de Dupuis, qui me sugg\u00e9ra de retourner sur le march\u00e9 fran\u00e7ais. \u00c0 traiter les th\u00e8mes que je souhaitais. Aujourd&#8217;hui, je lui en sais gr\u00e9!<\/p>\n<p><strong>Albinfo.ch: En 1999, vous vous \u00eates rendu au Kosovo en tant que journaliste. Vous en t\u00e9moignez dans vos romans graphiques &#8220;La derni\u00e8re image&#8221; et &#8220;Retour au Kosovo&#8221;. Comment avez-vous v\u00e9cu cette exp\u00e9rience?<\/strong><\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/laderniere-image.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-151412\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/laderniere-image.png\" alt=\"\" width=\"544\" height=\"761\" srcset=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/laderniere-image.png 630w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/laderniere-image-215x300.png 215w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/laderniere-image-283x396.png 283w\" sizes=\"auto, (max-width: 544px) 100vw, 544px\" \/><\/a><\/p>\n<p><strong>Gani Jakupi\u00a0:<\/strong> Vous pouvez vous imaginez \u00e0 quel point est douloureux de travailler sur un sujet qui comprend l&#8217;assassinat des membres de votre famille. N\u00e9anmoins, j&#8217;ai toujours fait tr\u00e8s attention de ne pas perdre de vue la d\u00e9ontologie du journalisme. J&#8217;ai \u00e9t\u00e9 ravi lors de l&#8217;entretien accord\u00e9 \u00e0 Fr\u00e9d\u00e9ric Potet de &#8220;Le Monde&#8221;, qui a commenc\u00e9 en me f\u00e9licitant pour l&#8217;objectivit\u00e9 de mes \u00e9crits! Il para\u00eet qu&#8217;on trouve &#8220;La derni\u00e8re image&#8221; dans toutes les biblioth\u00e8ques publiques en France, et ce roman graphique m&#8217;a valu des invitations \u00e0 des festivals de BD, de litt\u00e9rature et du cin\u00e9ma. Pour &#8220;Retour au Kosovo&#8221;, j&#8217;ai eut la chance de collaborer avec l\u2019un des plus grand graphistes argentins. Ce roman graphique a \u00e9t\u00e9 traduit en espagnol, italien et russe. Dans la pr\u00e9face, l&#8217;\u00e9diteur russe a exprim\u00e9 son d\u00e9saccord avec ma vision de l&#8217;intervention internationale au Kosovo, mais il a d\u00e9cid\u00e9 de publier l&#8217;\u0153uvre \u00e0 cause de la &#8220;profonde humanit\u00e9&#8221; qu&#8217;elle exprime.<\/p>\n<p><strong>Albinfo.ch: Comment en \u00eates-vous arriv\u00e9 au jazz? Avez-vous fait des \u00e9tudes musicales?<\/strong><\/p>\n<p><strong>Gani Jakupi\u00a0:<\/strong> Aucune! Je suis autodidacte, et j&#8217;en serai rest\u00e9 au niveau d&#8217;amateur, sans un heureux concours de circonstances. \u00c9tant bien int\u00e9gr\u00e9 dans le milieu du jazz \u00e0 Barcelone, je voulais faire enregistrer quelques unes de mes compositions par des amis. Heureusement pour moi, le plus grand <em>Latin jazz<\/em> pianiste de l&#8217;\u00e9poque, l&#8217;uruguayen Jos\u00e9 Reinoso les a \u00e9cout\u00e9, les a aim\u00e9, a d\u00e9cid\u00e9 de les jouer et m&#8217;a mis en contact avec de grands interpr\u00e8tes. Il \u00e9taient d&#8217;origine extr\u00eamement diversifi\u00e9es: Br\u00e9sil, Argentine, Venezuela, Moldavie, Suisse, etc. De mon c\u00f4t\u00e9, j&#8217;ai invit\u00e9 des musiciens kosovars que j&#8217;admire. Le r\u00e9sultat, l&#8217;album <em>Aldea<\/em> (2012) a d\u00e9pass\u00e9 mes expectatives. Il a attir\u00e9 l&#8217;attention de France Culture, de \u00ab\u00a0Jazz Magazine\u00a0\u00bb, des radios espagnoles, on me l&#8217;a r\u00e9clam\u00e9 depuis la radio de Montr\u00e9al (au Canada). Plus tard, on a jou\u00e9 ma musique aussi dans des radios de Buenos Aires, Miami&#8230;<\/p>\n<p>Cela m&#8217;a inspir\u00e9 pour monter un noyau dur constitu\u00e9 de : Marcelo Mercadante, le meilleur bandon\u00e9oniste en Espagne; Manuel Mart\u00ednez del Fresno, violoncelliste du Liceu (Op\u00e9ra de Barcelone) qui avait jou\u00e9 avec Jimmi Page et Robert Plant (Led Zeppelin), remplac\u00e9, vers la fin du projet, par la tr\u00e8s talentueuse C\u00e8lia Torres; Jordi Gaspar, le contrebassiste des vedettes espagnoles (Joan Manuel Serrat, Ferr\u00e0n Savall &#8211;\u00a0 fils de Jordi Savall-) ou am\u00e9ricaine (John Zorn, John Abercrombey); le meilleur batteur kosovar Nesim Maxhuni; et moi-m\u00eame \u00e0 la guitare. La formation s&#8217;est vue renforc\u00e9e par Raynald Col\u00f3m, quatre ann\u00e9es cons\u00e9cutives meilleurs trompettiste jazz d&#8217;Espagne, publi\u00e9 en France et en Grande Bretagne par <em>Harmonia Mundi<\/em>. Pour le deuxi\u00e8me album, <em>Kismet<\/em> (2014), j\u2019ai invit\u00e9 des interpr\u00e8tes de Gr\u00e8ce, Iran, Turquie, Inde et Kosovo.<\/p>\n<p>\u00c0 cause d&#8217;un projet de roman graphique volumineux et extr\u00eamement exigeant, actuellement en cours, je n&#8217;ai pas pu accepter faire de la sc\u00e8ne que tr\u00e8s peu de fois, mais nous pr\u00e9voyons de donner plus de concerts d\u00e8s l&#8217;ann\u00e9es prochaine.<\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-151346\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok-1024x729.jpg\" alt=\"\" width=\"640\" height=\"456\" srcset=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok-1024x729.jpg 1024w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok-300x214.jpg 300w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok-768x547.jpg 768w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok-556x396.jpg 556w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2017\/06\/gani-jakupi-gjeneve-ok.jpg 1890w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec pour tout bagage un sac \u00e0 dos et un portfolio de 6 dessins, il y a 40 ans, il alla frapper \u00e0 la porte des plus grands magazines de Paris. &#8220;J&#8217;\u00e9tais assez na\u00eff!&#8221;, reconna\u00eet-il aujourd&#8217;hui, en rem\u00e9morant ses d\u00e9buts. Mais en d\u00e9pit de cette na\u00efvet\u00e9 initiale, gr\u00e2ce \u00e0 un travail acharn\u00e9, il s&#8217;est forg\u00e9 un nom dans le monde de la BD, du jazz et du journalisme. Il s&#8217;agit de Gani Jakupi, un fils de paysans du Kosovo qui aujourd&#8217;hui vit \u00e0 Barcelone. Albinfo.ch vient de r\u00e9aliser un entretien avec lui. <\/p>\n","protected":false},"author":10,"featured_media":151397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1164,1163,1168,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-151402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-integration-fr","category-fr-e-diaspora","category-culture","category-newsletter-fr","category-newsletter-media-fr","wiwcategory-kulture","wiwcategory-art","wiwcategory-literature","wiwcategory-pikture"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/151402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=151402"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/151402\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/151397"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=151402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=151402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=151402"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=151402"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=151402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}