{"id":133077,"date":"2016-11-30T10:14:30","date_gmt":"2016-11-30T09:14:30","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=133077"},"modified":"2016-11-30T17:46:59","modified_gmt":"2016-11-30T16:46:59","slug":"les-fromagers-suisses-formeront-la-releve-kosovare","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/les-fromagers-suisses-formeront-la-releve-kosovare\/","title":{"rendered":"Les fromagers suisses formeront la rel\u00e8ve kosovare"},"content":{"rendered":"<p>Dans le cadre de cette rencontre, la d\u00e9l\u00e9gation kosovare \u00e9tait men\u00e9e par Kurtan Kajtazi, Vice-Ministre, Ramadan Avdiu, Ambassadeur Consul-G\u00e9n\u00e9ral et Arsim J.Memaj, haut fonctionnaire du minist\u00e8re de l\u2019agriculture du Kosovo et Flamur Krasniqi. Quant aux h\u00f4tes suisses, outre l\u2019initiateur de cette rencontre, Stefan Sarkany, ont \u00e9galement particip\u00e9 \u00e0 cette rencontre Ren\u00e9 Kolly, de la fromagerie Kolly, Magistrat et ancien Pr\u00e9sident des fromagers suisses, Jacques Gygax, Directeur de Fromart et Jean Pierre Wicht, membre de la Chambre de commerce et du parlement de l\u2019USAM.<\/p>\n<p>Cette r\u00e9union qui a \u00e9t\u00e9 marqu\u00e9e par des \u00e9changes fructueux entre fromagers et responsables suisses et kosovars, car dans ce cadre, il a \u00e9t\u00e9 d\u00e9cid\u00e9 qu\u2019une d\u00e9l\u00e9gation suisse, compos\u00e9e de quatre \u00e0 six personnes, aille, du 22 au 24 janvier 2017, au Kosovo.<\/p>\n<p>Les buts de cette visite seront doubles : d\u2019une part d\u2019explorer la possibilit\u00e9 de mettre en place une collaboration technique et une formation professionnelle fromag\u00e8re au Kosovo. Il s\u2019agira d\u2019autre part d\u2019organiser le commerce de Gruy\u00e8re et autres fromages suisses vers ce pays, et de fromages de brebis du Kosovo vers la Suisse. Cet \u00e9change commercial pourra \u00e9ventuellement s\u2019effectuer par compensation.<\/p>\n<p>A cette issue positive ont pr\u00e9c\u00e9d\u00e9e des \u00e9changes d\u2019informations et un \u00e9tat des lieux des besoins et potentiels effectu\u00e9s des deux parties dans la domaine de la production laiti\u00e8re et fromag\u00e8re en Suisse et au Kosovo.<\/p>\n<p>Cette initiative originale est \u00e0 saluer, compte tenu du potentiel exportateur du Kosovo dans le domaine de la production laiti\u00e8re, notamment vis-\u00e0-vis du march\u00e9 de sa nombreuse diaspora qui consomme r\u00e9guli\u00e8rement de fromage de brebis, mais qui, \u00e0 d\u00e9faut d\u2019une production kosovare, ach\u00e8te des fromages import\u00e9s en Suisse depuis d\u2019autres pays de la r\u00e9gion ou de la Turquie. Le Kosovo a besoin de conseils et de l\u2019aide dans ce domaine pour renforcer ses capacit\u00e9s. Ce pays r\u00e9unit les conditions pour accro\u00eetre et moderniser la production laiti\u00e8re, mais n\u2019arrive m\u00eame pas \u00e0 subvenir \u00e0 ses propres besoins, en important le lait de l\u2019\u00e9tranger.<\/p>\n<p>Le soutien des fromagers suisses, par le biais des associations fa\u00eeti\u00e8res suisses, sera pr\u00e9cieux pour le Kosovo, notamment dans le domaine de la transmission du savoir-faire suisse mondialement connu, mais aussi dans la formation des futurs fromagers kosovars. En fait, la formation de qualit\u00e9 des fromagers kosovars s\u2019av\u00e8re \u00eatre comme une condition <em>sine qua non<\/em> pour favoriser cet important secteur de son \u00e9conomie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s un investissement personnel sans m\u00e9nagement, le 28 octobre dernier, Stefan Sarkany, Pr\u00e9sident de la Chambre de commerce Suisse-Kosovo, a r\u00e9ussi \u00e0 concr\u00e9tiser une rencontre strat\u00e9gique entre fromagers suisses, un membre du parlement de l\u2019Union suisse des Arts et m\u00e9tiers (USAM) ainsi que des repr\u00e9sentants politiques du minist\u00e8re kosovars de l\u2019agriculture et des diplomates de ce pays en Suisse.<\/p>\n","protected":false},"author":10,"featured_media":133115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1161,1159,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-133077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investissement","category-ch-balkans","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/133077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=133077"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/133077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media\/133115"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=133077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=133077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=133077"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=133077"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=133077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}