{"id":127756,"date":"2016-10-12T09:27:29","date_gmt":"2016-10-12T07:27:29","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=127756"},"modified":"2016-10-12T09:27:29","modified_gmt":"2016-10-12T07:27:29","slug":"le-kosovo-a-besoin-du-soutien-de-la-giz","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-kosovo-a-besoin-du-soutien-de-la-giz\/","title":{"rendered":"Le Kosovo a besoin du soutien de la GIZ"},"content":{"rendered":"<p>Le Ministre des Affaires \u00e9trang\u00e8res du Kosovo, Enver Hoxhaj, a remerci\u00e9 les repr\u00e9sentants de la <em>Deutsche Gesellschaft f\u00fcr Internationale Zusammenarbeit<\/em> (GIZ) pour le soutien apport\u00e9 au d\u00e9veloppement du Kosovo depuis 1999 dans divers secteurs.<\/p>\n<p>\u00ab\u00a0La R\u00e9publique du Kosovo a besoin davantage d\u2019aide de la GIZ, \u00e0 travers des projets concrets, afin de r\u00e9aliser les priorit\u00e9s de politique \u00e9trang\u00e8re que le Kosovo doit remplir tout au long de la route du processus d\u2019int\u00e9gration europ\u00e9enne\u00a0\u00bb.<\/p>\n<p>Ce sont les d\u00e9clarations du ministre des Affaires \u00e9trang\u00e8res de la R\u00e9publique du Kosovo, Enver Hoxhaj, au cours d\u2019une r\u00e9union tenue avec le chef de l\u2019\u00c9quipe europ\u00e9enne de la GIZ de soutien au processus d\u2019int\u00e9gration du Kosovo et la repr\u00e9sentante de l\u2019ambassade d\u2019Allemagne \u00e0 Prishtina, Henriette Kotter.<\/p>\n<p>Hoxhaj a remerci\u00e9 les repr\u00e9sentants de la GIZ, rappelant leur soutien continu au d\u00e9veloppement du Kosovo depuis 1999, dans divers secteurs tels que l\u2019\u00e9ducation, l\u2019\u00e9conomie, la sant\u00e9 et l\u2019agriculture. Selon lui, gr\u00e2ce \u00e0 cette coop\u00e9ration, le Kosovo pourrait \u00e9galement progresser dans sa politique \u00e9trang\u00e8re et au niveau du processus d\u2019int\u00e9gration.<\/p>\n<p>Il a ajout\u00e9 que le minist\u00e8re travaillera en coordination avec ses partenaires afin de b\u00e9n\u00e9ficier des expertises qui peuvent aider le d\u00e9veloppement du Kosovo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ministre des Affaires \u00e9trang\u00e8res du Kosovo, Enver Hoxhaj, a remerci\u00e9 les repr\u00e9sentants de la Deutsche Gesellschaft f\u00fcr Internationale Zusammenarbeit (GIZ) pour le soutien apport\u00e9 au d\u00e9veloppement du Kosovo depuis 1999 dans divers secteurs. \u00ab\u00a0La R\u00e9publique du Kosovo a besoin davantage d\u2019aide de la GIZ, \u00e0 travers des projets concrets, afin de r\u00e9aliser les priorit\u00e9s [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-127756","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/127756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=127756"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/127756\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=127756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=127756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=127756"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=127756"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=127756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}