{"id":127256,"date":"2016-10-05T14:20:03","date_gmt":"2016-10-05T12:20:03","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/edhe-bdi-e-perfshire-ne-vjedhjen-e-votave\/"},"modified":"2016-10-07T10:06:51","modified_gmt":"2016-10-07T08:06:51","slug":"edhe-bdi-e-perfshire-ne-vjedhjen-e-votave","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/edhe-bdi-e-perfshire-ne-vjedhjen-e-votave\/","title":{"rendered":"Le BDI impliqu\u00e9 dans le trucage du scrutin"},"content":{"rendered":"<p>Parmi les \u00ab\u00a0bombes\u00a0\u00bb pr\u00e9sent\u00e9es au procureur sp\u00e9cial public (PSP) par l\u2019Union sociale-d\u00e9mocrate de Mac\u00e9doine (SDSM), il y a quelques enregistrements qui d\u00e9montreraient que le BDI est impliqu\u00e9 dans une fraude \u00e9lectorale.<\/p>\n<p>Le Procureur sp\u00e9cial de la Mac\u00e9doine poss\u00e8de des enregistrements de discussions de certains dirigeants du BDI, le parti d\u2019Ali Ahmeti qui \u00e9tait au gouvernement, qui d\u00e9voilent leur participation \u00e0 une fraude lors des \u00e9lections pr\u00e9c\u00e9dentes. Dans cet enregistrement, deux membres sup\u00e9rieurs du parti d\u00e9clareraient avoir rempli les urnes dans les bureaux de vote, d\u2019apr\u00e8s ce que rapporte le journal <em>Lajm<\/em>.<\/p>\n<p>Dans un autre enregistrement, deux membres du parti discutent du fait qu\u2019un troisi\u00e8me membre aurait \u00e9t\u00e9 surpris et enregistr\u00e9 alors qu\u2019il \u00e9tait en train de remplir les urnes. Les deux membres discutent alors de la fa\u00e7on dont ils pourraient aider cette troisi\u00e8me personne \u00e0 \u00e9chapper aux sanctions. Cet enregistrement a \u00e9t\u00e9 pris avec un t\u00e9l\u00e9phone mobile et nos sources disent qu\u2019une partie de celui-ci a \u00e9t\u00e9 divulgu\u00e9 au public.<\/p>\n<p>Des sources proches du journal pensent que ces \u00e9v\u00e8nements sont les raisons qui ont pouss\u00e9 ce parti albanais \u00e0 ne pas soutenir la modification de la loi pour la protection des t\u00e9moins qu\u2019a demand\u00e9e le procureur sp\u00e9cial de la Mac\u00e9doine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parmi les \u00ab\u00a0bombes\u00a0\u00bb pr\u00e9sent\u00e9es au procureur sp\u00e9cial public (PSP) par l\u2019Union sociale-d\u00e9mocrate de Mac\u00e9doine (SDSM), il y a quelques enregistrements qui d\u00e9montreraient que le BDI est impliqu\u00e9 dans une fraude \u00e9lectorale. Le Procureur sp\u00e9cial de la Mac\u00e9doine poss\u00e8de des enregistrements de discussions de certains dirigeants du BDI, le parti d\u2019Ali Ahmeti qui \u00e9tait au gouvernement, [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-127256","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/127256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=127256"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/127256\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=127256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=127256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=127256"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=127256"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=127256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}