{"id":126486,"date":"2016-09-28T11:34:13","date_gmt":"2016-09-28T09:34:13","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/kosova-ne-lufte-me-papunesine\/"},"modified":"2016-10-03T12:45:48","modified_gmt":"2016-10-03T10:45:48","slug":"kosova-ne-lufte-me-papunesine","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/kosova-ne-lufte-me-papunesine\/","title":{"rendered":"Le Kosovo lutte contre le ch\u00f4mage"},"content":{"rendered":"<p>Les experts \u00e9conomiques pensent que ce pourcentage de ch\u00f4mage \u00e9lev\u00e9 ne devrait pas fl\u00e9chir avant 2018.<\/p>\n<p>Dans son dernier rapport, la Banque mondiale a pr\u00e9dit que la croissance \u00e9conomique au Kosovo pour 2016 sera de 3,6\u00a0%, ce qui repr\u00e9sente un niveau inf\u00e9rieur par rapport \u00e0 l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Mais le m\u00eame rapport pr\u00e9voit une augmentation de 3,7\u00a0% en 2018.<\/p>\n<p>Muhamet Sadiku, professeur d\u2019\u00e9conomie \u00e0 l\u2019universit\u00e9, a soulign\u00e9 que la croissance \u00e9conomique de 3,6\u00a0% est nominale, mais que s\u2019il y a une r\u00e9duction de l\u2019inflation dans la zone euro, le Kosovo aura une croissance encore plus faible, en dessous de 3\u00a0%.<\/p>\n<p>\u00ab\u00a0Cette croissance, \u00e9tant donn\u00e9 le faible niveau de d\u00e9veloppement \u00e9conomique du Kosovo, o\u00f9 le produit int\u00e9rieur brut par habitant est d\u2019environ 2\u00a0700\u00a0euros, est nettement insuffisante pour r\u00e9soudre les probl\u00e8mes auxquels le Kosovo fait face, probl\u00e8mes essentiellement sociaux\u00a0\u00bb, a d\u00e9clar\u00e9 Muhamet Sadiku.<\/p>\n<p>Pour am\u00e9liorer cette situation de ch\u00f4mage grave au Kosovo, le professeur Sadiku ajoute que le pays doit r\u00e9aliser une croissance \u00e9conomique sup\u00e9rieure \u00e0 6\u00a0%, et qu\u2019il faut \u00e9tablir une politique \u00e9conomique avec une orientation claire visant \u00e0 la transformation de la croissance \u00e9conomique en un v\u00e9ritable d\u00e9veloppement \u00e9conomique.<\/p>\n<p>\u00ab\u00a0Le taux de ch\u00f4mage au Kosovo s\u2019att\u00e9nue gr\u00e2ce au d\u00e9veloppement du secteur priv\u00e9, des secteurs productifs et de l\u2019environnement des affaires, ainsi que l\u2019encouragement des investisseurs \u00e9trangers. Ce que nous attendons est que les soci\u00e9t\u00e9s multinationales commencent \u00e0 ouvrir leurs propres usines de fabrication. Ce n\u2019est que dans ce cas que pourront \u00eatre absorb\u00e9s plus de 10 mille demandeurs d\u2019emploi par an\u00a0\u00bb, a soulign\u00e9 Muhamet Sadiku.<\/p>\n<p>Naim Gashi, expert en \u00e9conomie, pense que le d\u00e9veloppement des petites et moyennes entreprises offre \u00e9galement des opportunit\u00e9s de r\u00e9duction du taux de ch\u00f4mage au Kosovo.<\/p>\n<p>\u00ab\u00a0Cette croissance de 3 \u00e0 4\u00a0% au cours des deux prochaines ann\u00e9es, selon les experts \u00e9conomiques, sera insuffisante pour absorber pr\u00e8s de 25 mille jeunes qui chaque ann\u00e9e entrent sur le march\u00e9 du travail\u00a0\u00bb, a d\u00e9clar\u00e9 Gashi pour <em>REL<\/em>.<\/p>\n<p>\u00abCe que nous devons faire est d\u2019encourager l\u2019investissement et notre capacit\u00e9 interne, afin d\u2019atteindre un taux de croissance \u00e9conomique de 8\u00a0%, permettant ainsi d\u2019absorber le contingent de jeunes qui cherchent du travail\u00a0\u00bb, a-t-il ajout\u00e9.<\/p>\n<p>La cr\u00e9ation de nouveaux emplois dans tous les pays d\u2019Europe de l\u2019Est, dit Gashi, a \u00e9t\u00e9 le fait de l\u2019autonomisation du secteur priv\u00e9. Selon lui, la tendance qui veut qu\u2019\u00e0 travers les grandes entreprises on lutte contre le ch\u00f4mage, n\u2019a pas montr\u00e9 son efficacit\u00e9 dans tous les pays ayant subi la transition, le Kosovo en \u00e9tant un exemple.<\/p>\n<p>Le Kosovo a connu sa croissance la plus \u00e9lev\u00e9e en\u00a02010 et\u00a02011, atteignant plus de 5\u00a0%, mais m\u00eame \u00e0 ce moment-l\u00e0, le ch\u00f4mage restait l\u2019un des plus grands probl\u00e8mes. Le taux le plus prononc\u00e9 de ch\u00f4mage au Kosovo est celui des jeunes de 15-24 ans.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le taux de ch\u00f4mage au Kosovo, selon les chiffres officiels, atteint 32,9 %, mais selon les repr\u00e9sentants syndicaux, il serait sup\u00e9rieur \u00e0 45 %.<\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-126486","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/126486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=126486"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/126486\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=126486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=126486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=126486"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=126486"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=126486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}