{"id":122235,"date":"2016-08-15T12:43:55","date_gmt":"2016-08-15T10:43:55","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=122235"},"modified":"2016-08-15T12:45:34","modified_gmt":"2016-08-15T10:45:34","slug":"aeroport-de-prishtina-209053-passagers-rien-que-pour-juillet","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/aeroport-de-prishtina-209053-passagers-rien-que-pour-juillet\/","title":{"rendered":"A\u00e9roport de Prishtina : 209\u2019053 passagers rien que pour juillet"},"content":{"rendered":"<p>L&#8217;augmentation du mois de juillet s\u2019inscrit comme une continuation de la forte augmentation du nombre de passagers en 2016 par rapport \u00e0 la m\u00eame p\u00e9riode de l&#8217;ann\u00e9e derni\u00e8re, peut-on lire dans la d\u00e9claration donn\u00e9e par l&#8217;Autorit\u00e9 de l&#8217;aviation civile du Kosovo (AAK).<\/p>\n<p>L\u2019Autorit\u00e9 de l&#8217;aviation civile du Kosovo a annonc\u00e9 rien que pour le mois de juillet 209\u2019053 passagers. Ces derniers \u00a0ont vol\u00e9 vers et depuis l&#8217;a\u00e9roport international de Pristina &#8220;Adem Jashari&#8221;.<\/p>\n<p>&#8220;Ce chiffre repr\u00e9sente une augmentation de 8,9% par rapport au mois de juillet 2015, qui d\u00e9nombrait alors 192\u2019000 passagers.<\/p>\n<p>L&#8217;augmentation du mois de juillet s\u2019inscrit comme une continuation de la forte augmentation du nombre de passagers en 2016 par rapport \u00e0 la m\u00eame p\u00e9riode de l&#8217;ann\u00e9e derni\u00e8re, peut-on lire dans la d\u00e9claration donn\u00e9e par l&#8217;Autorit\u00e9 de l&#8217;aviation civile du Kosovo (AAK).<\/p>\n<p>Selon la AAK, au cours des sept premiers mois de cette ann\u00e9e ont transit\u00e9 par l\u2019a\u00e9roport de Prishtina 985\u2019555 passagers, soit une augmentation de 13,6% par rapport \u00e0 la m\u00eame p\u00e9riode de l&#8217;an dernier.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;augmentation du mois de juillet s\u2019inscrit comme une continuation de la forte augmentation du nombre de passagers en 2016 par rapport \u00e0 la m\u00eame p\u00e9riode de l&#8217;ann\u00e9e derni\u00e8re, peut-on lire dans la d\u00e9claration donn\u00e9e par l&#8217;Autorit\u00e9 de l&#8217;aviation civile du Kosovo (AAK). L\u2019Autorit\u00e9 de l&#8217;aviation civile du Kosovo a annonc\u00e9 rien que pour le mois [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-122235","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/122235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=122235"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/122235\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=122235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=122235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=122235"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=122235"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=122235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}