{"id":114445,"date":"2016-05-23T08:21:44","date_gmt":"2016-05-23T06:21:44","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/zvicerani-eksploron-me-biciklete-bukurite-e-shqiperise\/"},"modified":"2016-05-24T09:09:13","modified_gmt":"2016-05-24T07:09:13","slug":"un-suisse-explore-les-beautes-de-lalbanie-a-velo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/un-suisse-explore-les-beautes-de-lalbanie-a-velo\/","title":{"rendered":"Un suisse explore les beaut\u00e9s de l\u2019Albanie \u00e0 v\u00e9lo"},"content":{"rendered":"<p><span style=\"line-height: 1.5;\">Tobi Gessler invite tous les Europ\u00e9ens \u00e0 d\u00e9couvrir l\u2019Albanie, car selon lui il s\u2019agit d\u2019un pays propice au cyclotourisme.<\/span><\/p>\n<p>Gessler, qui participe \u00e0 des courses de v\u00e9lo de montagne, explique que c\u2019est ainsi qu\u2019il a d\u00e9couvert l\u2019Albanie.<\/p>\n<p>Il encourage le plus grand nombre d\u2019\u00e9trangers \u00e0 explorer l\u2019Albanie \u00e0 v\u00e9lo, car le pays compte parmi les meilleurs sites mondiaux pour ce genre de tourisme.<\/p>\n<p>\u00ab\u00a0Tous les amateurs de v\u00e9lo devraient explorer l\u2019Albanie. Il y a des villages et des rues fantastiques qu\u2019on ne trouve dans aucuns autres pays\u00a0\u00bb, a d\u00e9clar\u00e9 Gessler pour le journal albanais \u00ab\u00a0Shekulli\u00a0\u00bb.<\/p>\n<p>Le suisse de 35 ans vit en Albanie depuis 2013. En Suisse, il \u00e9tait travailleur social et livreur \u00e0 v\u00e9lo dans la ville de Z\u00fcrich.<\/p>\n<p>\u00ab\u00a0Je distribuais des produits m\u00e9dicaux dans des laboratoires et cliniques dentaires. J\u2019aimais ce travail parce que je le faisais \u00e0 v\u00e9lo, ce qui est ma passion depuis toujours. J\u2019ai toujours pratiqu\u00e9 le cyclisme dans les Alpes suisses et dans diff\u00e9rents pays\u00a0\u00bb, a d\u00e9clar\u00e9 Tobi Gessler.<\/p>\n<p>\u00ab\u00a0Avec un groupe d\u2019amis, nous sommes partis de Z\u00fcrich\u00a0et pendant six semaines, nous sommes pass\u00e9s par B\u00e2le, le nord de la France, puis on a travers\u00e9 le tunnel de la Manche par ferry pour rejoindre l\u2019Angleterre m\u00e9ridionale et p\u00e9daler jusqu\u2019au Pays de Galles. Nous sommes ensuite rentr\u00e9s en train. Ce fut une exp\u00e9rience merveilleuse\u00a0\u00bb, a d\u00e9clar\u00e9 Gessler.<\/p>\n<p><strong>L\u2019Albanie est tr\u00e8s belle et appropri\u00e9e pour ce genre d\u2019activit\u00e9<\/strong><\/p>\n<p>\u00ab\u00a0L\u2019Albanie a une nature tr\u00e8s belle et sauvage, dans le sens positif du terme, et les gens y sont tr\u00e8s sympathiques. Faire du v\u00e9lo de montagne ici en Albanie est une exp\u00e9rience merveilleuse pour tout le monde, mais je pense que c\u2019est tout particuli\u00e8rement vrai pour les \u00e9trangers. Si vous venez de l\u2019Europe occidentale, des \u00c9tats-Unis ou d\u2019ailleurs, et que vous visitez les villages albanais, il vous semblera avoir fait un voyage dans le temps. On se sent comme retourner 50 ou m\u00eame 100 ans en arri\u00e8re. C\u2019est comme se trouver dans un mus\u00e9e\u00a0: les chemins de terre ne sont pas entretenus, tout est produit de mani\u00e8re artisanale, les maisons sont vieilles, les gens portent des v\u00eatements traditionnels et la nourriture est bio. Ce sont de belles choses, que nous ne trouvons plus aujourd\u2019hui dans l\u2019Europe industrialis\u00e9e\u00a0\u00bb, explique Gessler.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/05\/qtd4thw.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-114332\" src=\"http:\/\/www.albinfo.ch\/wp-content\/uploads\/2016\/05\/qtd4thw-225x300.jpg\" alt=\"QTd4thW\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2016\/05\/qtd4thw-225x300.jpg 225w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2016\/05\/qtd4thw-768x1024.jpg 768w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2016\/05\/qtd4thw-297x396.jpg 297w, https:\/\/www.albinfo.at\/wp-content\/uploads\/2016\/05\/qtd4thw.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Albanie peut \u00eatre visit\u00e9e \u00e0 v\u00e9lo, cela est devenu r\u00e9alit\u00e9 pour le Suisse Tobi Gessler.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1159,1184,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-114445","post","type-post","status-publish","format-standard","hentry","category-ch-balkans","category-fotolajmi-fr","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/114445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=114445"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/114445\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=114445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=114445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=114445"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=114445"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=114445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}