{"id":111659,"date":"2016-04-20T09:44:33","date_gmt":"2016-04-20T07:44:33","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=111659"},"modified":"2016-04-20T09:44:33","modified_gmt":"2016-04-20T07:44:33","slug":"les-albanais-en-macedoine-faible-representation-politique","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/les-albanais-en-macedoine-faible-representation-politique\/","title":{"rendered":"Les Albanais en Mac\u00e9doine, faible repr\u00e9sentation politique"},"content":{"rendered":"<h1><\/h1>\n<p>Attaqu\u00e9 physiquement par les fans de Vardar \u00e0 Skopje, le Maire de Prishtina Shpend Ahmeti accuse l\u2019\u00e9lite politique en Mac\u00e9doine pour une tr\u00e8s faible repr\u00e9sentation dans ce pays. Ce qu\u2019il a vu chez les fans mac\u00e9doniens est l\u2019expression de la haine maximale envers les Albanais.<\/p>\n<p>Ahmeti se trouvait dans les tribunes du stade de Skopje, pour suivre le match entre Vardar et Shk\u00ebndija. Il \u00e9tait accompagn\u00e9 de Ragip Behrami, le p\u00e8re du joueur de l\u2019\u00e9quipe nationale suisse Valon Behrami et des repr\u00e9sentants du club de football Tetova-Shk\u00ebndija.<\/p>\n<p>Sur le statut de sa page \u200b\u200bFacebook, Ahmeti a d\u00e9clar\u00e9 \u00eatre un grand fan de Shk\u00ebndija et dit qu\u2019il suit la plupart des matchs.<\/p>\n<p>\u00ab\u00a0Tous ceux qui me connaissent savent que je suis un grand fan de football. Depuis plusieurs ann\u00e9es maintenant, je suis aussi fan de l\u2019\u00e9quipe Shk\u00ebndija de Tetovo et selon mes disponibilit\u00e9s, je suis le championnat en Mac\u00e9doine et \u00e9galement les matchs pour la qualification europ\u00e9enne\u00a0\u00bb, a \u00e9crit M. Ahmeti.<\/p>\n<p>Le week-end dernier, il regardait le match crucial pour le championnat entre Vardar et Shk\u00ebndija \u00e0 Skopje. Les fans de Shk\u00ebndija n\u2019ont pas pu entrer dans le stade, alors qu\u2019il y avait environ 2\u00a0000 fans de l\u2019\u00e9quipe Vardar.<\/p>\n<p>\u00ab\u00a0Nous \u00e9tions environ 20 Albanais invit\u00e9s du club Shk\u00ebndija. Les leaders du Vardar nous ont plac\u00e9s parmi les fans de Vardar. Tout au long du jeu, les fans de Vardar criaient \u00ab\u00a0les bons Albanais sont les Albanais morts\u00a0\u00bb, a d\u00e9clar\u00e9 M. Ahmeti.<\/p>\n<p>\u00ab\u00a0Cependant, l\u2019incident est survenu lorsque Shk\u00ebndija a marqu\u00e9 un but \u00e9galisateur et que le pr\u00e9sident du club s\u2019est lev\u00e9 pour c\u00e9l\u00e9brer. \u00c0 partir de ce moment, ils ont commenc\u00e9 \u00e0 nous jeter divers objets et \u00e0 frapper les personnes qui se trouvaient parmi eux. La police est intervenue tardivement et a tent\u00e9 en vain de les calmer. Ils nous ont sortis du stade pour notre propre s\u00e9curit\u00e9\u00a0\u00bb, a-t-il dit.<\/p>\n<p>Ahmeti dit qu\u2019il est conscient que des hooligans de football, il y en a partout dans le monde, mais selon le maire de Prishtina, \u00ab\u00a0La haine des Albanais est au maximum et dans de telles situations l\u2019on peut constater la faible repr\u00e9sentation des Albanais en Mac\u00e9doine. Nos partis veulent juste gouverner sans avoir de buts clairs pour les Albanais. Cela apportera plus de discrimination et de haine envers les Albanais, et pas seulement dans le monde du football\u00a0\u00bb, a-t-il dit.<\/p>\n<p>\u00ab\u00a0Moi, je me rends en Mac\u00e9doine seulement une fois tous les deux ou trois mois, mais les Albanais de Mac\u00e9doine vivent dans ces conditions tout au long de l\u2019ann\u00e9e, tant \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur d\u2019un stade\u00a0\u00bb, a-t-il ajout\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attaqu\u00e9 physiquement par les fans de Vardar \u00e0 Skopje, le Maire de Prishtina Shpend Ahmeti accuse l\u2019\u00e9lite politique en Mac\u00e9doine pour une tr\u00e8s faible repr\u00e9sentation dans ce pays. Ce qu\u2019il a vu chez les fans mac\u00e9doniens est l\u2019expression de la haine maximale envers les Albanais. Ahmeti se trouvait dans les tribunes du stade de Skopje, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-111659","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/111659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=111659"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/111659\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=111659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=111659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=111659"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=111659"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=111659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}